{"id":31,"date":"2016-09-19T13:24:33","date_gmt":"2016-09-19T13:24:33","guid":{"rendered":"http:\/\/cursos.ufrrj.br\/posgraduacao\/ppgpacs\/?page_id=31"},"modified":"2024-08-17T22:22:17","modified_gmt":"2024-08-18T01:22:17","slug":"infra-estrutura","status":"publish","type":"page","link":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgpacs\/infra-estrutura\/","title":{"rendered":"Infraestrutura"},"content":{"rendered":"<p><strong>N\u00daCLEOS DE PESQUISA E LABORAT\u00d3RIOS<\/strong><\/p>\n<ul>\n<li><strong>&nbsp; N\u00facleo de Pesquisa em Patrim\u00f4nio e Mem\u00f3ria NUPAM<\/strong> (L\u00edder: J\u00falio Sampaio IT\/UFRRJ 2012 a 2018 , Elis Regina Barbosa Angelo IM\/UFRRJ 2018 a atual ) Fundado em 2012, re\u00fane pesquisadores da UFRRJ e UFJF e promove atividades de pesquisa na \u00e1rea de Prote\u00e7\u00e3o e Conserva\u00e7\u00e3o do Patrim\u00f4nio Cultural.<\/li>\n<li><strong>&nbsp;&nbsp; Laborat\u00f3rio de Economia e Hist\u00f3ria &#8211; LEHI<\/strong> (L\u00edder: M\u00f4nica Martins IM\/UFRRJ) Fundado em 2009, congrega pesquisadores de Institui\u00e7\u00f5es de pesquisa do estado do Rio de Janeiro (UFRRJ,UFF, UFRJ,UERJ, CPII).<\/li>\n<li><strong>&nbsp; Laborat\u00f3rio N\u00facleo Interdisciplinar de Estudos Hist\u00f3ricos Pluralitas<\/strong> (L\u00edder: Raquel Alvitos Pereira) Fundado em 2012, congrega pesquisadores de Institui\u00e7\u00f5es de pesquisa do estado do Rio de Janeiro (UFRRJ, UFF e UNIRIO).<\/li>\n<li><strong>&nbsp; Laborat\u00f3rio de Estudos Afro-Brasileiros e Ind\u00edgenas Leafro<\/strong> (L\u00edder: Otair Fernandes de Oliveira DES\/IM\/UFRRJ) criado em 2006 \u00e9 integrado por pesquisadores, pesquisadoras e grupos de pesquisas pertencentes a diferentes cores e identidades \u00e9tnico-racial, cultural, geracional, de g\u00eanero, orienta\u00e7\u00e3o sexual, classe social, credo religioso (ou n\u00e3o), bem como por integrantes (ou n\u00e3o), de movimentos sociais negros e ind\u00edgenas, no \u00e2mbito da UFRRJ. Integrante do CONNEABS Cons\u00f3rcio Nacional de Neabs (N\u00facleos de Estudos Afro-Brasileiros).<\/li>\n<li><strong>&nbsp; Grupo de Pesquisa Educa\u00e7\u00e3o Superior e Rela\u00e7\u00f5es \u00c9tnico-Raciais GPESURER<\/strong> (L\u00edder: Ahyas Siss DES\/IM\/UFRRJ) &#8211; formado em 2006, congrega pesquisadores que discutem as pol\u00edticas de a\u00e7\u00e3o afirmativa e a diversidade \u00e9tnico-racial no Ensino Superior.<\/li>\n<li><strong>&nbsp; Grupo de Pesquisa Arte: Ensino e Produ\u00e7\u00e3o<\/strong> (L\u00edder: Arthur Gomes Valle DARTES\/ICHS\/UFRRJ), Grupo institucionalizado em 2009. Seus membros realizaram um n\u00famero significativo de exposi\u00e7\u00f5es art\u00edsticas e publica\u00e7\u00f5es relacionadas \u00e0s linhas de pesquisas ora desenvolvidas. Nos \u00faltimos quatro anos, foram apresentados resultados parciais de pesquisas vinculadas \u00e0s atuais linhas do grupo em diversas publica\u00e7\u00f5es, semin\u00e1rios, encontros, congressos e col\u00f3quios, de \u00e2mbito nacional e internacional, que podem ser consultadas nos curr\u00edculos Lattes dos pesquisadores.<\/li>\n<li><strong>&nbsp;&nbsp; N\u00facleo de Estudos e Pesquisas em Turismo. NEPET &#8211;<\/strong>&nbsp;Institucionalizado em 2006. Os componentes trabalham algumas linhas de pesquisa versadas em Turismo, Cultura, Sociedade e Planejamento Urbano, incluindo Pol\u00edticas P\u00fablicas e afins.<\/li>\n<li><strong>Grupo de Pesquisa em Express\u00e3o, Representa\u00e7\u00e3o e An\u00e1lise da Arquitetura &#8211; GERAR<\/strong> (L\u00edder: Helio Herbst &#8211; DAU-IT\/UFRRJ) &#8211; Fundado em 2009, re\u00fane pesquisadores da UFRRJ e promove atividades de pesquisa sobre desenho, modelagem e projeto em seus desdobramentos nos processos de cria\u00e7\u00e3o, codifica\u00e7\u00e3o e percep\u00e7\u00e3o dos espa\u00e7os arquitet\u00f4nicos.<\/li>\n<\/ul>\n<p><strong>SALAS&nbsp; ( BLOCO P\u00d3S GRADUA\u00c7\u00c3O )<\/strong><\/p>\n<p>SALA 101 \u2013 LEAFRO (LABORAT\u00d3RIO DE ESTUDOS AFRO-BRASILEIROS)<\/p>\n<p>SALA 102 \u2013 CEDIM (CENTRO DE DOCUMENTA\u00c7\u00c3O E IMAGEM)<\/p>\n<p>SALA 103 \u2013 SALA DE AULA<\/p>\n<p>SALA 104 \u2013 REPRESENTA\u00c7\u00c3O PROPPG \/ SECRETARIA DO PPGPACS\/ SECRETARIA PR\u00c9-ENEM<\/p>\n<p>SALA 105 \u2013 SALA DE AULA<\/p>\n<p>SALA 106 \u2013 SALA DE AULA<\/p>\n<p>SALA 107 \u2013 SALA DE REUNI\u00c3O<\/p>\n<p>SALA 108 \u2013 AUDIT\u00d3RIO<\/p>\n<p>SALA 109 \u2013 COTIC (COORDENADORIA DE TECNOLOGIA DA INFORMA\u00c7\u00c3O E COMUNICA\u00c7\u00c3O) \/ REDES<\/p>\n<p>SALA 110 \u2013 SALA DE AULA<\/p>\n<p><strong>BIBLIOTECAS<\/strong><\/p>\n<p>A Biblioteca Central (BC) da UFRRJ est\u00e1 situada no Campus Serop\u00e9dica, ao lado do pr\u00e9dio principal da institui\u00e7\u00e3o (P1). Possui 30 computadores ligados \u00e0 Internet. Nos \u00faltimos anos a Biblioteca vem ampliando de forma significativa seu acervo bibliogr\u00e1fico, buscando atender as demandas dos antigos e novos cursos de gradua\u00e7\u00e3o e p\u00f3s-gradua\u00e7\u00e3o, especialmente nas \u00e1reas de Ci\u00eancias Humanas e Sociais. Assim, a UFRRJ ampliou os recursos or\u00e7ament\u00e1rios para a constitui\u00e7\u00e3o de acervo bibliogr\u00e1fico para atender \u00e0 realidade da expans\u00e3o universit\u00e1ria. Atrav\u00e9s do sistema de preg\u00e3o eletr\u00f4nico, foram adquiridos t\u00edtulos de diversas \u00e1reas. Foram investidos, aproximadamente, 2 milh\u00f5es de reais entre 2010 e 2012, com a aquisi\u00e7\u00e3o de 8.000 novos t\u00edtulos, compondo seu acervo de cerca de 70.000 t\u00edtulos. A BC disponibiliza acesso on-line para consulta do acervo de todas as bibliotecas da universidade, por meio do Sistema Integrado de Bibliotecas Pergamum. Disponibiliza, tamb\u00e9m, acesso \u00e0s bases nacionais e estrangeiras integrantes do Portal de Peri\u00f3dicos da CAPES e outras redes de comunica\u00e7\u00e3o cient\u00edfica, como o JSTOR, tanto nos laborat\u00f3rios e salas de trabalho dos docentes, como atrav\u00e9s de trinta terminais localizados na pr\u00f3pria Biblioteca Central.<\/p>\n<p>A Biblioteca do Centro de Documenta\u00e7\u00e3o Ivan de Otero Ribeiro, do CPDA, est\u00e1 localizada no Centro do Rio de Janeiro e seu acervo \u00e9 composto de 9.797 t\u00edtulos em livros e 276 t\u00edtulos em peri\u00f3dicos. Cabe destacar a excel\u00eancia desse acervo, especializado em Ci\u00eancias Sociais Aplicadas, movimentos sociais e pol\u00edticas p\u00fablicas no campo. Recentemente, o acervo da Biblioteca do Centro de Documenta\u00e7\u00e3o Ivan de Otero Ribeiro foi enriquecido pela doa\u00e7\u00e3o do Acervo Maria Yedda Leite Linhares, especializado em Hist\u00f3ria Agr\u00e1ria e Rela\u00e7\u00f5es Internacionais.<\/p>\n<p>A BIBLIOTECA DO INSTITUTO MULTIDISCIPLINAR localiza-se no campus de Nova Igua\u00e7u, tendo sido inaugurada em 2010 e, desde ent\u00e3o, tem recebido investimentos importantes. Em 2011, por exemplo, mediante investimento total de R$ 450.000,00, foram adquiridos cerca de 2.900 t\u00edtulos em l\u00edngua estrangeira e portuguesa nas \u00e1reas de Ci\u00eancias Humanas e Sociais.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>N\u00daCLEOS DE PESQUISA E LABORAT\u00d3RIOS &nbsp; N\u00facleo de Pesquisa em Patrim\u00f4nio e Mem\u00f3ria NUPAM (L\u00edder: J\u00falio Sampaio IT\/UFRRJ 2012 a <a class=\"read-more\" href=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgpacs\/infra-estrutura\/ \" >&#8230; <span class=\"font-italic\">leia mais <i class=\"fas fa-angle-right\"><\/i><\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_acf_changed":false,"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"class_list":["post-31","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Infraestrutura - PPGPACS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgpacs\/infra-estrutura\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Infraestrutura - PPGPACS\" \/>\n<meta property=\"og:description\" content=\"N\u00daCLEOS DE PESQUISA E LABORAT\u00d3RIOS &nbsp; N\u00facleo de Pesquisa em Patrim\u00f4nio e Mem\u00f3ria NUPAM (L\u00edder: J\u00falio Sampaio IT\/UFRRJ 2012 a ... leia mais\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgpacs\/infra-estrutura\/\" \/>\n<meta property=\"og:site_name\" content=\"PPGPACS\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-18T01:22:17+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgpacs\\\/infra-estrutura\\\/\",\"url\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgpacs\\\/infra-estrutura\\\/\",\"name\":\"Infraestrutura - PPGPACS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgpacs\\\/#website\"},\"datePublished\":\"2016-09-19T13:24:33+00:00\",\"dateModified\":\"2024-08-18T01:22:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgpacs\\\/infra-estrutura\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgpacs\\\/infra-estrutura\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgpacs\\\/infra-estrutura\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgpacs\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Infraestrutura\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgpacs\\\/#website\",\"url\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgpacs\\\/\",\"name\":\"PPGPACS\",\"description\":\"Programa de P\u00f3s-Gradua\u00e7\u00e3o em Patrim\u00f4nio, Cultura e Sociedade\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgpacs\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Infraestrutura - PPGPACS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgpacs\/infra-estrutura\/","og_locale":"pt_BR","og_type":"article","og_title":"Infraestrutura - PPGPACS","og_description":"N\u00daCLEOS DE PESQUISA E LABORAT\u00d3RIOS &nbsp; N\u00facleo de Pesquisa em Patrim\u00f4nio e Mem\u00f3ria NUPAM (L\u00edder: J\u00falio Sampaio IT\/UFRRJ 2012 a ... leia mais","og_url":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgpacs\/infra-estrutura\/","og_site_name":"PPGPACS","article_modified_time":"2024-08-18T01:22:17+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgpacs\/infra-estrutura\/","url":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgpacs\/infra-estrutura\/","name":"Infraestrutura - PPGPACS","isPartOf":{"@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgpacs\/#website"},"datePublished":"2016-09-19T13:24:33+00:00","dateModified":"2024-08-18T01:22:17+00:00","breadcrumb":{"@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgpacs\/infra-estrutura\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgpacs\/infra-estrutura\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgpacs\/infra-estrutura\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgpacs\/"},{"@type":"ListItem","position":2,"name":"Infraestrutura"}]},{"@type":"WebSite","@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgpacs\/#website","url":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgpacs\/","name":"PPGPACS","description":"Programa de P\u00f3s-Gradua\u00e7\u00e3o em Patrim\u00f4nio, Cultura e Sociedade","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgpacs\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgpacs\/wp-json\/wp\/v2\/pages\/31","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgpacs\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgpacs\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgpacs\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgpacs\/wp-json\/wp\/v2\/comments?post=31"}],"version-history":[{"count":9,"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgpacs\/wp-json\/wp\/v2\/pages\/31\/revisions"}],"predecessor-version":[{"id":1866,"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgpacs\/wp-json\/wp\/v2\/pages\/31\/revisions\/1866"}],"wp:attachment":[{"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgpacs\/wp-json\/wp\/v2\/media?parent=31"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}