{"id":27,"date":"2016-09-19T13:24:10","date_gmt":"2016-09-19T13:24:10","guid":{"rendered":"http:\/\/cursos.ufrrj.br\/posgraduacao\/ppgpacs\/?page_id=27"},"modified":"2026-05-26T18:14:32","modified_gmt":"2026-05-26T21:14:32","slug":"apresentacao","status":"publish","type":"page","link":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgpacs\/apresentacao\/","title":{"rendered":"Apresenta\u00e7\u00e3o"},"content":{"rendered":"<p><strong>Coordena\u00e7\u00e3o Acad\u00eamica (mandato 2022\/2024)<\/strong><\/p>\n<p><strong>Coordenador: <\/strong>Profa. Elis Regina Barbosa Angelo<\/p>\n<p><strong>Vice-Coordenador: <\/strong>Prof. Fabio Pereira Cerdera<\/p>\n<p><strong>Informa\u00e7\u00f5es: <\/strong>Secretaria do PPGPACS<\/p>\n<p><strong>E-mail: <\/strong><span class=\"_5yl5\">secretariapgpacsufrrj@gmail.com<\/span><\/p>\n<p>Institui\u00e7\u00e3o centen\u00e1ria, que come\u00e7ou como refer\u00eancia nacional nas \u00e1reas de Agronomia e Veterin\u00e1ria, hoje a Universidade Federal Rural do Rio de Janeiro (UFRRJ) diversificou-se: tornou-se multicampi e multidisciplinar, estendendo sua atua\u00e7\u00e3o de ensino, pesquisa e extens\u00e3o a todas as \u00e1reas do conhecimento. O marco de sua origem \u00e9 o Decreto-lei no 8.319, de 20\/10\/1910, que estabeleceu as bases para o ensino agr\u00edcola no Brasil e criou a Escola Superior de Agronomia e Medicina Veterin\u00e1ria (ESAMV). Nos anos subsequentes, a ESAMV passou por amplia\u00e7\u00f5es e reordenamentos e pelo Decreto-Lei no 6.155, de 30\/12\/1943, foi elevada \u00e0 categoria de Universidade Rural, quando se consolidaram novos cursos e servi\u00e7os.<\/p>\n<p>Pouco depois, em julho de 1947, foi inaugurado o Campus Serop\u00e9dica, em uma propriedade de aproximadamente 3.500 ha, \u00e0s margens da antiga rodovia Rio-S\u00e3o Paulo, atualmente denominada BR-465. Em 1962, a Universidade Rural passou a denominar-se UniversidadeRural do Brasil (URB), sendo-lhe reconhecida a autonomia did\u00e1tica, administrativa, financeira e disciplinar. Ao longo da d\u00e9cada de 1960, a Universidade conheceu uma gradual expans\u00e3o, com a cria\u00e7\u00e3o de novos cursos e pelo Decreto no 60.731, de 19\/05\/1967, ganhou a denomina\u00e7\u00e3o de Universidade Federal Rural do Rio de Janeiro (UFRRJ), que mantem at\u00e9 hoje. Durante a d\u00e9cada de 1970, a UFRRJ criou novos cursos de gradua\u00e7\u00e3o, ampliando o seu perfil para al\u00e9m da \u00e1rea das Ci\u00eancias Agr\u00e1rias, quando implantou os cursos de Administra\u00e7\u00e3o, Ci\u00eancias Econ\u00f4micas, Licenciatura em Economia Dom\u00e9stica, Geologia, Zootecnia, Licenciatura em Educa\u00e7\u00e3o F\u00edsica e Licenciatura em Ci\u00eancias com habilita\u00e7\u00f5es em Matem\u00e1tica, F\u00edsica, Qu\u00edmica e Biologia. No in\u00edcio dos anos 1990, foram criados os cursos de Engenharia de Alimentos e o primeiro curso noturno da institui\u00e7\u00e3o: Administra\u00e7\u00e3o. Na d\u00e9cada de 2000 novos cursos foram criados: Engenharia de Agrimensura, Licenciatura em Qu\u00edmica, Engenharia Agr\u00edcola, Arquitetura e Urbanismo e, em 2001 destaca-se a cria\u00e7\u00e3o do curso de Hist\u00f3ria &#8211; Licenciatura, no turno noturno, vinculado ao Instituto de Ci\u00eancias Humanas e Sociais (ICHS), no Campus Serop\u00e9dica.<\/p>\n<p>A partir de 2005, a UFRRJ iniciou um significativo processo de crescimento e expans\u00e3o, deixando de ser uma IES de pequeno porte para se transformar em uma universidade de m\u00e9dio porte, com aproximadamente 15.000 alunos distribu\u00eddos em 58 cursos de gradua\u00e7\u00e3o, em turnos e campi diferentes. Por meio do Programa de Expans\u00e3o do Ensino Superior, do Governo Federal, foi criado um campus universit\u00e1rio da UFRRJ no munic\u00edpio de Nova Igua\u00e7u, denominado Instituto Multidisciplinar (IM), onde passaram a funcionar sete cursos de gradua\u00e7\u00e3o: Administra\u00e7\u00e3o, Matem\u00e1tica, Pedagogia, Ci\u00eancias Econ\u00f4micas, Turismo, Hotelaria e Hist\u00f3ria. Em 2007, no quadro ainda do Programa de Expans\u00e3o conduzido pelo MEC, a UFRRJ direcionou sua aten\u00e7\u00e3o para a cria\u00e7\u00e3o do Campus Tr\u00eas Rios o Instituto de Tr\u00eas Rios (ITR) , onde s\u00e3o oferecidos quatro cursos de gradua\u00e7\u00e3o: Administra\u00e7\u00e3o, Ci\u00eancias Econ\u00f4micas, Direito e Gest\u00e3o Ambiental.<\/p>\n<p>Em 2008, concomitantemente ao processo de implanta\u00e7\u00e3o dos seus dois novos campi universit\u00e1rios, a UFRRJ iniciou seu Programa de Reestrutura\u00e7\u00e3o e Expans\u00e3o (PRE), a\u00e7\u00e3o que foi uma resposta institucional propositiva ao REUNI, institu\u00eddo pelo MEC, cujo impacto social nas regi\u00f5es de sua influ\u00eancia mostra-se extremamente relevante. Como desdobramento do processo de expans\u00e3o e reestrutura\u00e7\u00e3o, foram criados no ICHS, no Campus Serop\u00e9dica, os cursos de gradua\u00e7\u00e3o em Artes, Letras, Filosofia, Ci\u00eancias Sociais, Comunica\u00e7\u00e3o Social, Hotelaria, Administra\u00e7\u00e3o P\u00fablica, Ci\u00eancias Cont\u00e1beis, Rela\u00e7\u00f5es Internacionais, Direito e duas novas modalidades do curso de Hist\u00f3ria: Bacharelado (noturno e vespertino) e\u00a0 Licenciatura (vespertino). Pari passu ao processo de amplia\u00e7\u00e3o dos cursos de gradua\u00e7\u00e3o, a UFRRJ buscou consolidar-se como centro de excel\u00eancia nas \u00e1reas de pesquisa e de p\u00f3s-gradua\u00e7\u00e3o, oferecendo programas de resson\u00e2ncia internacional e nacional e produzindo impactos locais e regionais relevantes. Em conson\u00e2ncia com o projeto de fortalecimento da \u00e1rea de Humanidades na UFRRJ e alinhando-se \u00e0s diretrizes gerais do Plano Nacional de P\u00f3s-Gradua\u00e7\u00e3o (PNPG) 2005-2010, que manifesta a meta de interiorizar e descentralizar os programas de p\u00f3s-gradua\u00e7\u00e3o, segundo o entendimento de que a expans\u00e3o dos mesmos \u00e9 fator estrat\u00e9gico no processo de desenvolvimento socioecon\u00f4mico e cultural da sociedade brasileira, destaca-se a cria\u00e7\u00e3o de v\u00e1rios Programas de P\u00f3s-Gradua\u00e7\u00e3o em \u00e1reas de Ci\u00eancias Humanas e Sociais. A partir de ent\u00e3o, foram implantados outros cursos de p\u00f3s-gradua\u00e7\u00e3o na<br \/>\nUFRRJ, como o Mestrado em Hist\u00f3ria, em 2007 (que ter\u00e1 turmas de doutorado a partir de 2014); o mestrado em Educa\u00e7\u00e3o Contextos Contempor\u00e2neos e Demandas Populares , em 2009; e os programas de mestrado acad\u00eamico em Psicologia (2011), Ci\u00eancias Sociais (2012), Desenvolvimento Territorial e Pol\u00edticas P\u00fablicas (2012) e Filosofia (2013). A UFRRJ oferece, atualmente, 33 cursos de p\u00f3s-gradua\u00e7\u00e3o stricto sensu nas \u00e1reas de Ci\u00eancias Agr\u00e1rias, Ci\u00eancias Humanas, Ci\u00eancias Sociais Aplicadas, Ci\u00eancias Exatas, Ci\u00eancias da Terra e Engenharias, sendo 20 mestrados acad\u00eamicos, 12 doutorados e 3 mestrados profissionais. Al\u00e9m disso, oferece cursos de p\u00f3s-gradua\u00e7\u00e3o lato sensu para a comunidade de forma regular. Por ser multicampi, atualmente a UFRRJ tem presen\u00e7a forte na Baixada Fluminense, na Zona Oeste do munic\u00edpio do Rio de Janeiro, no M\u00e9dio Para\u00edba e no Norte Fluminense e, por meio de suas a\u00e7\u00f5es de pesquisa, ensino e extens\u00e3o, vem crescentemente assumindo um papel relevante na inclus\u00e3o social, no desenvolvimento regional e na valoriza\u00e7\u00e3o da cultura e da hist\u00f3ria de suas popula\u00e7\u00f5es.<br \/>\nA Baixada Fluminense \u00e9 uma regi\u00e3o densamente povoada, abrigando 3,5 milh\u00f5es de pessoas e composta pelos munic\u00edpios de Nova Igua\u00e7u, Queimados, Caxias, Belford Roxo, S\u00e3o Jo\u00e3o de Meriti,Mesquita, Nil\u00f3polis, Serop\u00e9dica, Itagua\u00ed, Paracambi, Guapimirim, Japeri e Mag\u00e9 (Figura 01). Observe-se que, segundo in\u00fameros indicadores, essa macroregi\u00e3o, que integra a chamada Regi\u00e3o Metropolitana do Rio de Janeiro, acumula recordes negativos. Nela encontram-se as menores taxas de desenvolvimento humano do estado, sendo grav\u00edssimos os problemas de falta de saneamento b\u00e1sico, de habita\u00e7\u00e3o, de transporte de massas, de educa\u00e7\u00e3o de qualidade e de seguran\u00e7a p\u00fablica. A chamada Zona Oeste do munic\u00edpio do Rio de\u00a0 Janeiro \u00e9 outra regi\u00e3o localizada na zona de influ\u00eancia direta da UFRRJ. \u00c9, tamb\u00e9m, densamente povoada e economicamente fundamental para a cidade e o estado do Rio de Janeiro. Deve-se destacar os novos empreendimentos da Prefeitura do Rio de Janeiro e do Estado no sentido de facilitar o tr\u00e2nsito em dire\u00e7\u00e3o \u00e0 Zona Oeste da cidade por meio da constru\u00e7\u00e3o de faixas seletivas para \u00f4nibus (Transoeste), facilitando o acesso a bairros do munic\u00edpio do Rio de Janeiro pr\u00f3ximos a Serop\u00e9dica, tais como Campo Grande e Santa Cruz. Do mesmo modo, a constru\u00e7\u00e3o do Arco Metropolitano do Rio de Janeiro, que corta o munic\u00edpio de Serop\u00e9dica, tamb\u00e9m contribuir\u00e1 para a amplia\u00e7\u00e3o dos acessos \u00e0 universidade. Assim, a Baixada Fluminense, regi\u00e3o que congrega 13 munic\u00edpios do Estado do Rio de Janeiro e uma popula\u00e7\u00e3o de cerca de 3,5 milh\u00f5es de habitantes, onde s\u00e3o gerados 25% do PIB industrial do<br \/>\nEstado. Apesar de sua import\u00e2ncia econ\u00f4mica e da alta densidade populacional, a regi\u00e3o tem sido historicamente exclu\u00edda de alguns cen\u00e1rios culturais e intelectuais.<\/p>\n<p>A amplia\u00e7\u00e3o de institui\u00e7\u00f5es p\u00fablicas de ensino superior na regi\u00e3o, al\u00e9m de promover uma amplia\u00e7\u00e3o do acesso a esse n\u00edvel de ensino vem favorecer processos de mobilidade e inclus\u00e3o social, com impactos para o desenvolvimento da Baixada Fluminense. Geralmente, os programas e projetos que se dedicam \u00e0s \u00e1reas pol\u00edtica e culturalmente perif\u00e9ricas estipulam como vias de inclus\u00e3o social, a\u00e7\u00f5es nos setores de esporte e lazer ou t\u00e9cnico desprezando a op\u00e7\u00e3o acad\u00eamica, ora priorizada. Com o objetivo de contribuir para a constru\u00e7\u00e3o de novas concep\u00e7\u00f5es e pr\u00e1ticas das pol\u00edticas p\u00fablicas no \u00e2mbito da educa\u00e7\u00e3o superior brasileira, sobretudo no tocante ao desenvolvimento s\u00f3cio-cultural e o envolvimento pol\u00edtico dos jovens e adultos residentes nas regi\u00f5es da Baixada, Sul e Oeste fluminense, \u00e9 que a UFRRJ reafirma seu entendimento de que a via da educa\u00e7\u00e3o \u00e9 um dos principais elementos constituintes de uma pol\u00edtica de desenvolvimento social. Na Costa Verde, regi\u00e3o tamb\u00e9m impactada pela presen\u00e7a da UFRRJ, est\u00e3o os munic\u00edpios de Mangaratiba e Angra dos Reis, na dire\u00e7\u00e3o do Sul Fluminense. No Vale do Para\u00edba localizam-se os munic\u00edpios de Engenheiro Paulo de Frontin, Mendes, Vassouras, Valen\u00e7a, Tr\u00eas Rios, Quatis e Volta Redonda. Do ponto de vista geogr\u00e1fico, a UFRRJ \u00e9 a principal Institui\u00e7\u00e3o de Ensino Superior P\u00fablico Federal a impactar diretamente a vida de aproximadamente 7 milh\u00f5es de pessoas que vivem nas regi\u00f5es descritas acima. A recente expans\u00e3o da gradua\u00e7\u00e3o e da p\u00f3s-gradua\u00e7\u00e3o foi planejada e vem sendo operacionalizada com o objetivo de ampliar as oportunidades de ensino, pesquisa, extens\u00e3o a essa popula\u00e7\u00e3o que enfrenta enormes dificuldades para obter servi\u00e7os p\u00fablicos de qualidade, sendo a educa\u00e7\u00e3o um dos maiores problemas. Em n\u00edvel institucional e regional, as \u00e1reas de Ci\u00eancias Humanas e Sociais da UFRRJ tem-se consolidado a partir de uma preocupa\u00e7\u00e3o fundamental, que orienta todos os profissionais envolvidos no processo: contribuir para a interioriza\u00e7\u00e3o do ensino superior p\u00fablico, considerando de forma articulada a gradua\u00e7\u00e3o e a p\u00f3s-gradua\u00e7\u00e3o e favorecendo a aproxima\u00e7\u00e3o da universidade com a comunidade que a rodeia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Coordena\u00e7\u00e3o Acad\u00eamica (mandato 2022\/2024) Coordenador: Profa. Elis Regina Barbosa Angelo Vice-Coordenador: Prof. Fabio Pereira Cerdera Informa\u00e7\u00f5es: Secretaria do PPGPACS E-mail: <a class=\"read-more\" href=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgpacs\/apresentacao\/ \" >&#8230; <span class=\"font-italic\">leia mais <i class=\"fas fa-angle-right\"><\/i><\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_acf_changed":false,"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"class_list":["post-27","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Apresenta\u00e7\u00e3o - PPGPACS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgpacs\/apresentacao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Apresenta\u00e7\u00e3o - PPGPACS\" \/>\n<meta property=\"og:description\" content=\"Coordena\u00e7\u00e3o Acad\u00eamica (mandato 2022\/2024) Coordenador: Profa. Elis Regina Barbosa Angelo Vice-Coordenador: Prof. Fabio Pereira Cerdera Informa\u00e7\u00f5es: Secretaria do PPGPACS E-mail: ... leia mais\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgpacs\/apresentacao\/\" \/>\n<meta property=\"og:site_name\" content=\"PPGPACS\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-26T21:14:32+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgpacs\\\/apresentacao\\\/\",\"url\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgpacs\\\/apresentacao\\\/\",\"name\":\"Apresenta\u00e7\u00e3o - PPGPACS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgpacs\\\/#website\"},\"datePublished\":\"2016-09-19T13:24:10+00:00\",\"dateModified\":\"2026-05-26T21:14:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgpacs\\\/apresentacao\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgpacs\\\/apresentacao\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgpacs\\\/apresentacao\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgpacs\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Apresenta\u00e7\u00e3o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgpacs\\\/#website\",\"url\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgpacs\\\/\",\"name\":\"PPGPACS\",\"description\":\"Programa de P\u00f3s-Gradua\u00e7\u00e3o em Patrim\u00f4nio, Cultura e Sociedade\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgpacs\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Apresenta\u00e7\u00e3o - PPGPACS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgpacs\/apresentacao\/","og_locale":"pt_BR","og_type":"article","og_title":"Apresenta\u00e7\u00e3o - PPGPACS","og_description":"Coordena\u00e7\u00e3o Acad\u00eamica (mandato 2022\/2024) Coordenador: Profa. Elis Regina Barbosa Angelo Vice-Coordenador: Prof. Fabio Pereira Cerdera Informa\u00e7\u00f5es: Secretaria do PPGPACS E-mail: ... leia mais","og_url":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgpacs\/apresentacao\/","og_site_name":"PPGPACS","article_modified_time":"2026-05-26T21:14:32+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgpacs\/apresentacao\/","url":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgpacs\/apresentacao\/","name":"Apresenta\u00e7\u00e3o - PPGPACS","isPartOf":{"@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgpacs\/#website"},"datePublished":"2016-09-19T13:24:10+00:00","dateModified":"2026-05-26T21:14:32+00:00","breadcrumb":{"@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgpacs\/apresentacao\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgpacs\/apresentacao\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgpacs\/apresentacao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgpacs\/"},{"@type":"ListItem","position":2,"name":"Apresenta\u00e7\u00e3o"}]},{"@type":"WebSite","@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgpacs\/#website","url":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgpacs\/","name":"PPGPACS","description":"Programa de P\u00f3s-Gradua\u00e7\u00e3o em Patrim\u00f4nio, Cultura e Sociedade","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgpacs\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgpacs\/wp-json\/wp\/v2\/pages\/27","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgpacs\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgpacs\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgpacs\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgpacs\/wp-json\/wp\/v2\/comments?post=27"}],"version-history":[{"count":11,"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgpacs\/wp-json\/wp\/v2\/pages\/27\/revisions"}],"predecessor-version":[{"id":1799,"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgpacs\/wp-json\/wp\/v2\/pages\/27\/revisions\/1799"}],"wp:attachment":[{"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgpacs\/wp-json\/wp\/v2\/media?parent=27"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}