{"id":3754,"date":"2025-01-31T15:07:29","date_gmt":"2025-01-31T18:07:29","guid":{"rendered":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgletras\/?page_id=3754"},"modified":"2025-09-08T21:32:08","modified_gmt":"2025-09-09T00:32:08","slug":"apresentacao","status":"publish","type":"page","link":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgletras\/apresentacao\/","title":{"rendered":"Apresenta\u00e7\u00e3o"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">A Zona Oeste da Cidade do Rio e a Baixada Fluminense t\u00eam sofrido intensas transforma\u00e7\u00f5es que, embora diversas, trazem as marcas de processos hist\u00f3ricos. Neles est\u00e3o em jogo conflitos fundi\u00e1rios e territoriais, disputas pelo poder de nomear e definir os usos para essas regi\u00f5es por meio das pol\u00edticas p\u00fablicas, dos projetos de desenvolvimento e dos empreendimentos. Esse complexo de transforma\u00e7\u00f5es e de conflitos \u00e9 ainda integrado por formas de resist\u00eancia coletiva, de reelabora\u00e7\u00e3o identit\u00e1ria e de mobiliza\u00e7\u00e3o pol\u00edtica dos grupos que se entendem afetados pelos efeitos de tais processos. Nos \u00faltimos anos, os investimentos na moderniza\u00e7\u00e3o do porto de Itagua\u00ed; a constru\u00e7\u00e3o de ind\u00fastrias sider\u00fargicas, como previsto para os pr\u00f3ximos anos em Itagua\u00ed e Santa Cruz; o polo petroqu\u00edmico localizado no munic\u00edpio de Duque de Caxias; a moderniza\u00e7\u00e3o das estradas que atravessam a regi\u00e3o a partir da constru\u00e7\u00e3o da BR-493\/Rodovia Raphael de Almeida Magalh\u00e3es (popularmente conhecida como Arco Metropolitano), articulando a regi\u00e3o onde ser\u00e1 constru\u00edda uma grande refinaria de petr\u00f3leo no munic\u00edpio de Itabora\u00ed; o crescimento significativo do setor de servi\u00e7os; dentre outros investimentos p\u00fablicos e privados, evidenciam esse novo cen\u00e1rio das regi\u00f5es vizinhas \u00e0 UFRRJ. Esta complexa configura\u00e7\u00e3o da regi\u00e3o metropolitana do Rio de Janeiro nos convida a pensar o contexto da inser\u00e7\u00e3o regional da UFRRJ em um circuito de cidades \u2013 incluindo o Rio de Janeiro \u2013, relativizando uma poss\u00edvel dicotomia entre centro e periferia, na medida em que entre os dois polos est\u00e3o a circular importantes movimentos sociais, saberes e produ\u00e7\u00f5es, sinalizando a urg\u00eancia de um programa de Mestrado Acad\u00eamico na \u00e1rea de Letras que estimule investiga\u00e7\u00f5es acerca da tamb\u00e9m complexa interface entre linguagem e literatura originada e potencializada em tal quadro sociogeogr\u00e1fico. O Curso de Letras da UFRRJ j\u00e1 oferece, desde 2013, o Mestrado Profissional em Letras (PROFLETRAS) para professores de Portugu\u00eas de escolas p\u00fablicas advindos de parte dessas regi\u00f5es. Diante do resultado positivo desse Programa, que j\u00e1 formou em torno de 146 mestres, surge a necessidade de ampliar as \u00e1reas de conhecimento que emergiram ao longo destes nove anos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A proposta de Mestrado Acad\u00eamico preenche de forma mais abrangente as lacunas de conhecimento constatadas, permitindo reflex\u00f5es que possam contribuir para o desenvolvimento sociocultural das referidas regi\u00f5es. Tal preenchimento se aprofunda na medida em que docentes aqui inscritos executam tarefas acad\u00eamicas fortemente ligadas \u00e0 perspectiva da inclus\u00e3o social. Conforme registrado em seus curr\u00edculos, realizam-se, por exemplo, estudos dedicados a observar se livros did\u00e1ticos mapeiam varia\u00e7\u00f5es lingu\u00edsticas; pesquisas sobre m\u00fasica popular; trabalhos de leitura e produ\u00e7\u00e3o textual em unidades prisionais; an\u00e1lises da forma\u00e7\u00e3o do leitor diante do avan\u00e7o tecnol\u00f3gico do s\u00e9culo XXI. Como estas e outras iniciativas afins se apresentam ao lado de projetos de pesquisa centrados em debates do campo mais estritamente epistemol\u00f3gico, a proposta ora apresentada conjuga tend\u00eancias consolidadas e inova\u00e7\u00f5es contempor\u00e2neas, sendo ambas imprescind\u00edveis para confirmar e atualizar os compromissos da universidade p\u00fablica com a sociedade que a mant\u00e9m e justifica. Esse substantivo conjunto de itens sociais e acad\u00eamicos apresenta-se, assim, como o fator distintivo do Programa de Mestrado em tela, concebido a partir de debates e produ\u00e7\u00f5es cient\u00edficas sens\u00edveis \u00e0 diversidade cultural, \u00e9tnica e de g\u00eanero, bem como \u00e0s pol\u00edticas p\u00fablicas dirigidas \u00e0 ci\u00eancia. O circuito entre cidades e regi\u00f5es evidencia fen\u00f4menos a partir dos quais as no\u00e7\u00f5es de centro e periferia se movimentam e deslocam, o que instaura a necessidade de se conhecerem os discursos e os saberes da\u00ed emergidos, para que produ\u00e7\u00e3o acad\u00eamica e pol\u00edticas p\u00fablicas de Estado ganhem em abrang\u00eancia, teor de representatividade e poder de transforma\u00e7\u00e3o social.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Zona Oeste da Cidade do Rio e a Baixada Fluminense t\u00eam sofrido intensas transforma\u00e7\u00f5es que, embora diversas, trazem as marcas de [&hellip;]<\/p>\n","protected":false},"author":137,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":"","_links_to":"","_links_to_target":""},"class_list":["post-3754","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Apresenta\u00e7\u00e3o - Programa de P\u00f3s-Gradua\u00e7\u00e3o em Letras: Estudos de Linguagem e Literatura<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgletras\/apresentacao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Apresenta\u00e7\u00e3o - Programa de P\u00f3s-Gradua\u00e7\u00e3o em Letras: Estudos de Linguagem e Literatura\" \/>\n<meta property=\"og:description\" content=\"A Zona Oeste da Cidade do Rio e a Baixada Fluminense t\u00eam sofrido intensas transforma\u00e7\u00f5es que, embora diversas, trazem as marcas de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgletras\/apresentacao\/\" \/>\n<meta property=\"og:site_name\" content=\"Programa de P\u00f3s-Gradua\u00e7\u00e3o em Letras: Estudos de Linguagem e Literatura\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-09T00:32:08+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgletras\\\/apresentacao\\\/\",\"url\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgletras\\\/apresentacao\\\/\",\"name\":\"Apresenta\u00e7\u00e3o - Programa de P\u00f3s-Gradua\u00e7\u00e3o em Letras: Estudos de Linguagem e Literatura\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgletras\\\/#website\"},\"datePublished\":\"2025-01-31T18:07:29+00:00\",\"dateModified\":\"2025-09-09T00:32:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgletras\\\/apresentacao\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgletras\\\/apresentacao\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgletras\\\/apresentacao\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgletras\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Apresenta\u00e7\u00e3o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgletras\\\/#website\",\"url\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgletras\\\/\",\"name\":\"Programa de P\u00f3s-Gradua\u00e7\u00e3o em Letras: Estudos de Linguagem e Literatura\",\"description\":\"UFRRJ\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgletras\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Apresenta\u00e7\u00e3o - Programa de P\u00f3s-Gradua\u00e7\u00e3o em Letras: Estudos de Linguagem e Literatura","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgletras\/apresentacao\/","og_locale":"pt_BR","og_type":"article","og_title":"Apresenta\u00e7\u00e3o - Programa de P\u00f3s-Gradua\u00e7\u00e3o em Letras: Estudos de Linguagem e Literatura","og_description":"A Zona Oeste da Cidade do Rio e a Baixada Fluminense t\u00eam sofrido intensas transforma\u00e7\u00f5es que, embora diversas, trazem as marcas de [&hellip;]","og_url":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgletras\/apresentacao\/","og_site_name":"Programa de P\u00f3s-Gradua\u00e7\u00e3o em Letras: Estudos de Linguagem e Literatura","article_modified_time":"2025-09-09T00:32:08+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgletras\/apresentacao\/","url":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgletras\/apresentacao\/","name":"Apresenta\u00e7\u00e3o - Programa de P\u00f3s-Gradua\u00e7\u00e3o em Letras: Estudos de Linguagem e Literatura","isPartOf":{"@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgletras\/#website"},"datePublished":"2025-01-31T18:07:29+00:00","dateModified":"2025-09-09T00:32:08+00:00","breadcrumb":{"@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgletras\/apresentacao\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgletras\/apresentacao\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgletras\/apresentacao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgletras\/"},{"@type":"ListItem","position":2,"name":"Apresenta\u00e7\u00e3o"}]},{"@type":"WebSite","@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgletras\/#website","url":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgletras\/","name":"Programa de P\u00f3s-Gradua\u00e7\u00e3o em Letras: Estudos de Linguagem e Literatura","description":"UFRRJ","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgletras\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgletras\/wp-json\/wp\/v2\/pages\/3754","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgletras\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgletras\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgletras\/wp-json\/wp\/v2\/users\/137"}],"replies":[{"embeddable":true,"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgletras\/wp-json\/wp\/v2\/comments?post=3754"}],"version-history":[{"count":4,"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgletras\/wp-json\/wp\/v2\/pages\/3754\/revisions"}],"predecessor-version":[{"id":4381,"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgletras\/wp-json\/wp\/v2\/pages\/3754\/revisions\/4381"}],"wp:attachment":[{"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgletras\/wp-json\/wp\/v2\/media?parent=3754"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}