{"id":5038,"date":"2024-12-02T12:06:39","date_gmt":"2024-12-02T15:06:39","guid":{"rendered":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgfil\/?p=5038"},"modified":"2024-12-02T12:06:40","modified_gmt":"2024-12-02T15:06:40","slug":"curso-de-extensao-a-finitude-do-mundo-na-obra-ser-e-tempo-de-martin-heidegger-em-dialogo-com-o-pensamento-da-decolonialidade-profa-dra-manuela-saadeh-ppgfil-ufrrj","status":"publish","type":"post","link":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgfil\/curso-de-extensao-a-finitude-do-mundo-na-obra-ser-e-tempo-de-martin-heidegger-em-dialogo-com-o-pensamento-da-decolonialidade-profa-dra-manuela-saadeh-ppgfil-ufrrj\/","title":{"rendered":"Curso de Extens\u00e3o &#8220;A finitude do Mundo na obra Ser e Tempo de Martin Heidegger em di\u00e1logo com o pensamento da Decolonialidade&#8221; | Profa. Dra. Manuela Saadeh (PPGFil-UFRRJ)"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">A finitude do Mundo na obra Ser e Tempo de Martin Heidegger em di\u00e1logo com o pensamento da Decolonialidade &#8211; Profa. Dra. Manuela Saadeh (PPGFil-UFRRJ)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Per\u00edodo do Curso: 09\/12\/2024 a 27\/01\/2025<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Espa\u00e7os de Realiza\u00e7\u00e3o: Ambiente virtual<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Respons\u00e1vel pela A\u00e7\u00e3o: <strong>Profa. Dra. Manuela Saadeh (PPGFil-UFRRJ)<\/strong><br>E-mail do Respons\u00e1vel:santosmanuela0@gmail.com<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Inscri\u00e7\u00e3o: 27\/11\/2024 \u00e0 06\/12\/2024: <\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/sigaa.ufrrj.br\/sigaa\/link\/public\/extensao\/visualizacaoAcaoExtensao\/5665\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/sigaa.ufrrj.br\/sigaa\/link\/public\/extensao\/visualizacaoAcaoExtensao\/5665<\/a><br><br><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgfil\/files\/2024\/12\/241121_img_heiddeger.jpg\"><img decoding=\"async\" width=\"800\" height=\"400\" src=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgfil\/files\/2024\/12\/241121_img_heiddeger.jpg\" alt=\"\" class=\"wp-image-5039\" srcset=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgfil\/files\/2024\/12\/241121_img_heiddeger.jpg 800w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgfil\/files\/2024\/12\/241121_img_heiddeger-300x150.jpg 300w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgfil\/files\/2024\/12\/241121_img_heiddeger-768x384.jpg 768w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgfil\/files\/2024\/12\/241121_img_heiddeger-140x70.jpg 140w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Apresenta\u00e7\u00e3o do curso<\/strong><br><br>Martin Heidegger em sua obra Ser e Tempo, fenomenaliza a estrutura da compreens\u00e3o do Ser enquanto isto que determina o homem enquanto Dasein \u2013 n\u00e3o mais o homem enquanto Sujeito \u2013 como ser-no-mundo. Enquanto tal, este ente se manifesta hist\u00f3rico e circunscrito, e isto quer dizer que n\u00e3o h\u00e1 eternidade para a verdade e o conhecimento t\u00e3o pouco infinitude; a compreens\u00e3o humana se determinaria por sua finitude enquanto circunscri\u00e7\u00e3o de significa\u00e7\u00e3o e de Mundo; e enquanto mutante, poss\u00edvel, porquanto sempre j\u00e1 estruturalmente hist\u00f3rica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para compreendermos o que Heidegger pretende com tais postulados, contr\u00e1rios aos fundamentos de toda a Hist\u00f3ria da Metaf\u00edsica \u2013 uma vez que esta pressup\u00f5e a verdade (o Ser) como universal, v\u00e1lida e eterna \u2013 temos que nos inteirar propriamente tanto dos momentos fenomenais que comp\u00f5em a anal\u00edtica existencial do Dasein, quanto dos motivos hist\u00f3ricos desde os quais a Metaf\u00edsica enquanto verdade do ente na totalidade se instaura no pensamento humano como pensar un\u00e2nime, universal e atemporal.<br><br>O curso ser\u00e1 ministrado em formato virtual com um encontro semanal, sempre \u00e0s segundas-feiras das 18:30 \u00e0s 20:00hrs, atrav\u00e9s da plataforma Microsoft Teams. Est\u00e3o previstos sete encontros conduzidos pela professora respons\u00e1vel, com in\u00edcio no dia 9 de dezembro de 2024 (exceto dia 30\/12) e t\u00e9rmino no dia 27 de janeiro de 2025. A carga hor\u00e1ria total ser\u00e1 de 20h.<br><br><strong>Din\u00e2mica do curso<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O curso ser\u00e1 ministrado em formato virtual. A exposi\u00e7\u00e3o do tema pela professora respons\u00e1vel ter\u00e1 dura\u00e7\u00e3o de 70 minutos. Ap\u00f3s, os alunos ser\u00e3o convidados a participar por meio de perguntas e coment\u00e1rios. Ser\u00e3o disponibilizados com anteced\u00eancia os textos que ser\u00e3o estudados em cada aula.<br><br><strong>P\u00fablico-alvo<\/strong><br><br>Alunos de gradua\u00e7\u00e3o e de p\u00f3s-gradua\u00e7\u00e3o em filosofia da UFRRJ, bem como alunos de gradua\u00e7\u00e3o e de p\u00f3s-gradua\u00e7\u00e3o de outras universidades e quaisquer pessoas interessadas em Filosofia contempor\u00e2nea, Martin Heidegger, Metaf\u00edsica e Hist\u00f3ria da Filosofia.<br><br><strong>Objetivos<\/strong><br><br>O objetivo do curso \u00e9 trabalhar os conceitos mais fundamentais em Ser e Tempo e se dividir\u00e1 (como a obra) em duas partes. O objetivo da primeira parte do curso \u00e9 trabalhar os conceitos existenciais liberados pela anal\u00edtica do Ser do homem pensado por Heidegger como o Dasein (ser-o-a\u00ed) a partir do fen\u00f4meno ser-no-mundo, e isto com o intuito de transcender propriamente at\u00e9 as estruturas mais elementares do Ser deste ente, para que a possibilidade de compreens\u00e3o da estrutura do ente que n\u00f3s mesmos somos se torne vis\u00edvel. Sendo o Dasein o \u00fanico ente que det\u00e9m a compreens\u00e3o do Ser, a qual se institui desde a estrutura: Ser projetivo j\u00e1 em um Mundo junto ao ente intramundano encontrado, esta anal\u00edtica fenomenol\u00f3gica da compreens\u00e3o humana \u00e9 o passo prim\u00e1rio necess\u00e1rio para a compreens\u00e3o da quest\u00e3o que se pergunta pelo sentido do Ser de todo, que \u00e9 a quest\u00e3o posta no princ\u00edpio do tratado Ser e Tempo. Em Ser e Tempo, o fil\u00f3sofo procede sua anal\u00edtica existencial do Ser do Dasein, enquanto este ente que n\u00f3s mesmos somos. Em tal anal\u00edtica o pensamento desmembra pormenorizadamente todos os momentos fenomenais que comp\u00f5em a estrutura da compreens\u00e3o do Ser, os quais se movimentam simultaneamente, mas devem ser identificados em uma anal\u00edtica. A partir de tal anal\u00edtica, podemos tentar compreender os conceitos de finitude de Mundo de sentido, circunscri\u00e7\u00e3o de sentido, e a quest\u00e3o do Ser, como um dar-se finito enquanto verdade; o que nos leva a pensar sobre a descoloniza\u00e7\u00e3o de Mundos de sentido, uma vez que impor um Mundo de sentido sobre outro n\u00e3o implica em conceber que n\u00e3o houve a singularidade pr\u00f3pria (verdade, Ser) a tal e tal contexto de exist\u00eancia.<br><br><strong>Resumo<\/strong><br><br>Se como ensina Heidegger, a ess\u00eancia do Ser, \u00e9 o nada de coisa alguma; se, por conta disto aqui mesmo, n\u00e3o se o pode representar como um ente; se, com isso, o Ser s\u00f3 poderia se determinar pela liberdade, uma vez que n\u00e3o \u00e9 ente algum sendo a pura possibilita\u00e7\u00e3o de possibilidade, ent\u00e3o a ess\u00eancia do Ser, a ess\u00eancia da verdade, \u00e9 a liberdade. E isto quer dizer t\u00e3o somente que a verdade, o Ser, \u00e9 o pr\u00f3prio sentido de Acontecimento [das Ereignis]: o velamento-desvelamento. Velamento porquanto seja sempre em ess\u00eancia o escuro do nada de ente possibilitador da clareira enquanto as possibilidades de Mundo que permitem que o ente na totalidade apare\u00e7a enquanto tal e desvelamento consequente manifesto desde essas possibilidades no dar-se do Ser j\u00e1 enquanto sentido hist\u00f3rico-circunscrito (ente): Mundo institu\u00eddo, a cada vez, em cada povo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Essa estrutura do Ser e da verdade enquanto liberdade, nos ensina que n\u00e3o h\u00e1 a possibilidade uma verdade hist\u00f3rica (de um povo) que possa ser universal para todos os Mundos de sentido; justamente porque o Ser do Mundo \u00e9 a sua finitude enquanto circunscri\u00e7\u00e3o, de modo que cada povo, cada Mundo tem sua verdade do Ser t\u00e3o verdade como todas as outras de outros Mundos de sentido por conta da estrutura do Acontecimento do Ser. N\u00e3o h\u00e1 portanto aqui para teorias sobre a evolu\u00e7\u00e3o: pois esta j\u00e1 sempre pressup\u00f5e que a verdade e a significa\u00e7\u00e3o acerca do ente na totalidade vem evoluindo, do mais baixo para o mais complexo; e neste complexo estaria a verdade mais verdadeira. Assim pensa o Mundo da tecno-ci\u00eancia europeia que se manifesta, hoje, planetariamente. Da\u00ed a ilus\u00e3o de que a verdade do Mundo de sentido euroc\u00eantrico seja a verdade \u201cevolu\u00edda\u201d que os povos \u201cprimitivos\u201d n\u00e3o puderam alcan\u00e7ar; de onde tamb\u00e9m surge o sentido de supremacia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Programa\u00e7\u00e3o (cronograma)<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aula I &nbsp;(09\/12\/24) \u2013 Introdu\u00e7\u00e3o \u00e0 estrutura da compreens\u00e3o do Ser enquanto ser-no-mundo na primeira parte da obra Ser e Tempo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aula II (16\/12\/24) \u2013 Continuar explanando acerca da estrutura da compreens\u00e3o pormenorizada em Ser e Tempo enquanto possibilidade ontol\u00f3gica da linguagem &nbsp;e da Hist\u00f3ria. Come\u00e7ar a pensar a intramundaneidade do Ser e da verdade, portanto, sua finitude enquanto Mundo de sentido em oposi\u00e7\u00e3o \u00e0 universalidade e atemporalidade do Ser metaf\u00edsico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aula III (23\/12\/24) \u2013 Problematizar como Heidegger pensa a lida do Dasein com o ente que tem a forma do seu Ser (alteridade) e com os outros entes que n\u00e3o a tem para come\u00e7ar a compreender a temporalidade da compreens\u00e3o. &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aula IV (06\/01\/25) \u2013 Apresenta\u00e7\u00e3o do problema da n\u00e3o-subsist\u00eancia do Ser do Dasein em oposi\u00e7\u00e3o ao Ser do homem enquanto Sujeito subsistente de conhecimento e vontade. dos problemas fundamentais da segunda parte de Ser e Tempo, quais sejam: A Morte, A Delibera\u00e7\u00e3o, o d\u00e9bito, e a estrutura n\u00e3o-subsistente do Ser do Dasein.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aula V (13\/01\/25) &#8211; Pensar este sentido metaf\u00edsico (o pressuposto da atemporalidade e universalidade) para o Ser em oposi\u00e7\u00e3o aos existenciais heideggerianos, os quais encerram a metaf\u00edsica imputando o ser-no-mundo, o Mundo de sentido hist\u00f3rico-circunscrito e, portanto, inserindo pela primeira vez na hist\u00f3ria da filosofia a temporalidade, historicidade e finitude para o sentido do Ser.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aula VI (20\/01\/25) \u2013 Continuar a explana\u00e7\u00e3o da aula V.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aula VII (27\/01\/25) \u2013 &nbsp;Revisar todo o curso visando mostrar a temporalidade da compreens\u00e3o humana, a sua pretens\u00e3o impl\u00edcita de uma verdade (Ser) atemporal e universal ao longo de 2500 anos nas mais diversas figuras ontol\u00f3gico-metaf\u00edsicas, isto \u00e9, enquanto pressupostos atemporal e universal para a verdade. Evidenciar a contraposi\u00e7\u00e3o radical de Heidegger a tal universalidade e atemporalidade para a verdade, para o Mundo, para o ente na totalidade, para o Ser; o que nos levaria a dialogar propriamente com uma descoloniza\u00e7\u00e3o do pensamento humano.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A finitude do Mundo na obra Ser e Tempo de Martin Heidegger em di\u00e1logo com o pensamento da Decolonialidade &#8211; Profa. Dra. [&hellip;]<\/p>\n","protected":false},"author":54,"featured_media":5039,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_themeisle_gutenberg_block_has_review":false,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[13,6],"tags":[],"class_list":["post-5038","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventos","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Curso de Extens\u00e3o &quot;A finitude do Mundo na obra Ser e Tempo de Martin Heidegger em di\u00e1logo com o pensamento da Decolonialidade&quot; | Profa. Dra. Manuela Saadeh (PPGFil-UFRRJ) - Programa de P\u00f3s-Gradua\u00e7\u00e3o em Filosofia - UFRRJ<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgfil\/curso-de-extensao-a-finitude-do-mundo-na-obra-ser-e-tempo-de-martin-heidegger-em-dialogo-com-o-pensamento-da-decolonialidade-profa-dra-manuela-saadeh-ppgfil-ufrrj\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Curso de Extens\u00e3o &quot;A finitude do Mundo na obra Ser e Tempo de Martin Heidegger em di\u00e1logo com o pensamento da Decolonialidade&quot; | Profa. Dra. Manuela Saadeh (PPGFil-UFRRJ) - Programa de P\u00f3s-Gradua\u00e7\u00e3o em Filosofia - UFRRJ\" \/>\n<meta property=\"og:description\" content=\"A finitude do Mundo na obra Ser e Tempo de Martin Heidegger em di\u00e1logo com o pensamento da Decolonialidade &#8211; Profa. Dra. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgfil\/curso-de-extensao-a-finitude-do-mundo-na-obra-ser-e-tempo-de-martin-heidegger-em-dialogo-com-o-pensamento-da-decolonialidade-profa-dra-manuela-saadeh-ppgfil-ufrrj\/\" \/>\n<meta property=\"og:site_name\" content=\"Programa de P\u00f3s-Gradua\u00e7\u00e3o em Filosofia - UFRRJ\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-02T15:06:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-02T15:06:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgfil\/files\/2024\/12\/241121_img_heiddeger.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"danilobilate\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"danilobilate\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgfil\\\/curso-de-extensao-a-finitude-do-mundo-na-obra-ser-e-tempo-de-martin-heidegger-em-dialogo-com-o-pensamento-da-decolonialidade-profa-dra-manuela-saadeh-ppgfil-ufrrj\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgfil\\\/curso-de-extensao-a-finitude-do-mundo-na-obra-ser-e-tempo-de-martin-heidegger-em-dialogo-com-o-pensamento-da-decolonialidade-profa-dra-manuela-saadeh-ppgfil-ufrrj\\\/\"},\"author\":{\"name\":\"danilobilate\",\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgfil\\\/#\\\/schema\\\/person\\\/b071a8f9b7bf339652074bedb06bc661\"},\"headline\":\"Curso de Extens\u00e3o &#8220;A finitude do Mundo na obra Ser e Tempo de Martin Heidegger em di\u00e1logo com o pensamento da Decolonialidade&#8221; | Profa. Dra. Manuela Saadeh (PPGFil-UFRRJ)\",\"datePublished\":\"2024-12-02T15:06:39+00:00\",\"dateModified\":\"2024-12-02T15:06:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgfil\\\/curso-de-extensao-a-finitude-do-mundo-na-obra-ser-e-tempo-de-martin-heidegger-em-dialogo-com-o-pensamento-da-decolonialidade-profa-dra-manuela-saadeh-ppgfil-ufrrj\\\/\"},\"wordCount\":1398,\"image\":{\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgfil\\\/curso-de-extensao-a-finitude-do-mundo-na-obra-ser-e-tempo-de-martin-heidegger-em-dialogo-com-o-pensamento-da-decolonialidade-profa-dra-manuela-saadeh-ppgfil-ufrrj\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgfil\\\/files\\\/2024\\\/12\\\/241121_img_heiddeger.jpg\",\"articleSection\":[\"Eventos\",\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgfil\\\/curso-de-extensao-a-finitude-do-mundo-na-obra-ser-e-tempo-de-martin-heidegger-em-dialogo-com-o-pensamento-da-decolonialidade-profa-dra-manuela-saadeh-ppgfil-ufrrj\\\/\",\"url\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgfil\\\/curso-de-extensao-a-finitude-do-mundo-na-obra-ser-e-tempo-de-martin-heidegger-em-dialogo-com-o-pensamento-da-decolonialidade-profa-dra-manuela-saadeh-ppgfil-ufrrj\\\/\",\"name\":\"Curso de Extens\u00e3o \\\"A finitude do Mundo na obra Ser e Tempo de Martin Heidegger em di\u00e1logo com o pensamento da Decolonialidade\\\" | Profa. Dra. Manuela Saadeh (PPGFil-UFRRJ) - Programa de P\u00f3s-Gradua\u00e7\u00e3o em Filosofia - UFRRJ\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgfil\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgfil\\\/curso-de-extensao-a-finitude-do-mundo-na-obra-ser-e-tempo-de-martin-heidegger-em-dialogo-com-o-pensamento-da-decolonialidade-profa-dra-manuela-saadeh-ppgfil-ufrrj\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgfil\\\/curso-de-extensao-a-finitude-do-mundo-na-obra-ser-e-tempo-de-martin-heidegger-em-dialogo-com-o-pensamento-da-decolonialidade-profa-dra-manuela-saadeh-ppgfil-ufrrj\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgfil\\\/files\\\/2024\\\/12\\\/241121_img_heiddeger.jpg\",\"datePublished\":\"2024-12-02T15:06:39+00:00\",\"dateModified\":\"2024-12-02T15:06:40+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgfil\\\/#\\\/schema\\\/person\\\/b071a8f9b7bf339652074bedb06bc661\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgfil\\\/curso-de-extensao-a-finitude-do-mundo-na-obra-ser-e-tempo-de-martin-heidegger-em-dialogo-com-o-pensamento-da-decolonialidade-profa-dra-manuela-saadeh-ppgfil-ufrrj\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgfil\\\/curso-de-extensao-a-finitude-do-mundo-na-obra-ser-e-tempo-de-martin-heidegger-em-dialogo-com-o-pensamento-da-decolonialidade-profa-dra-manuela-saadeh-ppgfil-ufrrj\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgfil\\\/curso-de-extensao-a-finitude-do-mundo-na-obra-ser-e-tempo-de-martin-heidegger-em-dialogo-com-o-pensamento-da-decolonialidade-profa-dra-manuela-saadeh-ppgfil-ufrrj\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgfil\\\/files\\\/2024\\\/12\\\/241121_img_heiddeger.jpg\",\"contentUrl\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgfil\\\/files\\\/2024\\\/12\\\/241121_img_heiddeger.jpg\",\"width\":800,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgfil\\\/curso-de-extensao-a-finitude-do-mundo-na-obra-ser-e-tempo-de-martin-heidegger-em-dialogo-com-o-pensamento-da-decolonialidade-profa-dra-manuela-saadeh-ppgfil-ufrrj\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgfil\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Curso de Extens\u00e3o &#8220;A finitude do Mundo na obra Ser e Tempo de Martin Heidegger em di\u00e1logo com o pensamento da Decolonialidade&#8221; | Profa. Dra. Manuela Saadeh (PPGFil-UFRRJ)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgfil\\\/#website\",\"url\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgfil\\\/\",\"name\":\"Programa de P\u00f3s-Gradua\u00e7\u00e3o em Filosofia - UFRRJ\",\"description\":\"Programa de P\u00f3s-Gradua\u00e7\u00e3o em Filosofia - UFRRJ\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgfil\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgfil\\\/#\\\/schema\\\/person\\\/b071a8f9b7bf339652074bedb06bc661\",\"name\":\"danilobilate\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/de140275cd365ea398b5b2d21f1d6a416068173f45957775feecf1f5479ec501?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/de140275cd365ea398b5b2d21f1d6a416068173f45957775feecf1f5479ec501?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/de140275cd365ea398b5b2d21f1d6a416068173f45957775feecf1f5479ec501?s=96&d=mm&r=g\",\"caption\":\"danilobilate\"},\"url\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgfil\\\/author\\\/danilobilate\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Curso de Extens\u00e3o \"A finitude do Mundo na obra Ser e Tempo de Martin Heidegger em di\u00e1logo com o pensamento da Decolonialidade\" | Profa. Dra. Manuela Saadeh (PPGFil-UFRRJ) - Programa de P\u00f3s-Gradua\u00e7\u00e3o em Filosofia - UFRRJ","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgfil\/curso-de-extensao-a-finitude-do-mundo-na-obra-ser-e-tempo-de-martin-heidegger-em-dialogo-com-o-pensamento-da-decolonialidade-profa-dra-manuela-saadeh-ppgfil-ufrrj\/","og_locale":"pt_BR","og_type":"article","og_title":"Curso de Extens\u00e3o \"A finitude do Mundo na obra Ser e Tempo de Martin Heidegger em di\u00e1logo com o pensamento da Decolonialidade\" | Profa. Dra. Manuela Saadeh (PPGFil-UFRRJ) - Programa de P\u00f3s-Gradua\u00e7\u00e3o em Filosofia - UFRRJ","og_description":"A finitude do Mundo na obra Ser e Tempo de Martin Heidegger em di\u00e1logo com o pensamento da Decolonialidade &#8211; Profa. Dra. [&hellip;]","og_url":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgfil\/curso-de-extensao-a-finitude-do-mundo-na-obra-ser-e-tempo-de-martin-heidegger-em-dialogo-com-o-pensamento-da-decolonialidade-profa-dra-manuela-saadeh-ppgfil-ufrrj\/","og_site_name":"Programa de P\u00f3s-Gradua\u00e7\u00e3o em Filosofia - UFRRJ","article_published_time":"2024-12-02T15:06:39+00:00","article_modified_time":"2024-12-02T15:06:40+00:00","og_image":[{"width":800,"height":400,"url":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgfil\/files\/2024\/12\/241121_img_heiddeger.jpg","type":"image\/jpeg"}],"author":"danilobilate","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"danilobilate","Est. tempo de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgfil\/curso-de-extensao-a-finitude-do-mundo-na-obra-ser-e-tempo-de-martin-heidegger-em-dialogo-com-o-pensamento-da-decolonialidade-profa-dra-manuela-saadeh-ppgfil-ufrrj\/#article","isPartOf":{"@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgfil\/curso-de-extensao-a-finitude-do-mundo-na-obra-ser-e-tempo-de-martin-heidegger-em-dialogo-com-o-pensamento-da-decolonialidade-profa-dra-manuela-saadeh-ppgfil-ufrrj\/"},"author":{"name":"danilobilate","@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgfil\/#\/schema\/person\/b071a8f9b7bf339652074bedb06bc661"},"headline":"Curso de Extens\u00e3o &#8220;A finitude do Mundo na obra Ser e Tempo de Martin Heidegger em di\u00e1logo com o pensamento da Decolonialidade&#8221; | Profa. Dra. Manuela Saadeh (PPGFil-UFRRJ)","datePublished":"2024-12-02T15:06:39+00:00","dateModified":"2024-12-02T15:06:40+00:00","mainEntityOfPage":{"@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgfil\/curso-de-extensao-a-finitude-do-mundo-na-obra-ser-e-tempo-de-martin-heidegger-em-dialogo-com-o-pensamento-da-decolonialidade-profa-dra-manuela-saadeh-ppgfil-ufrrj\/"},"wordCount":1398,"image":{"@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgfil\/curso-de-extensao-a-finitude-do-mundo-na-obra-ser-e-tempo-de-martin-heidegger-em-dialogo-com-o-pensamento-da-decolonialidade-profa-dra-manuela-saadeh-ppgfil-ufrrj\/#primaryimage"},"thumbnailUrl":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgfil\/files\/2024\/12\/241121_img_heiddeger.jpg","articleSection":["Eventos","Not\u00edcias"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgfil\/curso-de-extensao-a-finitude-do-mundo-na-obra-ser-e-tempo-de-martin-heidegger-em-dialogo-com-o-pensamento-da-decolonialidade-profa-dra-manuela-saadeh-ppgfil-ufrrj\/","url":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgfil\/curso-de-extensao-a-finitude-do-mundo-na-obra-ser-e-tempo-de-martin-heidegger-em-dialogo-com-o-pensamento-da-decolonialidade-profa-dra-manuela-saadeh-ppgfil-ufrrj\/","name":"Curso de Extens\u00e3o \"A finitude do Mundo na obra Ser e Tempo de Martin Heidegger em di\u00e1logo com o pensamento da Decolonialidade\" | Profa. Dra. Manuela Saadeh (PPGFil-UFRRJ) - Programa de P\u00f3s-Gradua\u00e7\u00e3o em Filosofia - UFRRJ","isPartOf":{"@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgfil\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgfil\/curso-de-extensao-a-finitude-do-mundo-na-obra-ser-e-tempo-de-martin-heidegger-em-dialogo-com-o-pensamento-da-decolonialidade-profa-dra-manuela-saadeh-ppgfil-ufrrj\/#primaryimage"},"image":{"@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgfil\/curso-de-extensao-a-finitude-do-mundo-na-obra-ser-e-tempo-de-martin-heidegger-em-dialogo-com-o-pensamento-da-decolonialidade-profa-dra-manuela-saadeh-ppgfil-ufrrj\/#primaryimage"},"thumbnailUrl":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgfil\/files\/2024\/12\/241121_img_heiddeger.jpg","datePublished":"2024-12-02T15:06:39+00:00","dateModified":"2024-12-02T15:06:40+00:00","author":{"@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgfil\/#\/schema\/person\/b071a8f9b7bf339652074bedb06bc661"},"breadcrumb":{"@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgfil\/curso-de-extensao-a-finitude-do-mundo-na-obra-ser-e-tempo-de-martin-heidegger-em-dialogo-com-o-pensamento-da-decolonialidade-profa-dra-manuela-saadeh-ppgfil-ufrrj\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgfil\/curso-de-extensao-a-finitude-do-mundo-na-obra-ser-e-tempo-de-martin-heidegger-em-dialogo-com-o-pensamento-da-decolonialidade-profa-dra-manuela-saadeh-ppgfil-ufrrj\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgfil\/curso-de-extensao-a-finitude-do-mundo-na-obra-ser-e-tempo-de-martin-heidegger-em-dialogo-com-o-pensamento-da-decolonialidade-profa-dra-manuela-saadeh-ppgfil-ufrrj\/#primaryimage","url":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgfil\/files\/2024\/12\/241121_img_heiddeger.jpg","contentUrl":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgfil\/files\/2024\/12\/241121_img_heiddeger.jpg","width":800,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgfil\/curso-de-extensao-a-finitude-do-mundo-na-obra-ser-e-tempo-de-martin-heidegger-em-dialogo-com-o-pensamento-da-decolonialidade-profa-dra-manuela-saadeh-ppgfil-ufrrj\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgfil\/en\/"},{"@type":"ListItem","position":2,"name":"Curso de Extens\u00e3o &#8220;A finitude do Mundo na obra Ser e Tempo de Martin Heidegger em di\u00e1logo com o pensamento da Decolonialidade&#8221; | Profa. Dra. Manuela Saadeh (PPGFil-UFRRJ)"}]},{"@type":"WebSite","@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgfil\/#website","url":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgfil\/","name":"Programa de P\u00f3s-Gradua\u00e7\u00e3o em Filosofia - UFRRJ","description":"Programa de P\u00f3s-Gradua\u00e7\u00e3o em Filosofia - UFRRJ","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgfil\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgfil\/#\/schema\/person\/b071a8f9b7bf339652074bedb06bc661","name":"danilobilate","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/de140275cd365ea398b5b2d21f1d6a416068173f45957775feecf1f5479ec501?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/de140275cd365ea398b5b2d21f1d6a416068173f45957775feecf1f5479ec501?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/de140275cd365ea398b5b2d21f1d6a416068173f45957775feecf1f5479ec501?s=96&d=mm&r=g","caption":"danilobilate"},"url":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgfil\/author\/danilobilate\/"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgfil\/wp-json\/wp\/v2\/posts\/5038","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgfil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgfil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgfil\/wp-json\/wp\/v2\/users\/54"}],"replies":[{"embeddable":true,"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgfil\/wp-json\/wp\/v2\/comments?post=5038"}],"version-history":[{"count":3,"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgfil\/wp-json\/wp\/v2\/posts\/5038\/revisions"}],"predecessor-version":[{"id":5042,"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgfil\/wp-json\/wp\/v2\/posts\/5038\/revisions\/5042"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgfil\/wp-json\/wp\/v2\/media\/5039"}],"wp:attachment":[{"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgfil\/wp-json\/wp\/v2\/media?parent=5038"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgfil\/wp-json\/wp\/v2\/categories?post=5038"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgfil\/wp-json\/wp\/v2\/tags?post=5038"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}