{"id":6,"count":20,"description":"","link":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgf\/category\/corpo-docente\/","name":"Corpo Docente","slug":"corpo-docente","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arquivos Corpo Docente - Programa de P\u00f3s-Gradua\u00e7\u00e3o em Fitotecnia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgf\/category\/corpo-docente\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arquivos Corpo Docente - Programa de P\u00f3s-Gradua\u00e7\u00e3o em Fitotecnia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgf\/category\/corpo-docente\/\" \/>\n<meta property=\"og:site_name\" content=\"Programa de P\u00f3s-Gradua\u00e7\u00e3o em Fitotecnia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgf\\\/category\\\/corpo-docente\\\/\",\"url\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgf\\\/category\\\/corpo-docente\\\/\",\"name\":\"Arquivos Corpo Docente - Programa de P\u00f3s-Gradua\u00e7\u00e3o em Fitotecnia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgf\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgf\\\/category\\\/corpo-docente\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgf\\\/category\\\/corpo-docente\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgf\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Corpo Docente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgf\\\/#website\",\"url\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgf\\\/\",\"name\":\"Programa de P\u00f3s-Gradua\u00e7\u00e3o em Fitotecnia\",\"description\":\"Programa de P\u00f3s-Gradua\u00e7\u00e3o em Fitotecnia\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgf\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arquivos Corpo Docente - Programa de P\u00f3s-Gradua\u00e7\u00e3o em Fitotecnia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgf\/category\/corpo-docente\/","og_locale":"pt_BR","og_type":"article","og_title":"Arquivos Corpo Docente - Programa de P\u00f3s-Gradua\u00e7\u00e3o em Fitotecnia","og_url":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgf\/category\/corpo-docente\/","og_site_name":"Programa de P\u00f3s-Gradua\u00e7\u00e3o em Fitotecnia","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgf\/category\/corpo-docente\/","url":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgf\/category\/corpo-docente\/","name":"Arquivos Corpo Docente - Programa de P\u00f3s-Gradua\u00e7\u00e3o em Fitotecnia","isPartOf":{"@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgf\/#website"},"breadcrumb":{"@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgf\/category\/corpo-docente\/#breadcrumb"},"inLanguage":"pt-BR"},{"@type":"BreadcrumbList","@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgf\/category\/corpo-docente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgf\/"},{"@type":"ListItem","position":2,"name":"Corpo Docente"}]},{"@type":"WebSite","@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgf\/#website","url":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgf\/","name":"Programa de P\u00f3s-Gradua\u00e7\u00e3o em Fitotecnia","description":"Programa de P\u00f3s-Gradua\u00e7\u00e3o em Fitotecnia","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgf\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgf\/wp-json\/wp\/v2\/categories\/6","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgf\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgf\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgf\/wp-json\/wp\/v2\/posts?categories=6"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}