{"id":749,"date":"2015-10-04T09:27:09","date_gmt":"2015-10-04T12:27:09","guid":{"rendered":"http:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/?p=749"},"modified":"2015-10-04T09:27:09","modified_gmt":"2015-10-04T12:27:09","slug":"lancamento-de-novo-livro-do-professor-pesquisador-do-mpge","status":"publish","type":"post","link":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/lancamento-de-novo-livro-do-professor-pesquisador-do-mpge\/","title":{"rendered":"Lan\u00e7amento de novo livro do Professor Pesquisador do MPGE"},"content":{"rendered":"<p><a href=\"http:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2015\/10\/1.png\"><img decoding=\"async\" class=\"alignnone size-medium wp-image-750\" src=\"http:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2015\/10\/1-208x300.png\" alt=\"1\" width=\"208\" height=\"300\" srcset=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2015\/10\/1-208x300.png 208w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2015\/10\/1.png 370w\" sizes=\"(max-width: 208px) 100vw, 208px\" \/><\/a><\/p>\n<p>Est\u00e1 saindo do forno o novo livro do Professor do MPGE, Saulo Barbar\u00e1, denominado &#8220;Instrumentos de Gest\u00e3o P\u00fablica&#8221;.<\/p>\n<p>&#8220;&#8221;Instrumentos de Gest\u00e3o P\u00fablica\u201d surge em momento no qual a sociedade brasileira, mais exigente e atenta ao funcionamento do Estado, clama por servi\u00e7os p\u00fablicos capazes de promover efetivamente seus direitos inscritos na Constitui\u00e7\u00e3o Federal, financiados pela arrecada\u00e7\u00e3o de tributos, impostos e contribui\u00e7\u00f5es legalmente institu\u00eddas. Mais do que nunca <span class=\"text_exposed_show\">\u00e9 necess\u00e1rio tornar mais eficiente a gest\u00e3o dos entes p\u00fablicos, t\u00e3o necess\u00e1rios \u00e0 vida cotidiana e \u00e0 implanta\u00e7\u00e3o de pol\u00edticas p\u00fablicas que promovam direitos e servi\u00e7os essenciais. A obra exp\u00f5e esses desafios que envolvem a forma\u00e7\u00e3o e a qualifica\u00e7\u00e3o dos servidores p\u00fablicos, sua compreens\u00e3o sobre o papel do Estado e o seu trabalho, al\u00e9m da estrutura organizacional e operacional das institui\u00e7\u00f5es&#8221;.<\/span><\/p>\n<div class=\"text_exposed_show\">\n<p>A obra j\u00e1 est\u00e1 dispon\u00edvel no site da Editora Saraiva e nas melhores livrarias do pa\u00eds: <a href=\"http:\/\/www.saraiva.com.br\/instrumentos-de-gestao-publica-9086949.html\" target=\"_blank\" rel=\"nofollow\">http:\/\/www.saraiva.com.br\/instrumentos-de-gestao-publica-90\u2026<\/a><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Est\u00e1 saindo do forno o novo livro do Professor do MPGE, Saulo Barbar\u00e1, denominado &#8220;Instrumentos de Gest\u00e3o P\u00fablica&#8221;. &#8220;&#8221;Instrumentos de Gest\u00e3o P\u00fablica\u201d [&hellip;]<\/p>\n","protected":false},"author":34,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[12],"tags":[],"class_list":["post-749","post","type-post","status-publish","format-standard","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lan\u00e7amento de novo livro do Professor Pesquisador do MPGE - Programa de P\u00f3s-gradua\u00e7\u00e3o em Gest\u00e3o e Estrat\u00e9gia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/lancamento-de-novo-livro-do-professor-pesquisador-do-mpge\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lan\u00e7amento de novo livro do Professor Pesquisador do MPGE - Programa de P\u00f3s-gradua\u00e7\u00e3o em Gest\u00e3o e Estrat\u00e9gia\" \/>\n<meta property=\"og:description\" content=\"Est\u00e1 saindo do forno o novo livro do Professor do MPGE, Saulo Barbar\u00e1, denominado &#8220;Instrumentos de Gest\u00e3o P\u00fablica&#8221;. &#8220;&#8221;Instrumentos de Gest\u00e3o P\u00fablica\u201d [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/lancamento-de-novo-livro-do-professor-pesquisador-do-mpge\/\" \/>\n<meta property=\"og:site_name\" content=\"Programa de P\u00f3s-gradua\u00e7\u00e3o em Gest\u00e3o e Estrat\u00e9gia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MestradoProfissionalEmGestaoeEstrategia\" \/>\n<meta property=\"article:published_time\" content=\"2015-10-04T12:27:09+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2015\/10\/1-208x300.png\" \/>\n<meta name=\"author\" content=\"Flavia Luiza\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Flavia Luiza\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppge\\\/lancamento-de-novo-livro-do-professor-pesquisador-do-mpge\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppge\\\/lancamento-de-novo-livro-do-professor-pesquisador-do-mpge\\\/\"},\"author\":{\"name\":\"Flavia Luiza\",\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppge\\\/#\\\/schema\\\/person\\\/646fd7af752e31f864a22a60a2ba0cbf\"},\"headline\":\"Lan\u00e7amento de novo livro do Professor Pesquisador do MPGE\",\"datePublished\":\"2015-10-04T12:27:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppge\\\/lancamento-de-novo-livro-do-professor-pesquisador-do-mpge\\\/\"},\"wordCount\":184,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppge\\\/lancamento-de-novo-livro-do-professor-pesquisador-do-mpge\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppge\\\/files\\\/2015\\\/10\\\/1-208x300.png\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppge\\\/lancamento-de-novo-livro-do-professor-pesquisador-do-mpge\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppge\\\/lancamento-de-novo-livro-do-professor-pesquisador-do-mpge\\\/\",\"url\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppge\\\/lancamento-de-novo-livro-do-professor-pesquisador-do-mpge\\\/\",\"name\":\"Lan\u00e7amento de novo livro do Professor Pesquisador do MPGE - Programa de P\u00f3s-gradua\u00e7\u00e3o em Gest\u00e3o e Estrat\u00e9gia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppge\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppge\\\/lancamento-de-novo-livro-do-professor-pesquisador-do-mpge\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppge\\\/lancamento-de-novo-livro-do-professor-pesquisador-do-mpge\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppge\\\/files\\\/2015\\\/10\\\/1-208x300.png\",\"datePublished\":\"2015-10-04T12:27:09+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppge\\\/#\\\/schema\\\/person\\\/646fd7af752e31f864a22a60a2ba0cbf\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppge\\\/lancamento-de-novo-livro-do-professor-pesquisador-do-mpge\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppge\\\/lancamento-de-novo-livro-do-professor-pesquisador-do-mpge\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppge\\\/lancamento-de-novo-livro-do-professor-pesquisador-do-mpge\\\/#primaryimage\",\"url\":\"http:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppge\\\/files\\\/2015\\\/10\\\/1-208x300.png\",\"contentUrl\":\"http:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppge\\\/files\\\/2015\\\/10\\\/1-208x300.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppge\\\/lancamento-de-novo-livro-do-professor-pesquisador-do-mpge\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppge\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lan\u00e7amento de novo livro do Professor Pesquisador do MPGE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppge\\\/#website\",\"url\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppge\\\/\",\"name\":\"Programa de P\u00f3s-gradua\u00e7\u00e3o em Gest\u00e3o e Estrat\u00e9gia\",\"description\":\"Universidade Federal Rural do Rio de Janeiro \u2013 UFRRJ\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppge\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppge\\\/#\\\/schema\\\/person\\\/646fd7af752e31f864a22a60a2ba0cbf\",\"name\":\"Flavia Luiza\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/aeb49669330eb5a08102f847a82ed0c2ce78fd3987904f418ebd349a248b882d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/aeb49669330eb5a08102f847a82ed0c2ce78fd3987904f418ebd349a248b882d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/aeb49669330eb5a08102f847a82ed0c2ce78fd3987904f418ebd349a248b882d?s=96&d=mm&r=g\",\"caption\":\"Flavia Luiza\"},\"description\":\"GLPI 38949\",\"url\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppge\\\/author\\\/flavia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lan\u00e7amento de novo livro do Professor Pesquisador do MPGE - Programa de P\u00f3s-gradua\u00e7\u00e3o em Gest\u00e3o e Estrat\u00e9gia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/lancamento-de-novo-livro-do-professor-pesquisador-do-mpge\/","og_locale":"pt_BR","og_type":"article","og_title":"Lan\u00e7amento de novo livro do Professor Pesquisador do MPGE - Programa de P\u00f3s-gradua\u00e7\u00e3o em Gest\u00e3o e Estrat\u00e9gia","og_description":"Est\u00e1 saindo do forno o novo livro do Professor do MPGE, Saulo Barbar\u00e1, denominado &#8220;Instrumentos de Gest\u00e3o P\u00fablica&#8221;. &#8220;&#8221;Instrumentos de Gest\u00e3o P\u00fablica\u201d [&hellip;]","og_url":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/lancamento-de-novo-livro-do-professor-pesquisador-do-mpge\/","og_site_name":"Programa de P\u00f3s-gradua\u00e7\u00e3o em Gest\u00e3o e Estrat\u00e9gia","article_publisher":"https:\/\/www.facebook.com\/MestradoProfissionalEmGestaoeEstrategia","article_published_time":"2015-10-04T12:27:09+00:00","og_image":[{"url":"http:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2015\/10\/1-208x300.png","type":"","width":"","height":""}],"author":"Flavia Luiza","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Flavia Luiza","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/lancamento-de-novo-livro-do-professor-pesquisador-do-mpge\/#article","isPartOf":{"@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/lancamento-de-novo-livro-do-professor-pesquisador-do-mpge\/"},"author":{"name":"Flavia Luiza","@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/#\/schema\/person\/646fd7af752e31f864a22a60a2ba0cbf"},"headline":"Lan\u00e7amento de novo livro do Professor Pesquisador do MPGE","datePublished":"2015-10-04T12:27:09+00:00","mainEntityOfPage":{"@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/lancamento-de-novo-livro-do-professor-pesquisador-do-mpge\/"},"wordCount":184,"commentCount":0,"image":{"@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/lancamento-de-novo-livro-do-professor-pesquisador-do-mpge\/#primaryimage"},"thumbnailUrl":"http:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2015\/10\/1-208x300.png","articleSection":["Noticias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/lancamento-de-novo-livro-do-professor-pesquisador-do-mpge\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/lancamento-de-novo-livro-do-professor-pesquisador-do-mpge\/","url":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/lancamento-de-novo-livro-do-professor-pesquisador-do-mpge\/","name":"Lan\u00e7amento de novo livro do Professor Pesquisador do MPGE - Programa de P\u00f3s-gradua\u00e7\u00e3o em Gest\u00e3o e Estrat\u00e9gia","isPartOf":{"@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/lancamento-de-novo-livro-do-professor-pesquisador-do-mpge\/#primaryimage"},"image":{"@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/lancamento-de-novo-livro-do-professor-pesquisador-do-mpge\/#primaryimage"},"thumbnailUrl":"http:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2015\/10\/1-208x300.png","datePublished":"2015-10-04T12:27:09+00:00","author":{"@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/#\/schema\/person\/646fd7af752e31f864a22a60a2ba0cbf"},"breadcrumb":{"@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/lancamento-de-novo-livro-do-professor-pesquisador-do-mpge\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/lancamento-de-novo-livro-do-professor-pesquisador-do-mpge\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/lancamento-de-novo-livro-do-professor-pesquisador-do-mpge\/#primaryimage","url":"http:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2015\/10\/1-208x300.png","contentUrl":"http:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2015\/10\/1-208x300.png"},{"@type":"BreadcrumbList","@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/lancamento-de-novo-livro-do-professor-pesquisador-do-mpge\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/"},{"@type":"ListItem","position":2,"name":"Lan\u00e7amento de novo livro do Professor Pesquisador do MPGE"}]},{"@type":"WebSite","@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/#website","url":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/","name":"Programa de P\u00f3s-gradua\u00e7\u00e3o em Gest\u00e3o e Estrat\u00e9gia","description":"Universidade Federal Rural do Rio de Janeiro \u2013 UFRRJ","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/#\/schema\/person\/646fd7af752e31f864a22a60a2ba0cbf","name":"Flavia Luiza","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/aeb49669330eb5a08102f847a82ed0c2ce78fd3987904f418ebd349a248b882d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/aeb49669330eb5a08102f847a82ed0c2ce78fd3987904f418ebd349a248b882d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/aeb49669330eb5a08102f847a82ed0c2ce78fd3987904f418ebd349a248b882d?s=96&d=mm&r=g","caption":"Flavia Luiza"},"description":"GLPI 38949","url":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/author\/flavia\/"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/wp-json\/wp\/v2\/posts\/749","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/wp-json\/wp\/v2\/comments?post=749"}],"version-history":[{"count":1,"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/wp-json\/wp\/v2\/posts\/749\/revisions"}],"predecessor-version":[{"id":751,"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/wp-json\/wp\/v2\/posts\/749\/revisions\/751"}],"wp:attachment":[{"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/wp-json\/wp\/v2\/media?parent=749"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/wp-json\/wp\/v2\/categories?post=749"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/wp-json\/wp\/v2\/tags?post=749"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}