{"id":10990,"date":"2025-10-23T17:58:34","date_gmt":"2025-10-23T20:58:34","guid":{"rendered":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/?p=10990"},"modified":"2026-07-14T15:27:42","modified_gmt":"2026-07-14T18:27:42","slug":"corpodocentea","status":"publish","type":"post","link":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/corpodocentea\/","title":{"rendered":"Corpo Docente"},"content":{"rendered":"\n<h2 class=\"wp-block-heading has-text-align-center has-white-color has-midnight-gradient-background has-text-color has-background has-link-color has-medium-font-size wp-elements-758442b581b3968eddd187eef5ab1117\">Docentes da Linha 1<\/h2>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-4-1024x1024.jpg\" alt=\"Andre Cribb\" class=\"wp-image-10596\" style=\"aspect-ratio:4\/3;object-fit:contain\" srcset=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-4-1024x1024.jpg 1024w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-4-300x300.jpg 300w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-4-150x150.jpg 150w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-4-768x768.jpg 768w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-4-200x200.jpg 200w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-4-70x70.jpg 70w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-4.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" style=\"font-size:20px\">Andr\u00e9 Yves Cribb<\/h2>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\" style=\"text-decoration:underline\"><strong>Permanente<\/strong><\/p>\n\n\n\n<div class=\"wp-block-group is-content-justification-center is-nowrap is-layout-flex wp-container-core-group-is-layout-d05cb3ef wp-block-group-is-layout-flex\">\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\" style=\"font-size:16px\"><summary>Resumo<\/summary>\n<p class=\"wp-block-paragraph\" style=\"font-size:16px\">Engenheiro Agr\u00f4nomo pela UEH, Detentor de Certificado de Conclus\u00e3o do Ciclo de quatro anos de Estudos em n\u00edvel de Gradua\u00e7\u00e3o em Ci\u00eancias Econ\u00f4micas pela UEH e Mestre em Desenvolvimento Agr\u00edcola pela UFRRJ, concluiu o Doutorado em Engenharia de Produ\u00e7\u00e3o pela UFRJ e o P\u00f3s-Doutorado em Gest\u00e3o de PD Agropecu\u00e1rio pelo ICRA \/ Montpellier \/ Fran\u00e7a. Exerceu o cargo de Supervisor do Setor de Prospec\u00e7\u00e3o e Avalia\u00e7\u00e3o de Tecnologias e de Chefe-Adjunto Substituto de Transfer\u00eancia de Tecnologia na Embrapa Agroind\u00fastria de Alimentos (2011-2013). Atualmente, \u00e9 Pesquisador da Embrapa, Professor Permanente no Programa de P\u00f3s-Gradua\u00e7\u00e3o em Gest\u00e3o e Estrat\u00e9gia em Neg\u00f3cios da Universidade Federal Rural do Rio de Janeiro \u2013 UFRRJ (Rio de Janeiro, Brasil), Coordenador de Pesquisa Planejamento do GIFAD, Editor do Guia de Agronomia on-line, S\u00f3cio da SOBER, Avaliador do Journal of Information Systems and Technology Management, Consultor ad hoc da Revista Organiza\u00e7\u00f5es Rurais Agroindustriais, Revisor da Review of Business Management, Revisor da Revista Ibero-americana de Sistemas, Cibern\u00e9tica e Inform\u00e1tica, Revisor da Revista de Economia e Sociologia Rural, Revisor da Revista Gest\u00e3o Produ\u00e7\u00e3o, Revisor da Revista Informa\u00e7\u00f5es Econ\u00f4micas, Consultor Cient\u00edfico ad-hoc da FAPEMIG, Assessor ad-hoc da FAPESP, Consultor ad-hoc da Facepe, L\u00edder e Membro de Equipes de Projetos de PD, Membro de Comiss\u00f5es e Conselhos e Respons\u00e1vel pela Elabora\u00e7\u00e3o do Relat\u00f3rio Anual de Avalia\u00e7\u00e3o de Impactos de Tecnologias da Embrapa Agroind\u00fastria de Alimentos. Atuando como profissional desde 1982, tem experi\u00eancia na \u00e1rea de Economia, com \u00eanfase em Economia Rural. Dedica-se principalmente aos seguintes temas: gest\u00e3o do conhecimento, prospec\u00e7\u00e3o tecnol\u00f3gica, gest\u00e3o de PD, neg\u00f3cio tecnol\u00f3gico, gest\u00e3o da inova\u00e7\u00e3o, transfer\u00eancia de tecnologia, organiza\u00e7\u00e3o agroindustrial, avalia\u00e7\u00e3o de impactos de tecnologia, estudo de sistemas de produ\u00e7\u00e3o agr\u00edcola e diagn\u00f3stico de mercado.&nbsp;<a href=\"http:\/\/lattes.cnpq.br\/7853512647974161\" target=\"_blank\" rel=\"noreferrer noopener\">Lattes<\/a><\/p>\n<\/details>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:16px\"><a href=\"http:\/\/lattes.cnpq.br\/7853512647974161\" target=\"_blank\" rel=\"noreferrer noopener\">Lattes<\/a><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-group is-content-justification-center is-nowrap is-layout-flex wp-container-core-group-is-layout-d05cb3ef wp-block-group-is-layout-flex\">\n<ul class=\"wp-block-social-links is-layout-flex wp-block-social-links-is-layout-flex\"><li class=\"wp-social-link wp-social-link-mail wp-block-social-link\"><a href=\"mailto:&#097;n&#100;&#114;e.&#099;&#114;ibb&#064;embrap&#097;&#046;b&#114;\" class=\"wp-block-social-link-anchor\"><svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M19,5H5c-1.1,0-2,.9-2,2v10c0,1.1.9,2,2,2h14c1.1,0,2-.9,2-2V7c0-1.1-.9-2-2-2zm.5,12c0,.3-.2.5-.5.5H5c-.3,0-.5-.2-.5-.5V9.8l7.5,5.6,7.5-5.6V17zm0-9.1L12,13.6,4.5,7.9V7c0-.3.2-.5.5-.5h14c.3,0,.5.2.5.5v.9z\"><\/path><\/svg><span class=\"wp-block-social-link-label screen-reader-text\">E-mail<\/span><\/a><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:14px\">andre.cribb@embrapa.br<\/p>\n<\/div>\n<\/div><\/div>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\" style=\"font-size:13px\"><strong>ORCID:&nbsp;<a href=\"https:\/\/orcid.org\/0000-0003-4243-394X\" target=\"_blank\" rel=\"noreferrer noopener\">0000-0003-4243-394X<\/a><\/strong><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column has-midnight-gradient-background has-background is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:3px\"><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-6-1024x1024.jpg\" alt=\"\" class=\"wp-image-10602\" style=\"aspect-ratio:4\/3;object-fit:contain\" srcset=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-6-1024x1024.jpg 1024w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-6-300x300.jpg 300w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-6-150x150.jpg 150w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-6-768x768.jpg 768w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-6-200x200.jpg 200w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-6-70x70.jpg 70w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-6.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" style=\"font-size:20px\"> Beatriz Villardi<\/h2>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\" style=\"text-decoration:underline\"><strong>Permanente<\/strong><\/p>\n\n\n\n<div class=\"wp-block-group is-content-justification-center is-nowrap is-layout-flex wp-container-core-group-is-layout-d05cb3ef wp-block-group-is-layout-flex\">\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\" style=\"font-size:16px\"><summary>Resumo<\/summary>\n<p class=\"wp-block-paragraph\" style=\"font-size:16px\">Doutora em Administra\u00e7\u00e3o De Empresas na \u00c1rea de concentra\u00e7\u00e3o em Mudan\u00e7a Organizacional com Est\u00e1gio P\u00f3s Doutoral realizado sob o Edital Capes ColCiencias; Mestre em Administra\u00e7\u00e3o na \u00c1rea de Concentra\u00e7\u00e3o Planejamento e Organiza\u00e7\u00f5es; Bacharel em Administra\u00e7\u00e3o de Empresas P\u00fablicas e Privadas. Professora Doutora Associado. Atua no Curso de Gradua\u00e7\u00e3o em Administra\u00e7\u00e3o P\u00fablica do Dpto. Administra\u00e7\u00e3o P\u00fablica da Universidade Federal Rural Do Rio de Janeiro e Membro do N\u00facleo Docente Estruturante. Atua desde 2002 na P\u00f3s Gradua\u00e7\u00e3o stricto e lato sensu com experi\u00eancia de 2008 a 2013 em Vice Coordena\u00e7\u00e3o e, de 2013 a 2017 em Coordena\u00e7\u00e3o do Curso de Mestrado Profissional em Gest\u00e3o e Estrat\u00e9gia de 2013 \u2013 2017 onde continua Docente do Quadro Permanente do Mestrado Profissional em Gest\u00e3o e Estrat\u00e9gia \u2013 MPGE\/UFRRJ. Experiencia de 2013-2015 Coordenando o Mestrado Acad\u00eamico em Administra\u00e7\u00e3o \u2013 PPGA\/UFRRJ. Publica artigos cient\u00edficos em Peri\u00f3dicos Especializados e, Trabalhos Completos em Anais de Eventos da \u00c1rea de Administra\u00e7\u00e3o. L\u00edder de Tema sobre Epistemologia no ensino e pesquisa da Divis\u00e3o de Ensino e Pesquisa em Administra\u00e7\u00e3o e Contabilidade da ANPAD desde 2012. Experi\u00eancia profissional em gest\u00e3o de recursos humanos em empresas de constru\u00e7\u00e3o civil, de servi\u00e7os de alimenta\u00e7\u00e3o, de planejamento familiar e em consultoria sobre capacita\u00e7\u00e3o gerencial, avalia\u00e7\u00e3o de desempenho, planos de carreira e diagn\u00f3stico de clima organizacional. Desenvolve Produtos Tecnol\u00f3gicos e T\u00e9cnicos para Gest\u00e3o Estrat\u00e9gica de Pessoas em organiza\u00e7\u00f5es intensivas em conhecimento. Orienta Trabalhos de Conclus\u00e3o de Curso de Gradua\u00e7\u00e3o e de Mestrado. Pesquisa a Administra\u00e7\u00e3o P\u00fablica e Privada, com \u00canfase em Gest\u00e3o de Pessoas e Mudan\u00e7a Organizacional por meio de Estrat\u00e9gias de Aprendizagem Coletiva assim como em Gest\u00e3o Universit\u00e1ria e Desenvolvimento de Compet\u00eancias Profissionais Individuais e Organizacionais. Leciona e pesquisa em Cursos de Gradua\u00e7\u00e3o e P\u00f3s Gradua\u00e7\u00e3o Lato e Stricto Sensu em Administra\u00e7\u00e3o. Realiza pesquisa aplicada em Administra\u00e7\u00e3o, Diagn\u00f3stico Organizacional e Implanta\u00e7\u00e3o de Tecnologias de Estrat\u00e9gia Organizacional, Gest\u00e3o de Pessoas no Setor P\u00fablico e Privado e Desenvolvimento e Aprendizagem em organiza\u00e7\u00f5es de conhecimento intensivo, Desenvolvimento de compet\u00eancias e aprendizagem coletiva para ensino e pesquisa em administra\u00e7\u00e3o no Brasil e Latinoam\u00e9rica. Em pesquisa te\u00f3rica foca a epistemologia (phronesis, fenomenografia) e metodologia (reflexividade e an\u00e1lise fenomenogr\u00e1fica) em administra\u00e7\u00e3o para gerar conhecimento e interdisciplinar sobre as din\u00e2micas humanas e estrat\u00e9gias de gest\u00e3o do trabalho coletivo nas organiza\u00e7\u00f5es com \u00eanfase nos microprocessos de aprendizagem e mudan\u00e7a a partir das praticas compartilhadas. Avaliadora de revistas cient\u00edficas da \u00e1rea. Parecerista da Capes e do CNPQ. Membro do Conselho Fiscal Anpad mandato 2018 \u2013 2020.<a href=\"http:\/\/lattes.cnpq.br\/3613664703389917\">&nbsp;<\/a><a href=\"http:\/\/lattes.cnpq.br\/3613664703389917\" target=\"_blank\" rel=\"noreferrer noopener\">Lattes<\/a><\/p>\n<\/details>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:16px\"><a href=\"http:\/\/lattes.cnpq.br\/3613664703389917\" target=\"_blank\" rel=\"noreferrer noopener\">Lattes<\/a><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-group is-content-justification-center is-nowrap is-layout-flex wp-container-core-group-is-layout-d05cb3ef wp-block-group-is-layout-flex\">\n<ul class=\"wp-block-social-links is-layout-flex wp-block-social-links-is-layout-flex\"><li class=\"wp-social-link wp-social-link-mail wp-block-social-link\"><a href=\"https:\/\/rbvillardi@hotmail.com%20\" class=\"wp-block-social-link-anchor\"><svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M19,5H5c-1.1,0-2,.9-2,2v10c0,1.1.9,2,2,2h14c1.1,0,2-.9,2-2V7c0-1.1-.9-2-2-2zm.5,12c0,.3-.2.5-.5.5H5c-.3,0-.5-.2-.5-.5V9.8l7.5,5.6,7.5-5.6V17zm0-9.1L12,13.6,4.5,7.9V7c0-.3.2-.5.5-.5h14c.3,0,.5.2.5.5v.9z\"><\/path><\/svg><span class=\"wp-block-social-link-label screen-reader-text\">E-mail<\/span><\/a><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:14px\">rbvillardi@hotmail.com <\/p>\n<\/div>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\" style=\"font-size:13px\"><strong>ORCID:&nbsp;<a href=\"https:\/\/orcid.org\/0000-0001-9541-1694\" target=\"_blank\" rel=\"noreferrer noopener\">0000-0001-9541-1694<\/a><\/strong><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column has-midnight-gradient-background has-background is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:3px\"><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-7-1024x1024.jpg\" alt=\"\" class=\"wp-image-10603\" style=\"aspect-ratio:4\/3;object-fit:contain\" srcset=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-7-1024x1024.jpg 1024w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-7-300x300.jpg 300w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-7-150x150.jpg 150w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-7-768x768.jpg 768w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-7-200x200.jpg 200w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-7-70x70.jpg 70w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-7.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" style=\"font-size:20px\">Biancca Scarpeline<\/h2>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\" style=\"text-decoration:underline\"><strong>Permanente<\/strong><\/p>\n\n\n\n<div class=\"wp-block-group is-content-justification-center is-nowrap is-layout-flex wp-container-core-group-is-layout-d05cb3ef wp-block-group-is-layout-flex\">\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\" style=\"font-size:16px\"><summary>Resumo<\/summary>\n<p class=\"wp-block-paragraph\" style=\"font-size:16px\">Professora do curso de gradua\u00e7\u00e3o em Administra\u00e7\u00e3o P\u00fablica e do Programa de Mestrado Profissional em Gest\u00e3o e Estrat\u00e9gia (PPGE) da Universidade Federal Rural do Rio de Janeiro, Biancca S. de Castro, concluiu o doutorado em ci\u00eancias sociais na Universidade Estadual de Campinas, \u00e9 formada em ci\u00eancias econ\u00f4micas pela Universidade Estadual Paulista e possui mestrado em Desenvolvimento, Agricultura e Sociedade pela Universidade Federal Rural do Rio de Janeiro. Tem experi\u00eancia nas \u00e1reas de economia, sociologia e administra\u00e7\u00e3o p\u00fablica, atuando principalmente com as seguintes tem\u00e1ticas: Avalia\u00e7\u00e3o e Coordena\u00e7\u00e3o de pol\u00edticas p\u00fablicas; pol\u00edticas p\u00fablicas para ci\u00eancia e tecnologia, inova\u00e7\u00e3o e meio ambiente.&nbsp;<a href=\"http:\/\/lattes.cnpq.br\/6803897679311046\" target=\"_blank\" rel=\"noreferrer noopener\">Lattes<\/a><\/p>\n<\/details>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:16px\"><a href=\"http:\/\/lattes.cnpq.br\/6803897679311046\" target=\"_blank\" rel=\"noreferrer noopener\">Lattes<\/a><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-group is-content-justification-center is-nowrap is-layout-flex wp-container-core-group-is-layout-d05cb3ef wp-block-group-is-layout-flex\">\n<ul class=\"wp-block-social-links is-layout-flex wp-block-social-links-is-layout-flex\"><li class=\"wp-social-link wp-social-link-mail wp-block-social-link\"><a href=\"mailto:b&#105;ancc&#097;str&#111;2&#064;gm&#097;&#105;l.c&#111;m\" class=\"wp-block-social-link-anchor\"><svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M19,5H5c-1.1,0-2,.9-2,2v10c0,1.1.9,2,2,2h14c1.1,0,2-.9,2-2V7c0-1.1-.9-2-2-2zm.5,12c0,.3-.2.5-.5.5H5c-.3,0-.5-.2-.5-.5V9.8l7.5,5.6,7.5-5.6V17zm0-9.1L12,13.6,4.5,7.9V7c0-.3.2-.5.5-.5h14c.3,0,.5.2.5.5v.9z\"><\/path><\/svg><span class=\"wp-block-social-link-label screen-reader-text\">E-mail<\/span><\/a><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:14px\">bianccastro2@gmail.com<\/p>\n<\/div>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\" style=\"font-size:13px\"><strong>ORCID:&nbsp;<a href=\"https:\/\/orcid.org\/0000-0003-4878-1419\" target=\"_blank\" rel=\"noreferrer noopener\">0000-0003-4878-1419<\/a><\/strong><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-8-1024x1024.jpg\" alt=\"\" class=\"wp-image-10604\" style=\"aspect-ratio:4\/3;object-fit:contain\" srcset=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-8-1024x1024.jpg 1024w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-8-300x300.jpg 300w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-8-150x150.jpg 150w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-8-768x768.jpg 768w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-8-200x200.jpg 200w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-8-70x70.jpg 70w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-8.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" style=\"font-size:20px\">Caio Chain<\/h2>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\" style=\"text-decoration:underline\"><strong>Permanente<\/strong><\/p>\n\n\n\n<div class=\"wp-block-group is-content-justification-center is-nowrap is-layout-flex wp-container-core-group-is-layout-d05cb3ef wp-block-group-is-layout-flex\">\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\" style=\"font-size:16px\"><summary>Resumo<\/summary>\n<p class=\"wp-block-paragraph\" style=\"font-size:16px\">Caio Peixoto Chain \u00e9 graduado em Ci\u00eancias Econ\u00f4micas pela UFRRJ, mestre e doutor em Administra\u00e7\u00e3o pela UFLA. Atualmente \u00e9 professor do Departamento de Administra\u00e7\u00e3o P\u00fablica (DAP\/ICSA\/UFRRJ). Atua tamb\u00e9m como coordenador de discplina no curso de Administra\u00e7\u00e3o\/Cederj. Na p\u00f3s-gradua\u00e7\u00e3o est\u00e1 credenciado como docente permanente em dois programas: Gest\u00e3o e Estrat\u00e9gia (PPGE); e Economia Regional e Desenvolvimento (PPGER). Foi vice-chefe (2019\/21) e chefe (2021\/23) do DAP e vice-coordenador do PPGER (2022\/24). Atualmente \u00e9 vice-diretor do ICSA (2023\/27). Atua na \u00e1rea de Ci\u00eancias Sociais Aplicadas, com \u00eanfase em Administra\u00e7\u00e3o p\u00fablica, gest\u00e3o da cadeia de suprimentos, economia regional e gest\u00e3o agroindustrial.&nbsp;<a href=\"http:\/\/lattes.cnpq.br\/1332414714659455\" target=\"_blank\" rel=\"noreferrer noopener\">Lattes<\/a><\/p>\n<\/details>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:16px\"><a href=\"http:\/\/lattes.cnpq.br\/1332414714659455\" target=\"_blank\" rel=\"noreferrer noopener\">Lattes<\/a><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-group is-content-justification-center is-nowrap is-layout-flex wp-container-core-group-is-layout-d05cb3ef wp-block-group-is-layout-flex\">\n<ul class=\"wp-block-social-links is-layout-flex wp-block-social-links-is-layout-flex\"><li class=\"wp-social-link wp-social-link-mail wp-block-social-link\"><a href=\"https:\/\/caiochain.ufrrj@gmail.com%20\" class=\"wp-block-social-link-anchor\"><svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M19,5H5c-1.1,0-2,.9-2,2v10c0,1.1.9,2,2,2h14c1.1,0,2-.9,2-2V7c0-1.1-.9-2-2-2zm.5,12c0,.3-.2.5-.5.5H5c-.3,0-.5-.2-.5-.5V9.8l7.5,5.6,7.5-5.6V17zm0-9.1L12,13.6,4.5,7.9V7c0-.3.2-.5.5-.5h14c.3,0,.5.2.5.5v.9z\"><\/path><\/svg><span class=\"wp-block-social-link-label screen-reader-text\">E-mail<\/span><\/a><\/li><\/ul>\n\n\n\n<p class=\"wp-container-content-9cfa9a5a wp-block-paragraph\" style=\"font-size:12px\">caiochain.ufrrj@gmail.com <\/p>\n<\/div>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\" style=\"font-size:13px\"> <strong>ORCID:&nbsp;<a href=\"https:\/\/orcid.org\/0000-0002-9520-1547\" target=\"_blank\" rel=\"noreferrer noopener\">0000-0002-9520-1547<\/a><\/strong><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column has-midnight-gradient-background has-background is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:3px\"><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-9-1024x1024.jpg\" alt=\"\" class=\"wp-image-10605\" style=\"aspect-ratio:4\/3;object-fit:contain\" srcset=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-9-1024x1024.jpg 1024w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-9-300x300.jpg 300w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-9-150x150.jpg 150w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-9-768x768.jpg 768w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-9-200x200.jpg 200w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-9-70x70.jpg 70w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-9.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" style=\"font-size:20px\">Daniel Ribeiro <\/h2>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\" style=\"text-decoration:underline\"><strong>Permanente<\/strong><\/p>\n\n\n\n<div class=\"wp-block-group is-content-justification-center is-nowrap is-layout-flex wp-container-core-group-is-layout-d05cb3ef wp-block-group-is-layout-flex\">\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\" style=\"font-size:16px\"><summary>Resumo<\/summary>\n<p class=\"wp-block-paragraph\">Bacharel em Ci\u00eancias Econ\u00f4micas (2004) pela Universidade Federal Rural do Rio de Janeiro \u2013 UFRRJ, mestre (2007) e doutor (2011) em Economia pela Universidade Federal Fluminense \u2013 UFF. Professor do magist\u00e9rio superior em regime de dedica\u00e7\u00e3o exclusiva desde 2009 na UFRRJ, onde atualmente \u00e9 Professor Associado D 1, lotado no Departamento de Ci\u00eancias Econ\u00f4micas \u2013 DeCE do Instituto de Ci\u00eancias Sociais Aplicadas \u2013 ICSA. No ensino de gradua\u00e7\u00e3o em Economia atua principalmente nos temas ligados a macroeconomia, economia internacional e contabilidade nacional, na p\u00f3s-gradua\u00e7\u00e3o \u00e9 professor do corpo permanente do Programa de P\u00f3s-gradua\u00e7\u00e3o em Gest\u00e3o e Estrat\u00e9gia (mestrado profissional), onde leciona a disciplina de \u2018Organiza\u00e7\u00f5es, Estado e Gest\u00e3o P\u00fablica\u2019 e tamb\u00e9m orienta. Na \u00e1rea de gest\u00e3o acad\u00eamica tem experi\u00eancia como Chefe do DeCE e atualmente \u00e9 Diretor do ICSA, foi membro e presidente do Conselho de Curadores (CONCUR) da UFRRJ e \u00e9 presidente do Conselho de Ensino, Pesquisa e Extens\u00e3o da \u00c1rea de Ci\u00eancias Sociais Aplicadas (CEPEA-CSA). No campo da pesquisa coordenou diversos projetos com objetivo de orientar pol\u00edticas p\u00fablicas voltadas para o desenvolvimento socioecon\u00f4mico no estado do Rio de Janeiro. <a href=\"http:\/\/lattes.cnpq.br\/2545965022121459\" target=\"_blank\" rel=\"noreferrer noopener\">Lattes<\/a><\/p>\n<\/details>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:16px\"><a href=\"http:\/\/lattes.cnpq.br\/2545965022121459\" target=\"_blank\" rel=\"noreferrer noopener\">Lattes<\/a><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-group is-content-justification-center is-nowrap is-layout-flex wp-container-core-group-is-layout-d05cb3ef wp-block-group-is-layout-flex\">\n<ul class=\"wp-block-social-links is-layout-flex wp-block-social-links-is-layout-flex\"><li class=\"wp-social-link wp-social-link-mail wp-block-social-link\"><a href=\"mailto:&#100;a&#110;i&#101;l.eco&#064;&#117;&#111;l&#046;&#099;&#111;m&#046;br\" class=\"wp-block-social-link-anchor\"><svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M19,5H5c-1.1,0-2,.9-2,2v10c0,1.1.9,2,2,2h14c1.1,0,2-.9,2-2V7c0-1.1-.9-2-2-2zm.5,12c0,.3-.2.5-.5.5H5c-.3,0-.5-.2-.5-.5V9.8l7.5,5.6,7.5-5.6V17zm0-9.1L12,13.6,4.5,7.9V7c0-.3.2-.5.5-.5h14c.3,0,.5.2.5.5v.9z\"><\/path><\/svg><span class=\"wp-block-social-link-label screen-reader-text\">E-mail<\/span><\/a><\/li><\/ul>\n\n\n\n<p class=\"wp-container-content-9cfa9a5a wp-block-paragraph\" style=\"font-size:14px\">daniel.eco@uol.com.br<\/p>\n<\/div>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\" style=\"font-size:13px\"><strong>ORCID:&nbsp;<a href=\"https:\/\/orcid.org\/0000-0002-8787-8320\">0000-<\/a><a href=\"https:\/\/orcid.org\/0000-0002-8787-8320\" target=\"_blank\" rel=\"noreferrer noopener\">0002<\/a><a href=\"https:\/\/orcid.org\/0000-0002-8787-8320\">-8787-8320<\/a><\/strong><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column has-midnight-gradient-background has-background is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:3px\"><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-10-1024x1024.jpg\" alt=\"\" class=\"wp-image-10606\" style=\"aspect-ratio:4\/3;object-fit:contain\" srcset=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-10-1024x1024.jpg 1024w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-10-300x300.jpg 300w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-10-150x150.jpg 150w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-10-768x768.jpg 768w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-10-200x200.jpg 200w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-10-70x70.jpg 70w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-10.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" style=\"font-size:20px\">D\u00e9bora Vargas <\/h2>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\" style=\"text-decoration:underline\"><strong><strong>Colaborador<\/strong>a<\/strong><\/p>\n\n\n\n<div class=\"wp-block-group is-content-justification-center is-nowrap is-layout-flex wp-container-core-group-is-layout-d05cb3ef wp-block-group-is-layout-flex\">\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\" style=\"font-size:16px\"><summary>Resumo<\/summary>\n<p class=\"wp-block-paragraph\">Possui gradua\u00e7\u00e3o em Administra\u00e7\u00e3o de Empresas pela Universidade Federal de Juiz de Fora (2005), mestrado em Administra\u00e7\u00e3o pela Funda\u00e7\u00e3o Get\u00falio Vargas (2008) e doutorado em Administra\u00e7\u00e3o pela Universidade do Grande Rio (UNIGRANRIO) (2019). Atualmente \u00e9 Professora do Quadro Permanente do Mestrado em Gest\u00e3o &amp; Estrat\u00e9gia da UFRRJ na linha de pesquisa Gest\u00e3o Estrat\u00e9gica de Pessoas. \u00c9 Professora adjunta da Gradua\u00e7\u00e3o em Administra\u00e7\u00e3o da Universidade Federal Rural do Rio de Janeiro (UFRRJ ? campus Tr\u00eas Rios), das disciplinas de Gest\u00e3o de Pessoas e afins. Atua como chefe de departamento do DCAS, campus Tr\u00eas Rios. Tamb\u00e9m \u00e9 professora do MBA em Gest\u00e3o de Pessoas da UFJF. J\u00e1 atuou tamb\u00e9m como Gerente de Recrutamento, Sele\u00e7\u00e3o e Treinamento de multinacional do segmento de energia. Tem experi\u00eancia na \u00e1rea de Administra\u00e7\u00e3o, com \u00eanfase em Gest\u00e3o de Pessoas. Vice-l\u00edder do Grupo de Pesquisa em Gest\u00e3o Estrat\u00e9gica de Pessoas &amp; Organiza\u00e7\u00f5es (Diret\u00f3rio do CNPq). Membro do Grupo de Pesquisa\/CNPq: Grupo de Estudos e Pesquisas em Pessoas e Organiza\u00e7\u00f5es (UFJF) Pesquisa na \u00e1rea de Gest\u00e3o de Pessoas, Trabalho e Subjetividade. <a href=\"http:\/\/lattes.cnpq.br\/8509529172867577\" target=\"_blank\" rel=\"noreferrer noopener\">Lattes<\/a><\/p>\n<\/details>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:16px\"><a href=\"http:\/\/lattes.cnpq.br\/8509529172867577\" target=\"_blank\" rel=\"noreferrer noopener\">Lattes<\/a><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-group is-content-justification-center is-nowrap is-layout-flex wp-container-core-group-is-layout-d05cb3ef wp-block-group-is-layout-flex\">\n<ul class=\"wp-block-social-links is-nowrap is-layout-flex wp-container-core-social-links-is-layout-8f761849 wp-block-social-links-is-layout-flex\"><li class=\"wp-social-link wp-social-link-mail wp-block-social-link\"><a href=\"mailto:deb&#111;ra&#118;a&#114;&#103;as82&#064;&#103;m&#097;i&#108;&#046;co&#109;\" class=\"wp-block-social-link-anchor\"><svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M19,5H5c-1.1,0-2,.9-2,2v10c0,1.1.9,2,2,2h14c1.1,0,2-.9,2-2V7c0-1.1-.9-2-2-2zm.5,12c0,.3-.2.5-.5.5H5c-.3,0-.5-.2-.5-.5V9.8l7.5,5.6,7.5-5.6V17zm0-9.1L12,13.6,4.5,7.9V7c0-.3.2-.5.5-.5h14c.3,0,.5.2.5.5v.9z\"><\/path><\/svg><span class=\"wp-block-social-link-label screen-reader-text\">E-mail<\/span><\/a><\/li><\/ul>\n\n\n\n<p class=\"wp-container-content-9cfa9a5a wp-block-paragraph\" style=\"font-size:12px\">deboravargas82@gmail.com<\/p>\n<\/div>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\" style=\"font-size:13px\"> <strong>ORCID:&nbsp;<a href=\"https:\/\/orcid.org\/0000-0002-6716-6959\" target=\"_blank\" rel=\"noreferrer noopener\">0000-0002-6716-6959<\/a><\/strong><\/p>\n<\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-11-1024x1024.jpg\" alt=\"\" class=\"wp-image-10607\" style=\"aspect-ratio:4\/3;object-fit:contain\" srcset=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-11-1024x1024.jpg 1024w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-11-300x300.jpg 300w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-11-150x150.jpg 150w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-11-768x768.jpg 768w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-11-200x200.jpg 200w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-11-70x70.jpg 70w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-11.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" style=\"font-size:20px\">Fabr\u00edcia Constantino<\/h2>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\" style=\"text-decoration:underline\"><strong>Permanente<\/strong><\/p>\n\n\n\n<div class=\"wp-block-group is-content-justification-center is-nowrap is-layout-flex wp-container-core-group-is-layout-d05cb3ef wp-block-group-is-layout-flex\">\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\" style=\"font-size:16px\"><summary>Resumo<\/summary>\n<p class=\"wp-block-paragraph\" style=\"font-size:16px\">Doutora em Ci\u00eancias Cont\u00e1beis pela Universidade Federal do Rio de Janeiro (2020). Possui gradua\u00e7\u00e3o em Administra\u00e7\u00e3o pela Universidade Federal Rural do Rio de Janeiro (2005), mestrado em Administra\u00e7\u00e3o pela Universidade Federal de Minas Gerais (2008). \u00c9 Professora Adjunta da Universidade Federal Rural do Rio de Janeiro, no Departamento de Ci\u00eancias Cont\u00e1beis e Finan\u00e7as, atuando na gradua\u00e7\u00e3o presencial (nos cursos de Administra\u00e7\u00e3o, Ci\u00eancias cont\u00e1beis e outros) e EaD (Coordenadora de disciplinas do curso de Administra\u00e7\u00e3o do CEDERJ\/UFRRJ) com disciplinas da \u00e1rea financeira e cont\u00e1bil e no curso de Mestrado Profissional em Gest\u00e3o e Estrat\u00e9gia do PPGE\/UFRRJ. Desenvolve estudos sobre an\u00e1lise do conte\u00fado informacional da contabilidade, mercado segurador, regula\u00e7\u00e3o prudencial e an\u00e1lise de desempenho de institui\u00e7\u00f5es financeiras.&nbsp;<a href=\"http:\/\/lattes.cnpq.br\/7529250270305957\" target=\"_blank\" rel=\"noreferrer noopener\">Lattes<\/a><\/p>\n<\/details>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:16px\"><a href=\"http:\/\/lattes.cnpq.br\/7529250270305957\" target=\"_blank\" rel=\"noreferrer noopener\">Lattes<\/a><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-group is-content-justification-center is-nowrap is-layout-flex wp-container-core-group-is-layout-d05cb3ef wp-block-group-is-layout-flex\">\n<ul class=\"wp-block-social-links is-layout-flex wp-block-social-links-is-layout-flex\"><li class=\"wp-social-link wp-social-link-mail wp-block-social-link\"><a href=\"mailto:fa&#098;r&#105;ci&#097;d&#101;&#102;&#097;&#114;ias&#064;&#117;fr&#114;&#106;.&#098;&#114;\" class=\"wp-block-social-link-anchor\"><svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M19,5H5c-1.1,0-2,.9-2,2v10c0,1.1.9,2,2,2h14c1.1,0,2-.9,2-2V7c0-1.1-.9-2-2-2zm.5,12c0,.3-.2.5-.5.5H5c-.3,0-.5-.2-.5-.5V9.8l7.5,5.6,7.5-5.6V17zm0-9.1L12,13.6,4.5,7.9V7c0-.3.2-.5.5-.5h14c.3,0,.5.2.5.5v.9z\"><\/path><\/svg><span class=\"wp-block-social-link-label screen-reader-text\">E-mail<\/span><\/a><\/li><\/ul>\n\n\n\n<p class=\"wp-container-content-9cfa9a5a wp-block-paragraph\" style=\"font-size:14px\">fabriciadefarias@ufrrj.br<\/p>\n<\/div>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\" style=\"font-size:13px\"> <strong>ORCID:&nbsp;<a href=\"https:\/\/orcid.org\/0000-0003-3288-9273\" target=\"_blank\" rel=\"noreferrer noopener\">0000-0003-3288-9273<\/a><\/strong><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column has-midnight-gradient-background has-background is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:3px\"><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-12-1024x1024.jpg\" alt=\"\" class=\"wp-image-10612\" style=\"aspect-ratio:4\/3;object-fit:contain\" srcset=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-12-1024x1024.jpg 1024w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-12-300x300.jpg 300w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-12-150x150.jpg 150w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-12-768x768.jpg 768w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-12-200x200.jpg 200w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-12-70x70.jpg 70w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-12.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" style=\"font-size:20px\">Leonardo Darbilly<\/h2>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\" style=\"text-decoration:underline\"><strong>Colaborador<\/strong><\/p>\n\n\n\n<div class=\"wp-block-group is-content-justification-center is-nowrap is-layout-flex wp-container-core-group-is-layout-d05cb3ef wp-block-group-is-layout-flex\">\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\" style=\"font-size:16px\"><summary>Resumo<\/summary>\n<p class=\"wp-block-paragraph\" style=\"font-size:16px\">Doutor em Administra\u00e7\u00e3o e Mestre em Administra\u00e7\u00e3o P\u00fablica pela Escola Brasileira de Administra\u00e7\u00e3o P\u00fablica e de Empresas da Funda\u00e7\u00e3o Getulio Vargas (EBAPE\/FGV). Bacharel em Administra\u00e7\u00e3o pela Universidade C\u00e2ndido Mendes. Participante do Grupo de Estudos em Administra\u00e7\u00e3o Contempor\u00e2nea (GEAC). Professor adjunto do Departamento de Administra\u00e7\u00e3o e Turismo do Instituto Multidisciplinar da Universidade Federal Rural do Rio de Janeiro (UFRRJ). Tem experi\u00eancia em doc\u00eancia e pesquisa na \u00e1rea de Administra\u00e7\u00e3o, com \u00eanfase nas \u00e1reas de estudos organizacionais e administra\u00e7\u00e3o p\u00fablica.&nbsp;<a href=\"http:\/\/lattes.cnpq.br\/5006336527714854\" target=\"_blank\" rel=\"noreferrer noopener\">Lattes<\/a><\/p>\n<\/details>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:16px\"><a href=\"http:\/\/lattes.cnpq.br\/5006336527714854\" target=\"_blank\" rel=\"noreferrer noopener\">Lattes<\/a><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-group is-content-justification-center is-nowrap is-layout-flex wp-container-core-group-is-layout-d05cb3ef wp-block-group-is-layout-flex\">\n<ul class=\"wp-block-social-links is-layout-flex wp-block-social-links-is-layout-flex\"><li class=\"wp-social-link wp-social-link-mail wp-block-social-link\"><a href=\"mailto:&#108;&#101;o&#110;&#097;r&#100;&#111;.da&#114;b&#105;ll&#121;1&#064;&#103;&#109;&#097;&#105;&#108;.&#099;o&#109;\" class=\"wp-block-social-link-anchor\"><svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M19,5H5c-1.1,0-2,.9-2,2v10c0,1.1.9,2,2,2h14c1.1,0,2-.9,2-2V7c0-1.1-.9-2-2-2zm.5,12c0,.3-.2.5-.5.5H5c-.3,0-.5-.2-.5-.5V9.8l7.5,5.6,7.5-5.6V17zm0-9.1L12,13.6,4.5,7.9V7c0-.3.2-.5.5-.5h14c.3,0,.5.2.5.5v.9z\"><\/path><\/svg><span class=\"wp-block-social-link-label screen-reader-text\">E-mail<\/span><\/a><\/li><\/ul>\n\n\n\n<p class=\"wp-container-content-9cfa9a5a wp-block-paragraph\" style=\"font-size:11px\">leonardo.darbilly1@gmail.com<\/p>\n<\/div>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\" style=\"font-size:13px\"><strong>ORCID:&nbsp;<a href=\"https:\/\/orcid.org\/0000-0002-9520-1547\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><a href=\"https:\/\/orcid.org\/0000-0002-9063-8395\">0000-0002-9063-<\/a><a href=\"https:\/\/orcid.org\/0000-0002-9063-8395\" target=\"_blank\" rel=\"noreferrer noopener\">8395<\/a><\/strong><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column has-midnight-gradient-background has-background is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:3px\"><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-13-1024x1024.jpg\" alt=\"\" class=\"wp-image-10613\" style=\"aspect-ratio:4\/3;object-fit:contain\" srcset=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-13-1024x1024.jpg 1024w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-13-300x300.jpg 300w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-13-150x150.jpg 150w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-13-768x768.jpg 768w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-13-200x200.jpg 200w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-13-70x70.jpg 70w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-13.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" style=\"font-size:20px\">Marcia Cova<\/h2>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\" style=\"text-decoration:underline\"><strong>Permanente<\/strong><\/p>\n\n\n\n<div class=\"wp-block-group is-content-justification-center is-nowrap is-layout-flex wp-container-core-group-is-layout-d05cb3ef wp-block-group-is-layout-flex\">\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\" style=\"font-size:16px\"><summary>Resumo<\/summary>\n<p class=\"wp-block-paragraph\" style=\"font-size:16px\">Doutora em Ci\u00eancias Sociais (CPDA \u2013 UFRRJ), Mestre em Administra\u00e7\u00e3o Rural (DAE \u2013 UFLA), Bacharel em Administra\u00e7\u00e3o Empresa\/P\u00fablica (ICHS \u2013 UFRRJ). Avaliadora de Cursos de Gradua\u00e7\u00e3o de Administra\u00e7\u00e3o EAD (INEP\/MEC). Professora Associada no DAT\/IM\/UFRRJ com as seguintes atividades: 1. Professora de Lideran\u00e7a Estrat\u00e9gica (Mestrado Profissional em Gest\u00e3o e Estrat\u00e9gia \u2013 UFRRJ). 2. Professora de Gest\u00e3o de Pessoas 1 e 2 (Curso de Administra\u00e7\u00e3o \u2013 IM \u2013 UFRRJ). 3. Coordenadora das disciplinas Gest\u00e3o de Pessoas 1 e de Gest\u00e3o de Pessoas 2 (CEDERJ\/CECIERJ\/UAB\/UFRRJ). 4. Lider do Grupo de Pesquisa em Administra\u00e7\u00e3o e Desenvolvimento (GPAD \u2013 UFRRJ). Desenvolve suas atividades na \u00e1rea de Administra\u00e7\u00e3o, atuando principalmente na linha Estrat\u00e9gias Inovadoras para Organiza\u00e7\u00f5es P\u00fablicas e Privadas, no eixo tem\u00e1tico de lideran\u00e7a estrat\u00e9gica.&nbsp;<a href=\"http:\/\/buscatextual.cnpq.br\/buscatextual\/visualizacv.do?id=K4728525D2\" target=\"_blank\" rel=\"noreferrer noopener\">Lattes<\/a><\/p>\n<\/details>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:16px\"><a href=\"http:\/\/buscatextual.cnpq.br\/buscatextual\/visualizacv.do?id=K4728525D2\" target=\"_blank\" rel=\"noreferrer noopener\">Lattes<\/a><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-group is-content-justification-center is-nowrap is-layout-flex wp-container-core-group-is-layout-d05cb3ef wp-block-group-is-layout-flex\">\n<ul class=\"wp-block-social-links is-layout-flex wp-block-social-links-is-layout-flex\"><li class=\"wp-social-link wp-social-link-mail wp-block-social-link\"><a href=\"mailto:m&#097;&#114;cia&#099;o&#118;&#097;&#064;g&#109;ail&#046;&#099;om\" class=\"wp-block-social-link-anchor\"><svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M19,5H5c-1.1,0-2,.9-2,2v10c0,1.1.9,2,2,2h14c1.1,0,2-.9,2-2V7c0-1.1-.9-2-2-2zm.5,12c0,.3-.2.5-.5.5H5c-.3,0-.5-.2-.5-.5V9.8l7.5,5.6,7.5-5.6V17zm0-9.1L12,13.6,4.5,7.9V7c0-.3.2-.5.5-.5h14c.3,0,.5.2.5.5v.9z\"><\/path><\/svg><span class=\"wp-block-social-link-label screen-reader-text\">E-mail<\/span><\/a><\/li><\/ul>\n\n\n\n<p class=\"wp-container-content-9cfa9a5a wp-block-paragraph\" style=\"font-size:14px\">marciacova@gmail.com<\/p>\n<\/div>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\" style=\"font-size:13px\"> <strong>ORCID:&nbsp;<a href=\"https:\/\/orcid.org\/0000-0001-7477-5421\" target=\"_blank\" rel=\"noreferrer noopener\">0000-0001-7477-5421<\/a><\/strong><\/p>\n<\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-14-1024x1024.jpg\" alt=\"\" class=\"wp-image-10614\" style=\"aspect-ratio:4\/3;object-fit:contain\" srcset=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-14-1024x1024.jpg 1024w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-14-300x300.jpg 300w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-14-150x150.jpg 150w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-14-768x768.jpg 768w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-14-200x200.jpg 200w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-14-70x70.jpg 70w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-14.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" style=\"font-size:20px\">M\u00e1rcio Marietto<\/h2>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\" style=\"text-decoration:underline\"><strong>Permanente<\/strong><\/p>\n\n\n\n<div class=\"wp-block-group is-content-justification-center is-nowrap is-layout-flex wp-container-core-group-is-layout-d05cb3ef wp-block-group-is-layout-flex\">\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\" style=\"font-size:16px\"><summary>Resumo<\/summary>\n<p class=\"wp-block-paragraph\" style=\"font-size:16px\">Avaliador do Sistema Nacional de Avalia\u00e7\u00e3o da Educa\u00e7\u00e3o Superior (SINAES \u2013 BASis) de Cursos de Gradua\u00e7\u00e3o (INEP) em Administra\u00e7\u00e3o de Empresas e \u00e1reas correlatas. Professor e Pesquisador no Stricto Sensu (Mestrado e Doutorado) em Administra\u00e7\u00e3o de Empresas e Desenvolvimento Regional. L\u00edder do Grupo de Pesquisa no CNPQ: \u201cInstitui\u00e7\u00f5es, Organiza\u00e7\u00f5es e Inova\u00e7\u00e3o na Base da Pir\u00e2mide\u201d. Possui os Pr\u00eamios: Egresso de Destaque do Curso de Mestrado em Administra\u00e7\u00e3o de Empresas da UNIFACCAMP (2021); Melhor Avaliador da \u00c1rea de Estrat\u00e9gia e Pol\u00edticas de Neg\u00f3cios do Academy of Management (2010); Melhor artigo do EnANPAD (2009); e melhor artigo da divis\u00e3o de Administra\u00e7\u00e3o P\u00fablica e Gest\u00e3o Social (2009). Docente em cursos de MBA, especializa\u00e7\u00e3o e gradua\u00e7\u00e3o nas \u00e1reas de Administra\u00e7\u00e3o de Empresas, Com\u00e9rcio Exterior, Neg\u00f3cios Internacionais, Gest\u00e3o da Sa\u00fade, Gest\u00e3o em Log\u00edstica Empresarial, Gest\u00e3o em Seguros e Resseguros, entre outros. Avaliador em Peri\u00f3dicos Cient\u00edficos<br>Internacionais e Nacionais. Experi\u00eancia em Gest\u00e3o Acad\u00eamica: Coordenador do curso de p\u00f3s-gradua\u00e7\u00e3o em Gest\u00e3o de Neg\u00f3cios Internacionais (2012-2015). Experi\u00eancia profissional: Consultor Ad hoc em gest\u00e3o estrat\u00e9gica (2004-2012); Perito Judicial (2009-2018); Piloto de Linha A\u00e9rea de Avi\u00e3o e Gerente Operacional de empresas de t\u00e1xi a\u00e9reo e aeronaves particulares (1994-2002)<em>.<\/em><a href=\"https:\/\/lattes.cnpq.br\/5808655315359719\">&nbsp;<\/a><a href=\"https:\/\/lattes.cnpq.br\/5808655315359719\" target=\"_blank\" rel=\"noreferrer noopener\">Lattes<\/a><\/p>\n<\/details>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:16px\"><a href=\"https:\/\/lattes.cnpq.br\/5808655315359719\" target=\"_blank\" rel=\"noreferrer noopener\">Lattes<\/a><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-group is-content-justification-center is-nowrap is-layout-flex wp-container-core-group-is-layout-d05cb3ef wp-block-group-is-layout-flex\">\n<ul class=\"wp-block-social-links is-layout-flex wp-block-social-links-is-layout-flex\"><li class=\"wp-social-link wp-social-link-mail wp-block-social-link\"><a href=\"mailto:m&#097;&#114;c&#105;o&#108;ui&#122;&#109;&#097;&#114;i&#101;&#116;to&#064;&#117;&#102;rrj&#046;br\" class=\"wp-block-social-link-anchor\"><svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M19,5H5c-1.1,0-2,.9-2,2v10c0,1.1.9,2,2,2h14c1.1,0,2-.9,2-2V7c0-1.1-.9-2-2-2zm.5,12c0,.3-.2.5-.5.5H5c-.3,0-.5-.2-.5-.5V9.8l7.5,5.6,7.5-5.6V17zm0-9.1L12,13.6,4.5,7.9V7c0-.3.2-.5.5-.5h14c.3,0,.5.2.5.5v.9z\"><\/path><\/svg><span class=\"wp-block-social-link-label screen-reader-text\">E-mail<\/span><\/a><\/li><\/ul>\n\n\n\n<p class=\"wp-container-content-9cfa9a5a wp-block-paragraph\" style=\"font-size:12px\">marcioluizmarietto@ufrrj.br<\/p>\n<\/div>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\" style=\"font-size:13px\"><strong>ORCID:&nbsp;<\/strong><a href=\"https:\/\/orcid.org\/0000-0003-1526-6058\"><strong>0000-<\/strong><\/a><strong><a href=\"https:\/\/orcid.org\/0000-0003-1526-6058\" target=\"_blank\" rel=\"noreferrer noopener\">0003<\/a><\/strong><a href=\"https:\/\/orcid.org\/0000-0003-1526-6058\"><strong>-1526-6058<\/strong><\/a><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column has-midnight-gradient-background has-background is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:3px\"><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-15-1024x1024.jpg\" alt=\"\" class=\"wp-image-10615\" style=\"aspect-ratio:4\/3;object-fit:contain\" srcset=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-15-1024x1024.jpg 1024w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-15-300x300.jpg 300w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-15-150x150.jpg 150w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-15-768x768.jpg 768w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-15-200x200.jpg 200w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-15-70x70.jpg 70w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-15.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" style=\"font-size:20px\">Maria Cristina<\/h2>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\" style=\"text-decoration:underline\"><strong>Permanente<\/strong><\/p>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-group is-content-justification-center is-nowrap is-layout-flex wp-container-core-group-is-layout-d05cb3ef wp-block-group-is-layout-flex\">\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\" style=\"font-size:16px\"><summary>Resumo<\/summary>\n<p class=\"wp-block-paragraph\" style=\"font-size:16px\">Professora do Quadro Permanente do Mestrado em Gest\u00e3o &amp; Estrat\u00e9gia da UFRRJ, \u00e1rea de atua\u00e7\u00e3o: Gest\u00e3o Estrat\u00e9gica de Pessoas &amp; Organiza\u00e7\u00f5es. Projeto: Estrat\u00e9gias de Gest\u00e3o de Pessoas, Lideran\u00e7a Organizacional e Rela\u00e7\u00f5es de Trabalho (quadri\u00eanio: 2021\/2024) Docente das disciplinas: Turma 2020\/2021: An\u00e1lise Qualitativa em Estudos Organizacionais, Estrat\u00e9gia Empresarial Avan\u00e7ada e Produ\u00e7\u00e3o e publica\u00e7\u00e3o de artigos cient\u00edficos. Orientadora e co-orientadora do Programa. (2019) \u2013 T\u00f3picos em Administra\u00e7\u00e3o I (Gest\u00e3o do desempenho e clima organizacional) e das oficinas de produ\u00e7\u00e3o de artigos cient\u00edficos e produ\u00e7\u00e3o cient\u00edfica\/Lattes). (2018) \u2013 Estrat\u00e9gia Empresarial Organizacional e An\u00e1lise Qualitativa em Estudos Organizacionais. Professora colaboradora Programa de P\u00f3s-gradua\u00e7\u00e3o Profissional em Gest\u00e3o e Avalia\u00e7\u00e3o da Educa\u00e7\u00e3o P\u00fablica da Universidade Federal de Juiz de Fora (CAED\/UFJF) Docente da disciplina An\u00e1lise Qualitativa em Estudos Organizacionais (2 turmas em 2019). Orientadora do programa. Professora Adjunta do Curso de Administra\u00e7\u00e3o no Campus da UFRRJ em Tr\u00eas Rios, N\u00facleo de Fundamentos de Gest\u00e3o e Gest\u00e3o de Pessoas. L\u00edder do Grupo de Pesquisa Gest\u00e3o Estrat\u00e9gica de Pessoas &amp; Organiza\u00e7\u00f5es, Diret\u00f3rio CNPq. Link: https:\/\/itr.ufrrj.br\/portal\/grupo-de-pesquisa-gestao-estrategica-de-pessoas-organizacoes\/ Pesquisadora e membro do Grupo de Pesquisa\/CNPq: Grupo de Estudos e Pesquisas em Pessoas e Organiza\u00e7\u00f5es (UFJF) e Estrat\u00e9gias de Inova\u00e7\u00e3o na Organiza\u00e7\u00e3o do Trabalho (UFRRJ) Doutora em Ci\u00eancia, Tecnologia e Inova\u00e7\u00e3o Agropecu\u00e1ria (PPGCTIA) UFRRJ \u2013 Doutorado Binacional em parceria com a Universidad Nacional de Rio Cuarto (UNRC) na Argentina. Mestre em Sistemas de Gest\u00e3o (Escola de Engenharia de Produ\u00e7\u00e3o, UFF). Especialista em Organiza\u00e7\u00e3o e Estrat\u00e9gia (UFF), Administra\u00e7\u00e3o Rural (UFLA), e Sistemas de informa\u00e7\u00f5es Gerenciais (FMS\/UFRJ). Bacharel em Ci\u00eancias Econ\u00f4micas (UFJF) e em Direito (Instituto Vianna J\u00fanior) Atua como coordenadora de projetos de pesquisa e extens\u00e3o acad\u00eamica. Tem experi\u00eancia comprovada em Ensino, Pesquisa, e Extens\u00e3o em universidades p\u00fablicas e privadas e em empresas p\u00fablicas e privadas, bem como em consultoria, com destaque para coordena\u00e7\u00e3o de Programa de P\u00f3s-gradua\u00e7\u00e3o lato sensu, Pesquisa e Extens\u00e3o; na gest\u00e3o de P\u00f3lo de EaD e como Tutora de disciplinas teletransmitidas. Em doc\u00eancia de n\u00edvel superior nos cursos de Administra\u00e7\u00e3o, Direito, Economia, Engenharia de produ\u00e7\u00e3o, Publicidade e Propaganda, Turismo e outros; em Cursos de Ensino Superior Tecnol\u00f3gico em Marketing, Com\u00e9rcio Exterior, Log\u00edstica, Processos Gerenciais e Recursos Humanos. Em p\u00f3s-gradua\u00e7\u00e3o lato sensu nos cursos Com\u00e9rcio Exterior, Log\u00edstica, Recursos Humanos, Gest\u00e3o ambiental , Gest\u00e3o Estrat\u00e9gica de Custos e MBA de Gest\u00e3o Estrat\u00e9gica de Pessoas (UFJF).<a href=\"http:\/\/lattes.cnpq.br\/8402406521255088\">&nbsp;<\/a><a href=\"http:\/\/lattes.cnpq.br\/8402406521255088\" target=\"_blank\" rel=\"noreferrer noopener\">Lattes<\/a><\/p>\n<\/details>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:16px\"><a href=\"http:\/\/lattes.cnpq.br\/8402406521255088\" target=\"_blank\" rel=\"noreferrer noopener\">Lattes<\/a><\/p>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-group is-content-justification-center is-nowrap is-layout-flex wp-container-core-group-is-layout-d05cb3ef wp-block-group-is-layout-flex\">\n<ul class=\"wp-block-social-links is-layout-flex wp-block-social-links-is-layout-flex\"><li class=\"wp-social-link wp-social-link-mail wp-block-social-link\"><a href=\"mailto:&#099;&#114;&#105;&#115;&#116;&#105;n&#097;.u&#102;r&#114;&#106;&#046;it&#114;&#064;&#103;&#109;a&#105;l&#046;co&#109;\" class=\"wp-block-social-link-anchor\"><svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M19,5H5c-1.1,0-2,.9-2,2v10c0,1.1.9,2,2,2h14c1.1,0,2-.9,2-2V7c0-1.1-.9-2-2-2zm.5,12c0,.3-.2.5-.5.5H5c-.3,0-.5-.2-.5-.5V9.8l7.5,5.6,7.5-5.6V17zm0-9.1L12,13.6,4.5,7.9V7c0-.3.2-.5.5-.5h14c.3,0,.5.2.5.5v.9z\"><\/path><\/svg><span class=\"wp-block-social-link-label screen-reader-text\">E-mail<\/span><\/a><\/li><\/ul>\n\n\n\n<p class=\"wp-container-content-9cfa9a5a wp-block-paragraph\" style=\"font-size:12px\">cristina.ufrrj.itr@gmail.com<\/p>\n<\/div>\n<\/div><\/div>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\" style=\"font-size:13px\"><strong>ORCID:&nbsp;<a href=\"https:\/\/orcid.org\/0000-0001-7562-7367\" target=\"_blank\" rel=\"noreferrer noopener\">0000-0001-7562-7367<\/a><\/strong><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column has-midnight-gradient-background has-background is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:3px\"><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-16-1024x1024.jpg\" alt=\"\" class=\"wp-image-10616\" style=\"aspect-ratio:4\/3;object-fit:contain\" srcset=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-16-1024x1024.jpg 1024w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-16-300x300.jpg 300w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-16-150x150.jpg 150w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-16-768x768.jpg 768w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-16-200x200.jpg 200w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-16-70x70.jpg 70w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-16.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" style=\"font-size:20px\">Paulo Domingues<\/h2>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\" style=\"text-decoration:underline\"><strong>Permanente<\/strong><\/p>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-group is-content-justification-center is-nowrap is-layout-flex wp-container-core-group-is-layout-d05cb3ef wp-block-group-is-layout-flex\">\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\" style=\"font-size:16px\"><summary>Resumo<\/summary>\n<p class=\"wp-block-paragraph\" style=\"font-size:16px\">Possui gradua\u00e7\u00e3o em Ci\u00eancias Sociais pela USP, em Administra\u00e7\u00e3o pela Universidade Cat\u00f3lica de Santos e gradua\u00e7\u00e3o em Tecnologia de Processamento de Dados pela Faculdade de Tecnologia (FATEC-SP), mestrado em Administra\u00e7\u00e3o pela Pontif\u00edcia Universidade Cat\u00f3lica de S\u00e3o Paulo \u2013 PUC-SP (1998) e Doutorado em Sociologia pela USP (2006). Atualmente, \u00e9 Professor Associado na UFRRJ (Universidade Federal Rural do Rio de Janeiro), no campus de Tr\u00eas Rios (RJ). Leciona no curso de Bacharelado em Administra\u00e7\u00e3o do Instituto Tr\u00eas Rios., \u00e9 l\u00edder do grupo de pesquisa denominado Organiza\u00e7\u00f5es e Pessoas: Trabalho, Gest\u00e3o e Sustentabilidade (ITR \u2013 UFRRJ). Possui experi\u00eancia na \u00e1rea de seguran\u00e7a do trabalho, gest\u00e3o de pessoas, cooperativismo e associativismo, qualidade de vida e stress no trabalho. Foi professor permanente do Mestrado Acad\u00eamico em Administra\u00e7\u00e3o da UFRRJ,sendo respons\u00e1vel pela disciplina relacionada ao estudo da qualidade de vida no trabalho (QVT) e do stress ocupacional no Mestrado. Atualmente \u00e9 professor do Mestrado Profissional em Gest\u00e3o e Estrat\u00e9gia (MPGE) da UFRRJ. Tem dedicado atualmente especial aten\u00e7\u00e3o aos temas da Qualidade de Vida no Trabalho (QVT), causas e consequ\u00eancias do stress ocupacional (adoecimento, burnout, entre outros), bem como pol\u00edticas organizacionais voltadas para a qualidade de vida e o stress no trabalho. \u00c9 autor de 7 livros (um no prelo) e de diversos artigos cient\u00edficos em peri\u00f3dicos nacionais e internacionais. Al\u00e9m do Brasil, publicou artigos ou cap\u00edtulos na Espanha, Argentina, Estados Unidos e Europa. Tamb\u00e9m t\u00eam participado de importantes congressos nacionais e internacionais. A n\u00edvel internacional participou do I Congreso Argentino y Latinoamericano de Derechos Humanos em 2007 na cidade de Ros\u00e1rio \u2013 Argentina; do SOCIAL WORK SOCIAL DEVELOPMENT 2012: ACTION AND IMPACT, 2012, na cidade de Estocolmo \u2013 Su\u00e9cia; do 7 Annual Internacional Conference on Sociology, na cidade de Atenas \u2013 Gr\u00e9cia em 2013; do congresso From Decoupling to Entanglement. Workshop on the Formal and the Informal in Law, Institutions and Economy, 2013, realizado no prestigioso col\u00e9gio de sociologia de Vars\u00f3via, na Pol\u00f4nia; do ALAS (Associaci\u00f3n LatinoAmericana de Sociolog\u00eda), 2015, na cidade de San Jos\u00e9, Costa Rica; do XIII Congreso Estatal y I Iberoamericano de Trabajo Social, 2017 realizado em M\u00e9rida.na Espanha; do 13 Conference of The European Academy of Occupational Health Psychology, 2018, realizado em Lisboa, Portugal; do International Society for the Study of Work and Organizational Values, 2018, ISSWOV 2018, realizado em Trieste, na It\u00e1lia. Apresentou trabalho no Work, Stress and Health Conference, realizado na Filad\u00e9lfia (Pensilv\u00e2nia, Estados Unidos) em 2019. Fez a palestra de abertura do I Semin\u00e1rio Internacional ?Sa\u00fade e Trabalho na Contemporaneidade: Di\u00e1logos entre Portugal e Brasil, da Universidade Lus\u00f3fona do Porto (Portugal) em conv\u00eanio com a UFJF (Universidade Federal de Juiz de Fora). Apresentou trabalho no Work, Stress and Health Conference (Estados Unidos) em 2021. Apresentou trabalho no Boston Conference (2017), realizado na universidade de HARVARD (Estados Unidos) e participou de cursos\/congressos na \u00e1rea do stress da Universidade de HARVARD (Estados Unidos) em 2019, 2020 e 2021.&nbsp;<a href=\"http:\/\/lattes.cnpq.br\/4753607667153587\" target=\"_blank\" rel=\"noreferrer noopener\">Lattes<\/a><\/p>\n<\/details>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:16px\"><a href=\"http:\/\/lattes.cnpq.br\/4753607667153587\" target=\"_blank\" rel=\"noreferrer noopener\">Lattes<\/a><\/p>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-group is-content-justification-center is-nowrap is-layout-flex wp-container-core-group-is-layout-d05cb3ef wp-block-group-is-layout-flex\">\n<ul class=\"wp-block-social-links is-layout-flex wp-block-social-links-is-layout-flex\"><li class=\"wp-social-link wp-social-link-mail wp-block-social-link\"><a href=\"https:\/\/pldominguesjr@uol.com.br%20\" class=\"wp-block-social-link-anchor\"><svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M19,5H5c-1.1,0-2,.9-2,2v10c0,1.1.9,2,2,2h14c1.1,0,2-.9,2-2V7c0-1.1-.9-2-2-2zm.5,12c0,.3-.2.5-.5.5H5c-.3,0-.5-.2-.5-.5V9.8l7.5,5.6,7.5-5.6V17zm0-9.1L12,13.6,4.5,7.9V7c0-.3.2-.5.5-.5h14c.3,0,.5.2.5.5v.9z\"><\/path><\/svg><span class=\"wp-block-social-link-label screen-reader-text\">E-mail<\/span><\/a><\/li><\/ul>\n\n\n\n<p class=\"wp-container-content-9cfa9a5a wp-block-paragraph\" style=\"font-size:12px\">pldominguesjr@uol.com.br <\/p>\n<\/div>\n<\/div><\/div>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\" style=\"font-size:13px\"> <strong>ORCID:&nbsp;<a href=\"https:\/\/orcid.org\/0000-0002-4958-4989\" target=\"_blank\" rel=\"noreferrer noopener\">0000-0002-4958-4989<\/a><\/strong><\/p>\n<\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center has-white-color has-midnight-gradient-background has-text-color has-background has-link-color has-medium-font-size wp-elements-60b03222dcbd8e5483090d5fa8aed1d6\">Docentes da Linha 2<\/h2>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"423\" height=\"362\" src=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/10\/image.png\" alt=\"\" class=\"wp-image-10873\" style=\"aspect-ratio:4\/3;object-fit:contain\" srcset=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/10\/image.png 423w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/10\/image-300x257.png 300w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/10\/image-82x70.png 82w\" sizes=\"(max-width: 423px) 100vw, 423px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" style=\"font-size:20px\">Alessandra Cassol<\/h2>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\" style=\"text-decoration:underline\"><strong>Permanente<\/strong><\/p>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-group is-content-justification-center is-nowrap is-layout-flex wp-container-core-group-is-layout-d05cb3ef wp-block-group-is-layout-flex\">\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\" style=\"font-size:16px\"><summary>Resumo<\/summary>\n<p class=\"wp-block-paragraph\" style=\"font-size:16px\">Doutora em Administra\u00e7\u00e3o \u2013 \u00c1rea de concentra\u00e7\u00e3o: Estrat\u00e9gia em Organiza\u00e7\u00f5es (Universidade Nove de Julho \u2013 UNINOVE, 2018) com reconhecimento na Universidade de Lisboa, Portugal (registro n.\u00ba 120210128573). Mestre em Administra\u00e7\u00e3o \u2013 \u00c1rea de concentra\u00e7\u00e3o: Organiza\u00e7\u00f5es e Sociedade (Universidade do Vale do Itaja\u00ed \u2013 UNIVALI, 2014). Especialista em Gest\u00e3o Empresarial (Universidade do Contestado \u2013 UnC, 2011). Bacharel em Administra\u00e7\u00e3o: Habilita\u00e7\u00e3o em Com\u00e9rcio Exterior (Universidade do Oeste de Santa Catarina \u2013 UNOESC, 2009). Forma\u00e7\u00e3o no curso de Innovation &amp; Entrepreneurship no Institut d Administration des Entreprises em Grenoble, Fran\u00e7a (2014). Atuo como Professora Adjunta na Universidade Federal Rural do Rio De Janeiro (UFRRJ) e como professora colaboradora no Programa de Mestrado Acad\u00eamico em Administra\u00e7\u00e3o (IMED\/Atitus Educa\u00e7\u00e3o). Experi\u00eancia como professora em cursos Stricto Sensu: Mestrado Profissional em Administra\u00e7\u00e3o (UNC, 2018-2021) e Mestrado Associado em Sistemas Produtivos (UNC; UNIPLAC; UNIVILLE; UNESC, 2020-2021). Experi\u00eancia como professora em cursos de gradua\u00e7\u00e3o em Administra\u00e7\u00e3o na Universidade Federal da Fronteira Sul (UFFS, 2019-2021) e na Universidade do Contestado (UNC, 2011-2019). Experi\u00eancia em Gest\u00e3o Acad\u00eamica: Coordenadora do Programa de Mestrado Profissional em Administra\u00e7\u00e3o (UNC, 2018-2021), Coordenadora do Curso de Gradua\u00e7\u00e3o em Administra\u00e7\u00e3o e Gestora do N\u00facleo de Inova\u00e7\u00e3o Tecnol\u00f3gica (UNC, 2014-2017) e Coordenadora Administrativa da Incubadora de Neg\u00f3cios (UFFS, 2019-2021). Experi\u00eancia profissional como Gerente de Inova\u00e7\u00e3o na Cooperativa de Transporte do Estado de Santa Catarina (2018-2020). Professora em cursos de p\u00f3s-gradua\u00e7\u00e3o Latu Sensu em disciplinas de Inova\u00e7\u00e3o, Modelos de Neg\u00f3cio, Estrat\u00e9gia, Empreendedorismo, Jogos Empresariais. Avaliadora em Peri\u00f3dicos Cient\u00edficos Internacionais e Nacionais. Consultora ad hoc da FAPESC. Pesquisadora nas tem\u00e1ticas: Capacidade Din\u00e2micas e Absortivas, Aprendizagem Organizacional, Inova\u00e7\u00e3o, Redes de Inova\u00e7\u00e3o Colaborativas, Ecossistemas Regionais de Inova\u00e7\u00e3o, Empreendedorismo.&nbsp;<a href=\"http:\/\/lattes.cnpq.br\/9005547281638334\" target=\"_blank\" rel=\"noreferrer noopener\">Lattes<\/a><\/p>\n<\/details>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:16px\"><a href=\"http:\/\/lattes.cnpq.br\/9005547281638334\" target=\"_blank\" rel=\"noreferrer noopener\">Lattes<\/a><\/p>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-group is-content-justification-center is-nowrap is-layout-flex wp-container-core-group-is-layout-d05cb3ef wp-block-group-is-layout-flex\">\n<ul class=\"wp-block-social-links is-layout-flex wp-block-social-links-is-layout-flex\"><li class=\"wp-social-link wp-social-link-mail wp-block-social-link\"><a href=\"https:\/\/alessandracassol@ufrrj.br%20\" class=\"wp-block-social-link-anchor\"><svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M19,5H5c-1.1,0-2,.9-2,2v10c0,1.1.9,2,2,2h14c1.1,0,2-.9,2-2V7c0-1.1-.9-2-2-2zm.5,12c0,.3-.2.5-.5.5H5c-.3,0-.5-.2-.5-.5V9.8l7.5,5.6,7.5-5.6V17zm0-9.1L12,13.6,4.5,7.9V7c0-.3.2-.5.5-.5h14c.3,0,.5.2.5.5v.9z\"><\/path><\/svg><span class=\"wp-block-social-link-label screen-reader-text\">E-mail<\/span><\/a><\/li><\/ul>\n\n\n\n<p class=\"wp-container-content-9cfa9a5a wp-block-paragraph\" style=\"font-size:12px\">alessandracassol@ufrrj.br <\/p>\n<\/div>\n<\/div><\/div>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\" style=\"font-size:13px\"><strong>ORCID<\/strong><a href=\"ORCID:&nbsp;0000-0003-0753-9642\"><strong>:&nbsp;<\/strong><\/a><strong><a href=\"https:\/\/www.google.com\/url?sa=t&amp;rct=j&amp;q=&amp;esrc=s&amp;source=web&amp;cd=&amp;cad=rja&amp;uact=8&amp;ved=2ahUKEwj01pnbityPAxVzFbkGHe8GMUgQFnoECCUQAQ&amp;url=https%3A%2F%2Forcid.org%2F0000-0003-0753-9642&amp;usg=AOvVaw12k0HRlmJQ8tmxuKcg8H8C&amp;opi=89978449\">0000-<\/a><a href=\"https:\/\/www.google.com\/url?sa=t&amp;rct=j&amp;q=&amp;esrc=s&amp;source=web&amp;cd=&amp;cad=rja&amp;uact=8&amp;ved=2ahUKEwj01pnbityPAxVzFbkGHe8GMUgQFnoECCUQAQ&amp;url=https%3A%2F%2Forcid.org%2F0000-0003-0753-9642&amp;usg=AOvVaw12k0HRlmJQ8tmxuKcg8H8C&amp;opi=89978449\" target=\"_blank\" rel=\"noreferrer noopener\">0003<\/a><a href=\"https:\/\/www.google.com\/url?sa=t&amp;rct=j&amp;q=&amp;esrc=s&amp;source=web&amp;cd=&amp;cad=rja&amp;uact=8&amp;ved=2ahUKEwj01pnbityPAxVzFbkGHe8GMUgQFnoECCUQAQ&amp;url=https%3A%2F%2Forcid.org%2F0000-0003-0753-9642&amp;usg=AOvVaw12k0HRlmJQ8tmxuKcg8H8C&amp;opi=89978449\">-0753-<\/a><a href=\"https:\/\/www.google.com\/url?sa=t&amp;rct=j&amp;q=&amp;esrc=s&amp;source=web&amp;cd=&amp;cad=rja&amp;uact=8&amp;ved=2ahUKEwj01pnbityPAxVzFbkGHe8GMUgQFnoECCUQAQ&amp;url=https%3A%2F%2Forcid.org%2F0000-0003-0753-9642&amp;usg=AOvVaw12k0HRlmJQ8tmxuKcg8H8C&amp;opi=89978449\" target=\"_blank\" rel=\"noreferrer noopener\">9642<\/a><\/strong><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column has-midnight-gradient-background has-background is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:3px\"><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-medium\"><img decoding=\"async\" width=\"300\" height=\"250\" src=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/10\/image-1-300x250.png\" alt=\"\" class=\"wp-image-10874\" style=\"aspect-ratio:4\/3;object-fit:contain\" srcset=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/10\/image-1-300x250.png 300w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/10\/image-1-84x70.png 84w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/10\/image-1.png 307w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" style=\"font-size:20px\">Carlos Lidizia<\/h2>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\" style=\"text-decoration:underline\"><strong>Permanente<\/strong><\/p>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-group is-content-justification-center is-nowrap is-layout-flex wp-container-core-group-is-layout-d05cb3ef wp-block-group-is-layout-flex\">\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\" style=\"font-size:16px\"><summary>Resumo<\/summary>\n<p class=\"wp-block-paragraph\" style=\"font-size:16px\">Professor da Faculdade de Turismo e Hotelaria (FTH) da Universidade Federal Fluminense (UFF). P\u00f3s Doutor em Geografia pela Universidade do Estado do Rio de Janeiro. P\u00f3s Doutorando em Turismo Militar pela Universidade de Aveiro. Doutor em Engenharia Civil (UFF). Mestre em Engenharia de Produ\u00e7\u00e3o (UFF). Especialista em Administra\u00e7\u00e3o de Sistemas de Informa\u00e7\u00e3o (UFF). Gradua\u00e7\u00e3o em Administra\u00e7\u00e3o de Empresas. Vice diretor da Faculdade de Turismo e Hotelaria da UFF. Coordenador do Programa de P\u00f3s-Gradua\u00e7\u00e3o em Gest\u00e3o de Servi\u00e7os (MBA\/UFF). Coordenador do N\u00facleo de Projetos da FTH-UFF. L\u00edder do Grupo de Pesquisa CNPq \u201cGest\u00e3o, Acessibilidade e Inclus\u00e3o de Pessoas com Defici\u00eancia no Turismo\u201d (UFF). Pesquisador e L\u00edder do Grupo de Pesquisa Linha Patrim\u00f4nio Hist\u00f3rico e Cultural em Espa\u00e7os e Equipamentos Militares (UFF). Vice L\u00edder do Grupo de Pesquisa HOST \u2013 Rede de Estudos em Hospitalidade (CNPQ) e Coordenador Geral da Linha de Pesquisa e Extens\u00e3o Turismo, Hospitalidade e Inclus\u00e3o (UFF). Pesquisador do Grupo de Investiga\u00e7\u00e3o GOVCOP (Unidade de Investiga\u00e7\u00e3o em Governan\u00e7a, Competitividade e Pol\u00edticas P\u00fablicas) da Universidade de Aveiro. Ponto focal no Brasil da Rede Ibero-Americana de Turismo Rural. Professor Permanente do Programa de Stricto Sensu em Gest\u00e3o e Estrat\u00e9gia PPGE\/ UFRRJ. Atua como professor convidado em diversos Programas de Especializa\u00e7\u00e3o. Seus interesses de pesquisa incluem Gest\u00e3o Estrat\u00e9gica, ESG, Inova\u00e7\u00e3o, Inclus\u00e3o, Acessibilidade, Hospitalidade e Gerenciamento de Projetos e Turismo em espa\u00e7os e equipamentos militares.&nbsp;<a href=\"http:\/\/lattes.cnpq.br\/5555818378491999\" target=\"_blank\" rel=\"noreferrer noopener\">Lattes<\/a><\/p>\n<\/details>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:16px\"><a href=\"http:\/\/lattes.cnpq.br\/5555818378491999\" target=\"_blank\" rel=\"noreferrer noopener\">Lattes<\/a><\/p>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-group is-content-justification-center is-nowrap is-layout-flex wp-container-core-group-is-layout-d05cb3ef wp-block-group-is-layout-flex\">\n<ul class=\"wp-block-social-links is-layout-flex wp-block-social-links-is-layout-flex\"><li class=\"wp-social-link wp-social-link-mail wp-block-social-link\"><a href=\"https:\/\/csoares@id.uff.br%20\" class=\"wp-block-social-link-anchor\"><svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M19,5H5c-1.1,0-2,.9-2,2v10c0,1.1.9,2,2,2h14c1.1,0,2-.9,2-2V7c0-1.1-.9-2-2-2zm.5,12c0,.3-.2.5-.5.5H5c-.3,0-.5-.2-.5-.5V9.8l7.5,5.6,7.5-5.6V17zm0-9.1L12,13.6,4.5,7.9V7c0-.3.2-.5.5-.5h14c.3,0,.5.2.5.5v.9z\"><\/path><\/svg><span class=\"wp-block-social-link-label screen-reader-text\">E-mail<\/span><\/a><\/li><\/ul>\n\n\n\n<p class=\"wp-container-content-9cfa9a5a wp-block-paragraph\" style=\"font-size:14px\">csoares@id.uff.br <\/p>\n<\/div>\n<\/div><\/div>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\" style=\"font-size:13px\"><strong>ORCID:<a href=\"https:\/\/www.google.com\/url?sa=t&amp;rct=j&amp;q=&amp;esrc=s&amp;source=web&amp;cd=&amp;cad=rja&amp;uact=8&amp;ved=2ahUKEwjKha_3ityPAxUMHLkGHTWsO74QFnoECBwQAQ&amp;url=https%3A%2F%2Forcid.org%2F0000-0002-9929-7873&amp;usg=AOvVaw3iaX0YV-fy2z8f1fhabRP8&amp;opi=89978449\">&nbsp;0000-0002-<\/a><a href=\"https:\/\/www.google.com\/url?sa=t&amp;rct=j&amp;q=&amp;esrc=s&amp;source=web&amp;cd=&amp;cad=rja&amp;uact=8&amp;ved=2ahUKEwjKha_3ityPAxUMHLkGHTWsO74QFnoECBwQAQ&amp;url=https%3A%2F%2Forcid.org%2F0000-0002-9929-7873&amp;usg=AOvVaw3iaX0YV-fy2z8f1fhabRP8&amp;opi=89978449\" target=\"_blank\" rel=\"noreferrer noopener\">9929<\/a><a href=\"https:\/\/www.google.com\/url?sa=t&amp;rct=j&amp;q=&amp;esrc=s&amp;source=web&amp;cd=&amp;cad=rja&amp;uact=8&amp;ved=2ahUKEwjKha_3ityPAxUMHLkGHTWsO74QFnoECBwQAQ&amp;url=https%3A%2F%2Forcid.org%2F0000-0002-9929-7873&amp;usg=AOvVaw3iaX0YV-fy2z8f1fhabRP8&amp;opi=89978449\">-7873<\/a><\/strong><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column has-midnight-gradient-background has-background is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:3px\"><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"394\" height=\"261\" src=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/10\/image-2.png\" alt=\"\" class=\"wp-image-10877\" style=\"aspect-ratio:4\/3;object-fit:contain\" srcset=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/10\/image-2.png 394w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/10\/image-2-300x199.png 300w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/10\/image-2-106x70.png 106w\" sizes=\"(max-width: 394px) 100vw, 394px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" style=\"font-size:20px\">Clayton Gon\u00e7alves<\/h2>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\" style=\"text-decoration:underline\"><strong>Permanente<\/strong><\/p>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-group is-content-justification-center is-nowrap is-layout-flex wp-container-core-group-is-layout-d05cb3ef wp-block-group-is-layout-flex\">\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\" style=\"font-size:16px\"><summary>Resumo<\/summary>\n<p class=\"wp-block-paragraph\" style=\"font-size:16px\">Graduado em Administra\u00e7\u00e3o pela Escola Brasileira de Administra\u00e7\u00e3o P\u00fablica e de Empresas (EBAPE\/FGV) e p\u00f3s-graduado em Gest\u00e3o de Varejo pelo COPPEAD\/UFRJ. Mestre e Doutor em Administra\u00e7\u00e3o pela Universidade do Grande Rio (UNIGRANRIO \u2013 PPGA), com mais de 11 anos de experi\u00eancia profissional na \u00e1rea de Administra\u00e7\u00e3o, atuando como empreendedor no setor de Varejo. Atualmente, sou professor adjunto na Universidade Federal Rural do Rio de Janeiro (UFRRJ), onde tamb\u00e9m lidero o Grupo de Pesquisa em Marketing e Servi\u00e7os. Al\u00e9m disso, sou vice-coordenador do Programa de P\u00f3s-Gradua\u00e7\u00e3o em Administra\u00e7\u00e3o e Contabilidade (PPGAC) da Universidade Federal de Rond\u00f4nia (UNIR). Contribuo como revisor de peri\u00f3dicos nas \u00e1reas de Administra\u00e7\u00e3o e Turismo, e tenho conhecimento e interesse em mercados, marketing pol\u00edtico, sociologia cultural, teoria das organiza\u00e7\u00f5es, m\u00e9todos quantitativos, an\u00e1lise de redes sociais, pol\u00edticas p\u00fablicas, viol\u00eancia e autoritarismo. Ao longo da minha carreira, tenho coordenado projetos de pesquisa e participado como membro em projetos fomentados pelo CNPq.&nbsp;<a href=\"http:\/\/lattes.cnpq.br\/4543393919048194\" target=\"_blank\" rel=\"noreferrer noopener\">Lattes<\/a><\/p>\n<\/details>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:16px\"><a href=\"http:\/\/lattes.cnpq.br\/4543393919048194\" target=\"_blank\" rel=\"noreferrer noopener\">Lattes<\/a><\/p>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-group is-content-justification-center is-nowrap is-layout-flex wp-container-core-group-is-layout-d05cb3ef wp-block-group-is-layout-flex\">\n<ul class=\"wp-block-social-links is-layout-flex wp-block-social-links-is-layout-flex\"><li class=\"wp-social-link wp-social-link-mail wp-block-social-link\"><a href=\"https:\/\/crmiax@gmail.com%20\" class=\"wp-block-social-link-anchor\"><svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M19,5H5c-1.1,0-2,.9-2,2v10c0,1.1.9,2,2,2h14c1.1,0,2-.9,2-2V7c0-1.1-.9-2-2-2zm.5,12c0,.3-.2.5-.5.5H5c-.3,0-.5-.2-.5-.5V9.8l7.5,5.6,7.5-5.6V17zm0-9.1L12,13.6,4.5,7.9V7c0-.3.2-.5.5-.5h14c.3,0,.5.2.5.5v.9z\"><\/path><\/svg><span class=\"wp-block-social-link-label screen-reader-text\">E-mail<\/span><\/a><\/li><\/ul>\n\n\n\n<p class=\"wp-container-content-9cfa9a5a wp-block-paragraph\" style=\"font-size:14px\">crmiax@gmail.com <\/p>\n<\/div>\n<\/div><\/div>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\" style=\"font-size:13px\"><strong>ORCID:&nbsp;<a href=\"https:\/\/www.google.com\/url?sa=t&amp;rct=j&amp;q=&amp;esrc=s&amp;source=web&amp;cd=&amp;cad=rja&amp;uact=8&amp;ved=2ahUKEwit5ruii9yPAxVeArkGHWMcCn8QFnoECAkQAQ&amp;url=https%3A%2F%2Forcid.org%2F0000-0001-9743-8057&amp;usg=AOvVaw3sC2gzE-BkJmB3c_qlfuak&amp;opi=89978449\">0000-0001-<\/a><a href=\"https:\/\/www.google.com\/url?sa=t&amp;rct=j&amp;q=&amp;esrc=s&amp;source=web&amp;cd=&amp;cad=rja&amp;uact=8&amp;ved=2ahUKEwit5ruii9yPAxVeArkGHWMcCn8QFnoECAkQAQ&amp;url=https%3A%2F%2Forcid.org%2F0000-0001-9743-8057&amp;usg=AOvVaw3sC2gzE-BkJmB3c_qlfuak&amp;opi=89978449\" target=\"_blank\" rel=\"noreferrer noopener\">9743<\/a><a href=\"https:\/\/www.google.com\/url?sa=t&amp;rct=j&amp;q=&amp;esrc=s&amp;source=web&amp;cd=&amp;cad=rja&amp;uact=8&amp;ved=2ahUKEwit5ruii9yPAxVeArkGHWMcCn8QFnoECAkQAQ&amp;url=https%3A%2F%2Forcid.org%2F0000-0001-9743-8057&amp;usg=AOvVaw3sC2gzE-BkJmB3c_qlfuak&amp;opi=89978449\">-8057<\/a><\/strong><\/p>\n<\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-21-1024x1024.jpg\" alt=\"\" class=\"wp-image-10636\" style=\"aspect-ratio:4\/3;object-fit:contain\" srcset=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-21-1024x1024.jpg 1024w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-21-300x300.jpg 300w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-21-150x150.jpg 150w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-21-768x768.jpg 768w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-21-200x200.jpg 200w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-21-70x70.jpg 70w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-21.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" style=\"font-size:20px\">Fl\u00e1via Galindo<\/h2>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\" style=\"text-decoration:underline\"><strong>Permanente<\/strong><\/p>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-group is-content-justification-center is-nowrap is-layout-flex wp-container-core-group-is-layout-d05cb3ef wp-block-group-is-layout-flex\">\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\" style=\"font-size:16px\"><summary>Resumo<\/summary>\n<p class=\"wp-block-paragraph\" style=\"font-size:16px\">Jovem Cientista do Nosso Estado (JCNE) pela FAPERJ (2025). Professora Associada no DCA &#8211; Departamento de Ci\u00eancias Administrativas, vinculado ao ICSA Instituto de Ci\u00eancais Sociais Aplicadas da UFRRJ. Doutora em Ci\u00eancias Sociais (CPDA &#8211; UFRRJ), Mestre em Gest\u00e3o e Estrat\u00e9gia pelo PPGE\/UFRRJ, Bacharel em Administra\u00e7\u00e3o de Empresas pela UGF. MBA em Varejo pelo Instituto COPPEAD\/UFRJ, com visita t\u00e9cnica \u00e0 Universidade de San Diego (EUA), e P\u00f3s-Gradua\u00e7\u00e3o em Propaganda e Marketing pela ESPM-RJ. Presta consultorias ad hoc. Coordenadora das turmas de conv\u00eanios com o IFRJ Instituto Federal do Rio de Janeiro (em 2017 e 2018), CODEMAR Cia de Desenvolvimento de Maric\u00e1 (em 2020.1), IFAM Instituto Federal de Educa\u00e7\u00e3o, Ci\u00eancia e Tecnologia do Amazonas (2021, 2022 e 2023), IFRO Instituto Federal de Educa\u00e7\u00e3o, Ci\u00eancia e Tecnologia de Rond\u00f4nia (2022), IFAP Instituto Federal de Educa\u00e7\u00e3o, Ci\u00eancia e Tecnologia do Amap\u00e1 (2023). Coordenadora do PPGE Programa Profissional em Gest\u00e3o e Estrat\u00e9gia da UFRRJ (2018-2025). Sua carreira profissional come\u00e7ou na iniciativa privada, nas \u00e1reas de promo\u00e7\u00f5es e eventos, trade marketing, gest\u00e3o de varejo e atacado. Prestou consultorias em comunica\u00e7\u00e3o corporativa para diversas empresas. Possui experi\u00eancia profissional em marketing e comunica\u00e7\u00e3o corporativa em diversas empresas tais como Rede Manaus (Bridgestone Firestone), Grupo Abril, Cia Internacional de Seguros, Sweda Automa\u00e7\u00e3o Comercial, Tapetes Avanti, e N\u00f3s da Comunica\u00e7\u00e3o. Como docente e pesquisadora da \u00e1rea de Marketing, tem especial interesse pelo desenvolvimento de pesquisas sobre o consumo, comunica\u00e7\u00e3o corporativa e sociologia do marketing na Linha 2 do PPGE (Gest\u00e3o da Inova\u00e7\u00e3o, Mercados e Pol\u00edticas P\u00fablicas), e no projeto de pesquisa intitulado Consumo, Marketing e Sustentabilidade. \u00c9 associada ANPAD na Divis\u00e3o de Marketing, e uma das l\u00edderes do tema Transformando Sistemas Alimentares: Comportamento do Consumidor, Marketing e Sustentabilidade no Agroneg\u00f3cio para o tri\u00eanio 2025-2027. Integra os Comit\u00eas Cient\u00edfico e Organizador do ENEC Encontro Nacional dos Estudos do Consumo. \u00c9 l\u00edder do grupo de pesquisa em Consumo e Sociologia de Marketing (CNPq) e foi contemplada com o Aux\u00edlio Instala\u00e7\u00e3o da FAPERJ. Tem participado da comiss\u00e3o julgadora de pr\u00eamios nacionais como o Pr\u00eamio ABERJE. \u00c9 membro do Conselho de Ensino, Pesquisa e Extens\u00e3o &#8211; CEPE da UFRRJ, do CEPEA &#8211; Conselho de Ensino, Pesquisa e Extens\u00e3o de \u00c1rea, do Conselho de Unidade da UFRRJ (CONSUNI), dos colegiados de cursos de gradua\u00e7\u00e3o da UFRRJ. ORCID: http:\/\/orcid.org\/0000-0002-8678-631X. <a href=\"https:\/\/buscatextual.cnpq.br\/buscatextual\/visualizacv.do;jsessionid=469B5201FD8DF95EF6EAC2968A1514C5.buscatextual_0\">Lattes<\/a><\/p>\n<\/details>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:16px\"><a href=\"http:\/\/buscatextual.cnpq.br\/buscatextual\/visualizacv.do?id=K4254372H2\" type=\"link\" id=\"http:\/\/buscatextual.cnpq.br\/buscatextual\/visualizacv.do?id=K4254372H2\" target=\"_blank\" rel=\"noreferrer noopener\">Lattes<\/a><\/p>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-group is-content-justification-center is-nowrap is-layout-flex wp-container-core-group-is-layout-d05cb3ef wp-block-group-is-layout-flex\">\n<ul class=\"wp-block-social-links is-layout-flex wp-block-social-links-is-layout-flex\"><li class=\"wp-social-link wp-social-link-mail wp-block-social-link\"><a href=\"https:\/\/flaviagalindo@uol.com.br%20\" class=\"wp-block-social-link-anchor\"><svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M19,5H5c-1.1,0-2,.9-2,2v10c0,1.1.9,2,2,2h14c1.1,0,2-.9,2-2V7c0-1.1-.9-2-2-2zm.5,12c0,.3-.2.5-.5.5H5c-.3,0-.5-.2-.5-.5V9.8l7.5,5.6,7.5-5.6V17zm0-9.1L12,13.6,4.5,7.9V7c0-.3.2-.5.5-.5h14c.3,0,.5.2.5.5v.9z\"><\/path><\/svg><span class=\"wp-block-social-link-label screen-reader-text\">E-mail<\/span><\/a><\/li><\/ul>\n\n\n\n<p class=\"wp-container-content-9cfa9a5a wp-block-paragraph\" style=\"font-size:14px\">flaviagalindo@uol.com.br <\/p>\n<\/div>\n<\/div><\/div>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\" style=\"font-size:13px\"><strong>ORCID:&nbsp;<a href=\"https:\/\/orcid.org\/0000-0003-4243-394X\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><a href=\"https:\/\/orcid.org\/0000-0002-8678-631X\" target=\"_blank\" rel=\"noreferrer noopener\">0000-0002-8678-631X<\/a><\/strong><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column has-midnight-gradient-background has-background is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:3px\"><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-22-1024x1024.jpg\" alt=\"\" class=\"wp-image-10637\" style=\"aspect-ratio:4\/3;object-fit:contain\" srcset=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-22-1024x1024.jpg 1024w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-22-300x300.jpg 300w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-22-150x150.jpg 150w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-22-768x768.jpg 768w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-22-200x200.jpg 200w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-22-70x70.jpg 70w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-22.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" style=\"font-size:20px\">Jana\u00edna Souza<\/h2>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\" style=\"text-decoration:underline\"><strong>Colaborador<\/strong><\/p>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-group is-content-justification-center is-nowrap is-layout-flex wp-container-core-group-is-layout-d05cb3ef wp-block-group-is-layout-flex\">\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\" style=\"font-size:16px\"><summary>Resumo<\/summary>\n<p class=\"wp-block-paragraph\" style=\"font-size:16px\">Professora do Departamento de Administra\u00e7\u00e3o e Turismo (DAT) da Universidade Federal Rural do Rio de Janeiro (UFRRJ), campus de Nova Igua\u00e7u. L\u00edder CNPq do Grupo de Estudos em Marketing, Tecnologia e Ecologia (GEMTE). Doutora em Antropologia pela Universidade Federal Fluminense (UFF) com estudos sobre Cultura e Identidade; Mestre em Gest\u00e3o e Estrat\u00e9gia em Neg\u00f3cios pela UFRRJ com pesquisa sobre Marketing Verde e Comportamento do Consumidor; Especialista em Marketing pela Universidade C\u00e2ndido Mendes (UCAM) com estudos sobre Marketing Verde e Comportamento Organizacional; Especialista em Ecoturismo pela Universidade Federal de Lavras (UFLA) com trabalho sobre Comunidade Tradicional Cai\u00e7ara em Unidade de Conserva\u00e7\u00e3o; Bacharel em Administra\u00e7\u00e3o pela UFRRJ. Atua nas \u00e1reas de Estrat\u00e9gias de Marketing, Marketing Tur\u00edstico, Marketing Verde, Cultura, Identidade e Comportamento do Consumidor. \u00c9 Coordenadora da Disciplina de Marketing Tur\u00edstico e conteudista dos livros did\u00e1ticos da disciplina, oferecida para os cursos EAD, oferecida pelas universidades UFRRJ, UNIRIO e CEFET, atrav\u00e9s da Funda\u00e7\u00e3o CECIERJ. Avaliadora de Curso Superior Presencial e a Dist\u00e2ncia pelo Minist\u00e9rio da Educa\u00e7\u00e3o (MEC\/INEP).<strong>&nbsp;<\/strong>&nbsp;<a href=\"http:\/\/lattes.cnpq.br\/1864611234587211\" target=\"_blank\" rel=\"noreferrer noopener\">Lattes<\/a><\/p>\n<\/details>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:16px\"><a href=\"http:\/\/lattes.cnpq.br\/1864611234587211\" target=\"_blank\" rel=\"noreferrer noopener\">Lattes<\/a><\/p>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-group is-content-justification-center is-nowrap is-layout-flex wp-container-core-group-is-layout-d05cb3ef wp-block-group-is-layout-flex\">\n<ul class=\"wp-block-social-links is-layout-flex wp-block-social-links-is-layout-flex\"><li class=\"wp-social-link wp-social-link-mail wp-block-social-link\"><a href=\"https:\/\/jananss@yahoo.com.br%20\" class=\"wp-block-social-link-anchor\"><svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M19,5H5c-1.1,0-2,.9-2,2v10c0,1.1.9,2,2,2h14c1.1,0,2-.9,2-2V7c0-1.1-.9-2-2-2zm.5,12c0,.3-.2.5-.5.5H5c-.3,0-.5-.2-.5-.5V9.8l7.5,5.6,7.5-5.6V17zm0-9.1L12,13.6,4.5,7.9V7c0-.3.2-.5.5-.5h14c.3,0,.5.2.5.5v.9z\"><\/path><\/svg><span class=\"wp-block-social-link-label screen-reader-text\">E-mail<\/span><\/a><\/li><\/ul>\n\n\n\n<p class=\"wp-container-content-9cfa9a5a wp-block-paragraph\" style=\"font-size:14px\">jananss@yahoo.com.br <\/p>\n<\/div>\n<\/div><\/div>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\" style=\"font-size:13px\"><strong>ORCID:&nbsp;<a href=\"https:\/\/orcid.org\/0000-0001-9541-1694\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><a href=\"https:\/\/orcid.org\/0000-0001-5711-1084\">0000-0001<\/a><a href=\"https:\/\/orcid.org\/0000-0001-5711-1084\" target=\"_blank\" rel=\"noreferrer noopener\">&#8211;<\/a><a href=\"https:\/\/orcid.org\/0000-0001-5711-1084\">5711-1084<\/a><\/strong><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column has-midnight-gradient-background has-background is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:3px\"><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-23-1024x1024.jpg\" alt=\"\" class=\"wp-image-10638\" style=\"aspect-ratio:4\/3;object-fit:contain\" srcset=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-23-1024x1024.jpg 1024w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-23-300x300.jpg 300w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-23-150x150.jpg 150w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-23-768x768.jpg 768w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-23-200x200.jpg 200w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-23-70x70.jpg 70w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-23.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" style=\"font-size:20px\">Patr\u00edcia Leite<\/h2>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\" style=\"text-decoration:underline\"><strong>Permanente<\/strong><\/p>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-group is-content-justification-center is-nowrap is-layout-flex wp-container-core-group-is-layout-d05cb3ef wp-block-group-is-layout-flex\">\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\" style=\"font-size:16px\"><summary>Resumo<\/summary>\n<p class=\"wp-block-paragraph\" style=\"font-size:16px\">Doutora em Administra\u00e7\u00e3o pela Universidade FUMEC (MG), Mestre em Administra\u00e7\u00e3o e Desenvolvimento Empresarial pela Universidade Est\u00e1cio de S\u00e1 (UNESA), p\u00f3s graduada em Finan\u00e7as, Controladoria, Auditoria e Tributos pela Universidade Osvaldo Aranha (UNIFOA) e graduada em Administra\u00e7\u00e3o de Empresas pela Associa\u00e7\u00e3o Brasileira de Ensino Universit\u00e1rio (UNIABEU). Nove anos de atua\u00e7\u00e3o na \u00e1rea de doc\u00eancia, lecionando em cursos de gradua\u00e7\u00e3o, como Administra\u00e7\u00e3o, Ci\u00eancias Cont\u00e1beis, Gest\u00e3o de Recursos Humanos e Gest\u00e3o Log\u00edstica, e P\u00f3s Gradua\u00e7\u00e3o, como Gest\u00e3o em Administra\u00e7\u00e3o P\u00fablica, Gest\u00e3o Empresarial e Gest\u00e3o de Pessoas. Atua\u00e7\u00e3o como Professora Focal do Enade na Universidade Est\u00e1cio de S\u00e1 \u2013 Campus Angra dos Reis, colocando a Unidade como 1\u00aa colocada na ades\u00e3o a n\u00edvel Brasil. Atua\u00e7\u00e3o como Coordenadora do Curso de Administra\u00e7\u00e3o na Universidade Est\u00e1cio de S\u00e1, Campus de Angra dos Reis, RJ. Atua\u00e7\u00e3o como 2\u00ba Tenente ADM pela For\u00e7a A\u00e9rea Brasileira (FAB) servindo na Universidade da For\u00e7a A\u00e9rea (UNIFA) no Campo dos Afonsos \u2013 Rio de Janeiro \u2013 RJ, e professora Colaboradora dos cursos de Mestrado e Doutorado no Programa de P\u00f3s-Gradua\u00e7\u00e3o em Ci\u00eancias Aeroespaciais na Universidade da For\u00e7a A\u00e9rea (UNIFA). Atuo como Professora Adjunta na Universidade Federal Rural do Rio De Janeiro (UFRRJ). Pesquisadora nas tem\u00e1ticas: Marketing, Comportamento do Consumidor, Cultura e Consumo e Administra\u00e7\u00e3o Estrat\u00e9gica.&nbsp;<a href=\"http:\/\/lattes.cnpq.br\/6097082664548980\" target=\"_blank\" rel=\"noreferrer noopener\">Lattes<\/a><\/p>\n<\/details>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:16px\"><a href=\"http:\/\/lattes.cnpq.br\/6097082664548980\" target=\"_blank\" rel=\"noreferrer noopener\">Lattes<\/a><\/p>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-group is-content-justification-center is-nowrap is-layout-flex wp-container-core-group-is-layout-d05cb3ef wp-block-group-is-layout-flex\">\n<ul class=\"wp-block-social-links is-layout-flex wp-block-social-links-is-layout-flex\"><li class=\"wp-social-link wp-social-link-mail wp-block-social-link\"><a href=\"https:\/\/%20patricialeite@ufrrj.br%20\" class=\"wp-block-social-link-anchor\"><svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M19,5H5c-1.1,0-2,.9-2,2v10c0,1.1.9,2,2,2h14c1.1,0,2-.9,2-2V7c0-1.1-.9-2-2-2zm.5,12c0,.3-.2.5-.5.5H5c-.3,0-.5-.2-.5-.5V9.8l7.5,5.6,7.5-5.6V17zm0-9.1L12,13.6,4.5,7.9V7c0-.3.2-.5.5-.5h14c.3,0,.5.2.5.5v.9z\"><\/path><\/svg><span class=\"wp-block-social-link-label screen-reader-text\">E-mail<\/span><\/a><\/li><\/ul>\n\n\n\n<p class=\"wp-container-content-9cfa9a5a wp-block-paragraph\" style=\"font-size:14px\"> patricialeite@ufrrj.br <\/p>\n<\/div>\n<\/div><\/div>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\" style=\"font-size:13px\"><strong>ORCID:&nbsp;<a href=\"https:\/\/www.google.com\/url?sa=t&amp;rct=j&amp;q=&amp;esrc=s&amp;source=web&amp;cd=&amp;cad=rja&amp;uact=8&amp;ved=2ahUKEwiXxKSajtyPAxXKGLkGHUlbIzYQFnoECBkQAQ&amp;url=https%3A%2F%2Forcid.org%2F0000-0002-6678-3912&amp;usg=AOvVaw24tvvpT2T2d80_eFEBL2xS&amp;opi=89978449\" target=\"_blank\" rel=\"noreferrer noopener\">0000-0002-6678-3912<\/a><\/strong><\/p>\n<\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-24-1024x1024.jpg\" alt=\"\" class=\"wp-image-10648\" style=\"aspect-ratio:4\/3;object-fit:contain\" srcset=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-24-1024x1024.jpg 1024w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-24-300x300.jpg 300w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-24-150x150.jpg 150w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-24-768x768.jpg 768w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-24-200x200.jpg 200w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-24-70x70.jpg 70w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-24.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" style=\"font-size:20px\">Rafael Ferro<\/h2>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\" style=\"text-decoration:underline\"><strong>Permanente<\/strong><\/p>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-group is-content-justification-center is-nowrap is-layout-flex wp-container-core-group-is-layout-d05cb3ef wp-block-group-is-layout-flex\">\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\" style=\"font-size:16px\"><summary>Resumo<\/summary>\n<p class=\"wp-block-paragraph\" style=\"font-size:16px\">Doutor e Mestre em Hospitalidade pela Universidade Anhembi Morumbi (UAM), p\u00f3s-graduado (lato sensu) em Viticultura e Enologia pela Universidade Tuiuti do Paran\u00e1 (UTP), graduado em Tecnologia em Gastronomia pelo Centro Universit\u00e1rio Senac \u2013 Campus Campos do Jord\u00e3o e graduando em Filosofia. Atualmente \u00e9 Professor Adjunto da \u00e1rea de Alimentos e Bebidas do curso de Bacharelado em Hotelaria da Universidade Federal Rural do Rio de Janeiro (UFRRJ), Docente permanente do Programa de P\u00f3s-gradua\u00e7\u00e3o em Gest\u00e3o e Estrat\u00e9gia (PPGE) da UFRRJ e Docente colaborador do Programa de P\u00f3s-Gradua\u00e7\u00e3o (mestrado e doutorado) em Hospitalidade da UAM. Tem experi\u00eancia como professor em cursos de gradua\u00e7\u00e3o em Gastronomia (tecnol\u00f3gico e bacharelado) em diversas institui\u00e7\u00f5es e como coordenador de curso e coordenador acad\u00eamico de gradua\u00e7\u00e3o e p\u00f3s-gradua\u00e7\u00e3o lato sensu da \u00e1rea de Hospitalidade e Neg\u00f3cios. \u00c9 vice-l\u00edder do grupo de pesquisa Observat\u00f3rio te\u00f3rico-acad\u00eamico das gastronomias e membro dos grupos de pesquisa: Dimens\u00f5es e Contextos da Hospitalidade, associado ao Programa de P\u00f3s-Gradua\u00e7\u00e3o em Hospitalidade (UAM) e Processos de Gest\u00e3o, Sustentabilidade e Turismo (UFRRJ). \u00c9 Editor de se\u00e7\u00e3o (Gastronomia) da Revista Hospitalidade e avaliador de peri\u00f3dicos em \u00e2mbitos internacional e nacional. Tem interesse em projetos com os temas: Interfaces entre Gastronomia, Hospitalidade e Turismo; Hospitalidade e hostilidade nas interseccionalidades de g\u00eanero e sexualidade; \u00c9tica e diversidades.&nbsp;<a href=\"http:\/\/lattes.cnpq.br\/9643271002123963\" target=\"_blank\" rel=\"noreferrer noopener\">Lattes<\/a><\/p>\n<\/details>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:16px\"><a href=\"http:\/\/lattes.cnpq.br\/9643271002123963\" target=\"_blank\" rel=\"noreferrer noopener\">Lattes<\/a><\/p>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-group is-content-justification-center is-nowrap is-layout-flex wp-container-core-group-is-layout-d05cb3ef wp-block-group-is-layout-flex\">\n<ul class=\"wp-block-social-links is-layout-flex wp-block-social-links-is-layout-flex\"><li class=\"wp-social-link wp-social-link-mail wp-block-social-link\"><a href=\"https:\/\/rafaelferro@ufrrj.br%20\" class=\"wp-block-social-link-anchor\"><svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M19,5H5c-1.1,0-2,.9-2,2v10c0,1.1.9,2,2,2h14c1.1,0,2-.9,2-2V7c0-1.1-.9-2-2-2zm.5,12c0,.3-.2.5-.5.5H5c-.3,0-.5-.2-.5-.5V9.8l7.5,5.6,7.5-5.6V17zm0-9.1L12,13.6,4.5,7.9V7c0-.3.2-.5.5-.5h14c.3,0,.5.2.5.5v.9z\"><\/path><\/svg><span class=\"wp-block-social-link-label screen-reader-text\">E-mail<\/span><\/a><\/li><\/ul>\n\n\n\n<p class=\"wp-container-content-9cfa9a5a wp-block-paragraph\" style=\"font-size:14px\">rafaelferro@ufrrj.br <\/p>\n<\/div>\n<\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:13px\"><strong>ORCID:&nbsp;<a href=\"https:\/\/orcid.org\/0000-0001-9541-1694\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><a href=\"https:\/\/orcid.org\/0000-0002-9063-8395\" target=\"_blank\" rel=\"noreferrer noopener\">0000-0002-9063-8395<\/a><\/strong><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column has-midnight-gradient-background has-background is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:3px\"><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-25-1024x1024.jpg\" alt=\"\" class=\"wp-image-10649\" style=\"aspect-ratio:4\/3;object-fit:contain\" srcset=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-25-1024x1024.jpg 1024w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-25-300x300.jpg 300w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-25-150x150.jpg 150w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-25-768x768.jpg 768w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-25-200x200.jpg 200w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-25-70x70.jpg 70w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-25.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" style=\"font-size:20px\">Rodrigo Amado<\/h2>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\" style=\"text-decoration:underline\"><strong>Permanente<\/strong><\/p>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-group is-content-justification-center is-nowrap is-layout-flex wp-container-core-group-is-layout-d05cb3ef wp-block-group-is-layout-flex\">\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\" style=\"font-size:16px\"><summary>Resumo<\/summary>\n<p class=\"wp-block-paragraph\" style=\"font-size:16px\">Possui gradua\u00e7\u00e3o em Turismo pela Universidade Metodista de Piracicaba (2003) e mestrado em Ci\u00eancias Sociais pela Universidade Estadual Paulista J\u00falio de Mesquita Filho (2009). Em fevereiro de 2018 obt\u00e9m seu t\u00edtulo de doutor em Sistemas de Gest\u00e3o Sustent\u00e1veis pela Universidade Federal Fluminense (LATEC PPSIG), sendo aprovado em primeiro lugar no processo seletivo de 2014. Atualmente \u00e9 professor dos cursos de bacharelado em hotelaria e de licenciatura em turismo pela Universidade Federal Rural do Rio de Janeiro. \u00c9 professor permanente do MBA em Gest\u00e3o de Servi\u00e7os da Universidade Federal Fluminense e do Programa de P\u00f3s-Gradua\u00e7\u00e3o em Gest\u00e3o e Estrat\u00e9gia da UFRRJ. \u00c9 l\u00edder do seguinte Grupo de Pesquisa CNPQ: Processos de Gest\u00e3o, Sustentabilidade e Turismo (PROGESTUR). Possui experi\u00eancia nas \u00e1reas interdisciplinares e das ci\u00eancias sociais aplicadas, com enfoque em pesquisas que observam as seguintes tem\u00e1ticas: gest\u00f5es tur\u00edsticas sustent\u00e1veis; gest\u00f5es hoteleiras e excel\u00eancia organizacional; turismo, cultura e meio ambiente.&nbsp;<a href=\"http:\/\/lattes.cnpq.br\/1796719676504640\" target=\"_blank\" rel=\"noreferrer noopener\">Lattes<\/a><\/p>\n<\/details>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:16px\"><a href=\"http:\/\/lattes.cnpq.br\/1796719676504640\" target=\"_blank\" rel=\"noreferrer noopener\">Lattes<\/a><\/p>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-group is-content-justification-center is-nowrap is-layout-flex wp-container-core-group-is-layout-d05cb3ef wp-block-group-is-layout-flex\">\n<ul class=\"wp-block-social-links is-layout-flex wp-block-social-links-is-layout-flex\"><li class=\"wp-social-link wp-social-link-mail wp-block-social-link\"><a href=\"https:\/\/rodrigo_amado@ufrrj.br%20\" class=\"wp-block-social-link-anchor\"><svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M19,5H5c-1.1,0-2,.9-2,2v10c0,1.1.9,2,2,2h14c1.1,0,2-.9,2-2V7c0-1.1-.9-2-2-2zm.5,12c0,.3-.2.5-.5.5H5c-.3,0-.5-.2-.5-.5V9.8l7.5,5.6,7.5-5.6V17zm0-9.1L12,13.6,4.5,7.9V7c0-.3.2-.5.5-.5h14c.3,0,.5.2.5.5v.9z\"><\/path><\/svg><span class=\"wp-block-social-link-label screen-reader-text\">E-mail<\/span><\/a><\/li><\/ul>\n\n\n\n<p class=\"wp-container-content-9cfa9a5a wp-block-paragraph\" style=\"font-size:14px\">rodrigo_amado@ufrrj.br <\/p>\n<\/div>\n<\/div><\/div>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\" style=\"font-size:13px\"><strong>ORCID:&nbsp;<a href=\"https:\/\/orcid.org\/0000-0003-4243-394X\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><a href=\"https:\/\/orcid.org\/0000-0002-7143-5752\" target=\"_blank\" rel=\"noreferrer noopener\">0000-0002-7143-5752<\/a><\/strong><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column has-midnight-gradient-background has-background is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:3px\"><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-26-1024x1024.jpg\" alt=\"\" class=\"wp-image-10656\" style=\"aspect-ratio:4\/3;object-fit:contain\" srcset=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-26-1024x1024.jpg 1024w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-26-300x300.jpg 300w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-26-150x150.jpg 150w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-26-768x768.jpg 768w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-26-200x200.jpg 200w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-26-70x70.jpg 70w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-26.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" style=\"font-size:20px\">Roberta Dalvo<\/h2>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\" style=\"text-decoration:underline\"><strong>Permanente<\/strong><\/p>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-group is-content-justification-center is-nowrap is-layout-flex wp-container-core-group-is-layout-d05cb3ef wp-block-group-is-layout-flex\">\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\" style=\"font-size:16px\"><summary>Resumo<\/summary>\n<p class=\"wp-block-paragraph\" style=\"font-size:16px\">Doutora em Ci\u00eancia e Tecnologia de Pol\u00edmeros pela Universidade Federal do Rio de Janeiro (2012), Mestre em Gest\u00e3o e Estrat\u00e9gia (PPGE\/UFRRJ) (2006) e Graduada em Administra\u00e7\u00e3o de Empresas pela Universidade do Estado do Rio de Janeiro (2002) e. Fez um p\u00f3s-doutorado no IMA\/UFRJ (2014 \/ 2016), na \u00e1rea de Gest\u00e3o Ambiental. Atualmente \u00e9 coordenadora de disciplina \u2013 Cederj, docente do Centro Federal de Educa\u00e7\u00e3o Tecnol\u00f3gica Celso Suckow da Fonseca e docente permanente no Mestrado Profissional em Gest\u00e3o e Estrat\u00e9gia (PPGE\/UFRRJ). Tem experi\u00eancia na \u00e1rea de Administra\u00e7\u00e3o e Turismo, com \u00eanfase em gerenciamento de res\u00edduos, log\u00edstica reversa e sustentabilidade nas organiza\u00e7\u00f5es.&nbsp;<a href=\"http:\/\/lattes.cnpq.br\/6626213337928112\" target=\"_blank\" rel=\"noreferrer noopener\">Lattes<\/a><\/p>\n<\/details>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:16px\"><a href=\"http:\/\/lattes.cnpq.br\/6626213337928112\" target=\"_blank\" rel=\"noreferrer noopener\">Lattes<\/a><\/p>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-group is-content-justification-center is-nowrap is-layout-flex wp-container-core-group-is-layout-d05cb3ef wp-block-group-is-layout-flex\">\n<ul class=\"wp-block-social-links is-layout-flex wp-block-social-links-is-layout-flex\"><li class=\"wp-social-link wp-social-link-mail wp-block-social-link\"><a href=\"mailto:r&#100;a&#108;v&#111;&#064;g&#109;&#097;&#105;&#108;&#046;&#099;o&#109;\" class=\"wp-block-social-link-anchor\"><svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M19,5H5c-1.1,0-2,.9-2,2v10c0,1.1.9,2,2,2h14c1.1,0,2-.9,2-2V7c0-1.1-.9-2-2-2zm.5,12c0,.3-.2.5-.5.5H5c-.3,0-.5-.2-.5-.5V9.8l7.5,5.6,7.5-5.6V17zm0-9.1L12,13.6,4.5,7.9V7c0-.3.2-.5.5-.5h14c.3,0,.5.2.5.5v.9z\"><\/path><\/svg><span class=\"wp-block-social-link-label screen-reader-text\">E-mail<\/span><\/a><\/li><\/ul>\n\n\n\n<p class=\"wp-container-content-9cfa9a5a wp-block-paragraph\" style=\"font-size:14px\">rdalvo@gmail.com<\/p>\n<\/div>\n<\/div><\/div>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\" style=\"font-size:13px\"> <strong>ORCID:&nbsp;<a href=\"https:\/\/orcid.org\/0000-0001-9541-1694\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><a href=\"https:\/\/orcid.org\/0000-0002-1566-0437\" target=\"_blank\" rel=\"noreferrer noopener\">0000-0002-1566-0437<\/a><\/strong><\/p>\n<\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-27-1024x1024.jpg\" alt=\"\" class=\"wp-image-10658\" style=\"aspect-ratio:4\/3;object-fit:contain\" srcset=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-27-1024x1024.jpg 1024w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-27-300x300.jpg 300w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-27-150x150.jpg 150w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-27-768x768.jpg 768w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-27-200x200.jpg 200w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-27-70x70.jpg 70w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-27.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" style=\"font-size:20px\">Sandro Freire<\/h2>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\" style=\"text-decoration:underline\"><strong>Permanente<\/strong><\/p>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-group is-content-justification-center is-nowrap is-layout-flex wp-container-core-group-is-layout-d05cb3ef wp-block-group-is-layout-flex\">\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\" style=\"font-size:16px\"><summary>Resumo<\/summary>\n<p class=\"wp-block-paragraph\" style=\"font-size:16px\">Doutor em Inform\u00e1tica pelo Programa de P\u00f3s-Gradua\u00e7\u00e3o em Inform\u00e1tica (PPGI) da Universidade Federal do Estado do Rio de Janeiro (UNIRIO). Possui Bacharelado em Sistemas de Informa\u00e7\u00e3o (2008) com especializa\u00e7\u00f5es em Gerenciamentos de Projetos (2012), Gest\u00e3o em Administra\u00e7\u00e3o P\u00fablica (2016) e Gest\u00e3o em Administra\u00e7\u00e3o em Sa\u00fade P\u00fablica (2020) todas realizadas na Universidade Federal Fluminense (UFF). Possui Mestrado em Administra\u00e7\u00e3o (\u00canfase em \u200bTecnologias, Gest\u00e3o de Projetos e Processos) pelo Programa de P\u00f3s-Gradua\u00e7\u00e3o em Gest\u00e3o e Estrat\u00e9gia (PPGE) da Universidade Federal Rural do Rio de Janeiro (UFRRJ). Atuou em organiza\u00e7\u00f5es de natureza p\u00fablica com not\u00f3rio reconhecimento como Caixa Econ\u00f4mica Federal (CEF) e Universidade Federal Rural do Rio de Janeiro (UFRRJ), onde teve a oportunidade de exercer a posi\u00e7\u00e3o de Diretor de Tecnologia da Informa\u00e7\u00e3o. Atualmente \u00e9 Docente Permanente do Programa de P\u00f3s-Gradua\u00e7\u00e3o em Gest\u00e3o e Estrat\u00e9gia (PPGE) da Universidade Federal Rural do Rio de Janeiro. Al\u00e9m disso atua como Analista em Ci\u00eancia e Tecnologia na \u00e1rea de Recursos Tecnol\u00f3gicos do Instituto Nacional de C\u00e2ncer, atuando tamb\u00e9m na institui\u00e7\u00e3o como Docente no M\u00f3dulo Gest\u00e3o em Sa\u00fade do Programa de Resid\u00eancia Multiprofissional em Oncologia, na modalidade P\u00f3s-Gradua\u00e7\u00e3o Lato Sensu. Publicou artigos em peri\u00f3dicos e congressos na \u00e1rea de Sistemas de Informa\u00e7\u00e3o, Sistemas de Informa\u00e7\u00e3o em Sa\u00fade, Administra\u00e7\u00e3o, Administra\u00e7\u00e3o P\u00fablica. Atua como revisor de peri\u00f3dicos das \u00e1reas de Computa\u00e7\u00e3o, especialmente nos temas relacionados \u00e0 Sistemas de Informa\u00e7\u00e3o em Sa\u00fade. Seus principais campos de atua\u00e7\u00e3o s\u00e3o Sistemas de Informa\u00e7\u00e3o em Sa\u00fade, Inova\u00e7\u00e3o em Sa\u00fade, Administra\u00e7\u00e3o da Informa\u00e7\u00e3o, Planejamento Estrat\u00e9gico em Tecnologia da Informa\u00e7\u00e3o e Administra\u00e7\u00e3o P\u00fablica.<a href=\"http:\/\/lattes.cnpq.br\/0579936659778289\">&nbsp;<\/a><a href=\"http:\/\/lattes.cnpq.br\/0579936659778289\" target=\"_blank\" rel=\"noreferrer noopener\">Lattes<\/a><\/p>\n<\/details>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:16px\"><a href=\"http:\/\/lattes.cnpq.br\/0579936659778289\" target=\"_blank\" rel=\"noreferrer noopener\">Lattes<\/a><\/p>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-group is-content-justification-center is-nowrap is-layout-flex wp-container-core-group-is-layout-d05cb3ef wp-block-group-is-layout-flex\">\n<ul class=\"wp-block-social-links is-layout-flex wp-block-social-links-is-layout-flex\"><li class=\"wp-social-link wp-social-link-mail wp-block-social-link\"><a href=\"mailto:&#115;a&#110;&#100;rof&#114;&#101;i&#114;e&#064;&#103;ma&#105;&#108;.com\" class=\"wp-block-social-link-anchor\"><svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M19,5H5c-1.1,0-2,.9-2,2v10c0,1.1.9,2,2,2h14c1.1,0,2-.9,2-2V7c0-1.1-.9-2-2-2zm.5,12c0,.3-.2.5-.5.5H5c-.3,0-.5-.2-.5-.5V9.8l7.5,5.6,7.5-5.6V17zm0-9.1L12,13.6,4.5,7.9V7c0-.3.2-.5.5-.5h14c.3,0,.5.2.5.5v.9z\"><\/path><\/svg><span class=\"wp-block-social-link-label screen-reader-text\">E-mail<\/span><\/a><\/li><\/ul>\n\n\n\n<p class=\"wp-container-content-9cfa9a5a wp-block-paragraph\" style=\"font-size:14px\">sandrofreire@gmail.com<\/p>\n<\/div>\n<\/div><\/div>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\" style=\"font-size:13px\"> <strong>ORCID:&nbsp;<a href=\"https:\/\/orcid.org\/0000-0003-4243-394X\" target=\"_blank\" rel=\"noreferrer noopener\">0000-0003-0531-8950<\/a><\/strong><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column has-midnight-gradient-background has-background is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:3px\"><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-28-1024x1024.jpg\" alt=\"\" class=\"wp-image-10660\" style=\"aspect-ratio:4\/3;object-fit:contain\" srcset=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-28-1024x1024.jpg 1024w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-28-300x300.jpg 300w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-28-150x150.jpg 150w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-28-768x768.jpg 768w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-28-200x200.jpg 200w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-28-70x70.jpg 70w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-28.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" style=\"font-size:20px\">Thiago Renault<\/h2>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\" style=\"text-decoration:underline\"><strong><strong>Colaborador<\/strong><\/strong><\/p>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-group is-content-justification-center is-nowrap is-layout-flex wp-container-core-group-is-layout-d05cb3ef wp-block-group-is-layout-flex\">\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\" style=\"font-size:16px\"><summary>Resumo<\/summary>\n<p class=\"wp-block-paragraph\" style=\"font-size:16px\">Professor do Departamento de Ci\u00eancias Administrativas (DCAd) da Universidade Federal Rural do Rio de Janeiro (UFRRJ). Professor do Programa de P\u00f3s-gradua\u00e7\u00e3o em Gest\u00e3o e Estrat\u00e9gia. Membro do Centro de Estudos Avan\u00e7ados da UFRRJ, do Comit\u00ea T\u00e9cnico da Ag\u00eancia de Inova\u00e7\u00e3o e do Programa de bolsas de Inicia\u00e7\u00e3o a Inova\u00e7\u00e3o. Economista com mestrado e doutorado em engenharia de produ\u00e7\u00e3o, atua h\u00e1 vinte anos em atividades de ensino, pesquisa e extens\u00e3o em temas relacionados \u00e0 inova\u00e7\u00e3o e ao empreendedorismo. P\u00f3s doutorado no Departamento de Ci\u00eancias Sociais, Pol\u00edticas e do Territ\u00f3rio da Universidade de Aveiro em Portugal, P\u00f3s doutorado no Research Policy Institute da Universidade de Lund na Su\u00e9cia (Bolsista CAPES), pesquisador visitante na Universidade de Havana em Cuba (Bolsista CAPES). Aluno da academia Globelics de doutorado na Universidade de Tampere na Finl\u00e2ndia (Bolsa concedida pelo governo da Finl\u00e2ndia). Membro do National Advisory Council \u2013 NACI, ligado do Department of Science and Techonology do governo da \u00c1frica do Sul (2017 \u2013 2018). Membro do conselho consultivo do Plano Nacional de Empreendedorismo desenvolvido pela secretaria nacional da Juventude em 2017. Membro do conselho cient\u00edfico da confer\u00eancia nacional da ANPROTEC de 2017 at\u00e9 a presente data. Foi assessor t\u00e9cnico da Presid\u00eancia (2015 \u2013 2016) e Diretoria de Tecnologia e Inova\u00e7\u00e3o da FAPERJ (2016-2018). Foi diretor da Ag\u00eancia de Inova\u00e7\u00e3o da Universidade Federal Fluminense (2015 \u2013 2017). Foi coordenador adjunto do Centro de Estudos Avan\u00e7ados da UFRRJ (2018-2019). Pesquisador associado do Laborat\u00f3rio de Inova\u00e7\u00e3o Tecnol\u00f3gica, Organizacional e em Servi\u00e7os \u2013 LabrInTOS\/COPPE, da Universidade Federal do Rio de Janeiro. Pesquisador associado do Triple Helix Research Group Brazil da Universidade Federal Fluminense. Coordenador do N\u00facleo de Estudos sobre Inova\u00e7\u00e3o \u2013 NEIN, vinculado \u00e0 UFRRJ.&nbsp;<a href=\"http:\/\/lattes.cnpq.br\/3066311100730283\" target=\"_blank\" rel=\"noreferrer noopener\">Lattes<\/a><\/p>\n<\/details>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:16px\"><a href=\"http:\/\/lattes.cnpq.br\/3066311100730283\" target=\"_blank\" rel=\"noreferrer noopener\">Lattes<\/a><\/p>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-group is-content-justification-center is-nowrap is-layout-flex wp-container-core-group-is-layout-d05cb3ef wp-block-group-is-layout-flex\">\n<ul class=\"wp-block-social-links is-layout-flex wp-block-social-links-is-layout-flex\"><li class=\"wp-social-link wp-social-link-mail wp-block-social-link\"><a href=\"https:\/\/thiagorenault@ufrrj.br%20\" class=\"wp-block-social-link-anchor\"><svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M19,5H5c-1.1,0-2,.9-2,2v10c0,1.1.9,2,2,2h14c1.1,0,2-.9,2-2V7c0-1.1-.9-2-2-2zm.5,12c0,.3-.2.5-.5.5H5c-.3,0-.5-.2-.5-.5V9.8l7.5,5.6,7.5-5.6V17zm0-9.1L12,13.6,4.5,7.9V7c0-.3.2-.5.5-.5h14c.3,0,.5.2.5.5v.9z\"><\/path><\/svg><span class=\"wp-block-social-link-label screen-reader-text\">E-mail<\/span><\/a><\/li><\/ul>\n\n\n\n<p class=\"wp-container-content-9cfa9a5a wp-block-paragraph\" style=\"font-size:14px\">thiagorenault@ufrrj.br <\/p>\n<\/div>\n<\/div><\/div>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\" style=\"font-size:13px\"><strong>ORCID:&nbsp;<a href=\"https:\/\/orcid.org\/0000-0001-7523-2437\">0000-0001-<\/a><a href=\"https:\/\/orcid.org\/0000-0001-7523-2437\" target=\"_blank\" rel=\"noreferrer noopener\">7523<\/a><a href=\"https:\/\/orcid.org\/0000-0001-7523-2437\">-2437<\/a><\/strong><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column has-midnight-gradient-background has-background is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:3px\"><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading has-text-align-center\" style=\"font-size:20px\"><\/h2>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\" style=\"text-decoration:underline\"><\/p>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\"><\/div><\/div>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-group is-content-justification-center is-nowrap is-layout-flex wp-container-core-group-is-layout-d05cb3ef wp-block-group-is-layout-flex\"><\/div>\n<\/div><\/div>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\" style=\"font-size:13px\"><\/p>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Docentes da Linha 1 Andr\u00e9 Yves Cribb Permanente Lattes andre.cribb@embrapa.br ORCID:&nbsp;0000-0003-4243-394X Beatriz Villardi Permanente Lattes rbvillardi@hotmail.com ORCID:&nbsp;0000-0001-9541-1694 Biancca Scarpeline Permanente Lattes bianccastro2@gmail.com [&hellip;]<\/p>\n","protected":false},"author":121,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[1],"tags":[124],"class_list":["post-10990","post","type-post","status-publish","format-standard","hentry","category-sem-categoria","tag-corpo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Corpo Docente - Programa de P\u00f3s-gradua\u00e7\u00e3o em Gest\u00e3o e Estrat\u00e9gia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/corpodocentea\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Corpo Docente - Programa de P\u00f3s-gradua\u00e7\u00e3o em Gest\u00e3o e Estrat\u00e9gia\" \/>\n<meta property=\"og:description\" content=\"Docentes da Linha 1 Andr\u00e9 Yves Cribb Permanente Lattes andre.cribb@embrapa.br ORCID:&nbsp;0000-0003-4243-394X Beatriz Villardi Permanente Lattes rbvillardi@hotmail.com ORCID:&nbsp;0000-0001-9541-1694 Biancca Scarpeline Permanente Lattes bianccastro2@gmail.com [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/corpodocentea\/\" \/>\n<meta property=\"og:site_name\" content=\"Programa de P\u00f3s-gradua\u00e7\u00e3o em Gest\u00e3o e Estrat\u00e9gia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MestradoProfissionalEmGestaoeEstrategia\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-23T20:58:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-14T18:27:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rosamelo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"rosamelo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"33 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppge\\\/corpodocentea\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppge\\\/corpodocentea\\\/\"},\"author\":{\"name\":\"rosamelo\",\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppge\\\/#\\\/schema\\\/person\\\/1ebe486b3a994a3f43d2cf8345375b14\"},\"headline\":\"Corpo Docente\",\"datePublished\":\"2025-10-23T20:58:34+00:00\",\"dateModified\":\"2026-07-14T18:27:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppge\\\/corpodocentea\\\/\"},\"wordCount\":6018,\"image\":{\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppge\\\/corpodocentea\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppge\\\/files\\\/2025\\\/09\\\/Design-sem-nome-4-1024x1024.jpg\",\"keywords\":[\"corpo\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppge\\\/corpodocentea\\\/\",\"url\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppge\\\/corpodocentea\\\/\",\"name\":\"Corpo Docente - Programa de P\u00f3s-gradua\u00e7\u00e3o em Gest\u00e3o e Estrat\u00e9gia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppge\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppge\\\/corpodocentea\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppge\\\/corpodocentea\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppge\\\/files\\\/2025\\\/09\\\/Design-sem-nome-4-1024x1024.jpg\",\"datePublished\":\"2025-10-23T20:58:34+00:00\",\"dateModified\":\"2026-07-14T18:27:42+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppge\\\/#\\\/schema\\\/person\\\/1ebe486b3a994a3f43d2cf8345375b14\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppge\\\/corpodocentea\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppge\\\/corpodocentea\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppge\\\/corpodocentea\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppge\\\/files\\\/2025\\\/09\\\/Design-sem-nome-4.jpg\",\"contentUrl\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppge\\\/files\\\/2025\\\/09\\\/Design-sem-nome-4.jpg\",\"width\":1080,\"height\":1080,\"caption\":\"Andre Cribb\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppge\\\/corpodocentea\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppge\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Corpo Docente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppge\\\/#website\",\"url\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppge\\\/\",\"name\":\"Programa de P\u00f3s-gradua\u00e7\u00e3o em Gest\u00e3o e Estrat\u00e9gia\",\"description\":\"Universidade Federal Rural do Rio de Janeiro \u2013 UFRRJ\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppge\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppge\\\/#\\\/schema\\\/person\\\/1ebe486b3a994a3f43d2cf8345375b14\",\"name\":\"rosamelo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ebc86ad019748621346f154d9f93c7906fb1ba57b288a9f900ca0c21c661f6b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ebc86ad019748621346f154d9f93c7906fb1ba57b288a9f900ca0c21c661f6b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ebc86ad019748621346f154d9f93c7906fb1ba57b288a9f900ca0c21c661f6b?s=96&d=mm&r=g\",\"caption\":\"rosamelo\"},\"description\":\"Chamado - ID: 33276 (Rural - Seropedica)\",\"url\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppge\\\/author\\\/rosamelo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Corpo Docente - Programa de P\u00f3s-gradua\u00e7\u00e3o em Gest\u00e3o e Estrat\u00e9gia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/corpodocentea\/","og_locale":"pt_BR","og_type":"article","og_title":"Corpo Docente - Programa de P\u00f3s-gradua\u00e7\u00e3o em Gest\u00e3o e Estrat\u00e9gia","og_description":"Docentes da Linha 1 Andr\u00e9 Yves Cribb Permanente Lattes andre.cribb@embrapa.br ORCID:&nbsp;0000-0003-4243-394X Beatriz Villardi Permanente Lattes rbvillardi@hotmail.com ORCID:&nbsp;0000-0001-9541-1694 Biancca Scarpeline Permanente Lattes bianccastro2@gmail.com [&hellip;]","og_url":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/corpodocentea\/","og_site_name":"Programa de P\u00f3s-gradua\u00e7\u00e3o em Gest\u00e3o e Estrat\u00e9gia","article_publisher":"https:\/\/www.facebook.com\/MestradoProfissionalEmGestaoeEstrategia","article_published_time":"2025-10-23T20:58:34+00:00","article_modified_time":"2026-07-14T18:27:42+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-4.jpg","type":"image\/jpeg"}],"author":"rosamelo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"rosamelo","Est. tempo de leitura":"33 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/corpodocentea\/#article","isPartOf":{"@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/corpodocentea\/"},"author":{"name":"rosamelo","@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/#\/schema\/person\/1ebe486b3a994a3f43d2cf8345375b14"},"headline":"Corpo Docente","datePublished":"2025-10-23T20:58:34+00:00","dateModified":"2026-07-14T18:27:42+00:00","mainEntityOfPage":{"@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/corpodocentea\/"},"wordCount":6018,"image":{"@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/corpodocentea\/#primaryimage"},"thumbnailUrl":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-4-1024x1024.jpg","keywords":["corpo"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/corpodocentea\/","url":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/corpodocentea\/","name":"Corpo Docente - Programa de P\u00f3s-gradua\u00e7\u00e3o em Gest\u00e3o e Estrat\u00e9gia","isPartOf":{"@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/corpodocentea\/#primaryimage"},"image":{"@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/corpodocentea\/#primaryimage"},"thumbnailUrl":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-4-1024x1024.jpg","datePublished":"2025-10-23T20:58:34+00:00","dateModified":"2026-07-14T18:27:42+00:00","author":{"@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/#\/schema\/person\/1ebe486b3a994a3f43d2cf8345375b14"},"breadcrumb":{"@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/corpodocentea\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/corpodocentea\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/corpodocentea\/#primaryimage","url":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-4.jpg","contentUrl":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/files\/2025\/09\/Design-sem-nome-4.jpg","width":1080,"height":1080,"caption":"Andre Cribb"},{"@type":"BreadcrumbList","@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/corpodocentea\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/"},{"@type":"ListItem","position":2,"name":"Corpo Docente"}]},{"@type":"WebSite","@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/#website","url":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/","name":"Programa de P\u00f3s-gradua\u00e7\u00e3o em Gest\u00e3o e Estrat\u00e9gia","description":"Universidade Federal Rural do Rio de Janeiro \u2013 UFRRJ","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/#\/schema\/person\/1ebe486b3a994a3f43d2cf8345375b14","name":"rosamelo","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/2ebc86ad019748621346f154d9f93c7906fb1ba57b288a9f900ca0c21c661f6b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2ebc86ad019748621346f154d9f93c7906fb1ba57b288a9f900ca0c21c661f6b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2ebc86ad019748621346f154d9f93c7906fb1ba57b288a9f900ca0c21c661f6b?s=96&d=mm&r=g","caption":"rosamelo"},"description":"Chamado - ID: 33276 (Rural - Seropedica)","url":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/author\/rosamelo\/"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/wp-json\/wp\/v2\/posts\/10990","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/wp-json\/wp\/v2\/users\/121"}],"replies":[{"embeddable":true,"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/wp-json\/wp\/v2\/comments?post=10990"}],"version-history":[{"count":28,"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/wp-json\/wp\/v2\/posts\/10990\/revisions"}],"predecessor-version":[{"id":11881,"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/wp-json\/wp\/v2\/posts\/10990\/revisions\/11881"}],"wp:attachment":[{"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/wp-json\/wp\/v2\/media?parent=10990"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/wp-json\/wp\/v2\/categories?post=10990"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/wp-json\/wp\/v2\/tags?post=10990"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}