{"id":5113,"date":"2021-09-17T11:27:51","date_gmt":"2021-09-17T14:27:51","guid":{"rendered":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/?page_id=5113"},"modified":"2026-01-28T16:47:50","modified_gmt":"2026-01-28T19:47:50","slug":"apresentacao-2","status":"publish","type":"page","link":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/apresentacao-2\/","title":{"rendered":"Apresenta\u00e7\u00e3o"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>BEM-VINDO AO PROGRAMA DE MESTRADO PROFISSIONAL EM GEST\u00c3O E ESTRAT\u00c9GIA \u2013 PPGE\/UFRRJ!<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O PPGE atua na \u00c1REA DE CONCENTRA\u00c7\u00c3O denominada \u201cGEST\u00c3O E ESTRAT\u00c9GIA\u201d, desenvolvendo pesquisas e solu\u00e7\u00f5es sociot\u00e9cnicas transformadoras para organiza\u00e7\u00f5es de diferentes matrizes, beneficiando a sociedade como um todo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O programa tem um perfil dial\u00f3gico e participativo com a sociedade que resulta em uma atua\u00e7\u00e3o orientada para a melhoria da vida humana, por meio do impacto de seus produtos tecnol\u00f3gicos e, sobretudo, da qualifica\u00e7\u00e3o orientada para as trajet\u00f3rias profissionais de nossos egressos.&nbsp; O PPGE tem, como caracter\u00edstica, a capacidade de acionar redes complexas de sujeitos sociais em assimetria para o agir.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O PPGE se preocupa com a forma\u00e7\u00e3o de quadros preparados para a tomada de decis\u00e3o, e impulsiona a forma\u00e7\u00e3o te\u00f3rica discente, que se dividir\u00e1 em etapas, com objetivos espec\u00edficos, a saber: i) Fundamentos em Administra\u00e7\u00e3o,ii) M\u00e9todo e Forma\u00e7\u00e3o do Pesquisador, iii) Gest\u00e3o de Pessoas e de Recursos Organizacionais, iv) Estrat\u00e9gia em Organiza\u00e7\u00f5es e vi) componentes integradores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Com este itiner\u00e1rio pr\u00e1tico-te\u00f3rico, os alunos t\u00eam forma\u00e7\u00e3o de ponta, para a necess\u00e1ria vis\u00e3o cr\u00edtica e plasticidade mental que a pesquisa social aplicada em gest\u00e3o requer. Consequentemente, o egresso est\u00e1 apto a retornar para organiza\u00e7\u00f5es p\u00fablicas ou privadas em posi\u00e7\u00f5es de decis\u00e3o, ou prosseguir na carreira acad\u00eamica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O corpo docente do PPGE re\u00fane pesquisadores com perfil para atuar na modalidade profissional, e com reconhecimento em suas \u00e1reas de atua\u00e7\u00e3o. Seu perfil s\u00f3cio t\u00e9cnico orientado para a solu\u00e7\u00e3o de problemas organizacionais est\u00e1 organizado no ZENODO, um reposit\u00f3rio digital multidisciplinar de Acesso Aberto, para publicar e disseminar seus mais recentes ptts, todos com DOI e totalmente franqueados pelo selo Creative Commons.<\/p>\n\n\n\n<figure class=\"wp-block-embed\"><div class=\"wp-block-embed__wrapper\">\nhttps:\/\/zenodo.org\/communities\/ppge_ufrrj\/records?q=&#038;l=list&#038;p=1&#038;s=10&#038;sort=newest\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>INFORMA\u00c7\u00d5ES GERAIS<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>GEST\u00c3O DO PROGRAMA (2025 \u2013 atual)<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Coordenador:\u00a0 Prof. Daniel Ribeiro (e-mail: <a href=\"mailto:daniel.eco@uol.com.br\">daniel.eco@uol.com.br<\/a>).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vice-Coordenadora: Profa. Patr\u00edcia Leite (e-mail: <a href=\"mailto:flaviagalindo@ufrrj.br\">patricialeite@ufrrj.br<\/a>).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>SECRETARIA ACAD\u00caMICA DO MPGE e ATENDIMENTO AO P\u00daBLICO:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Email: <a href=\"mailto:secretariappge@ufrrj.br\">secretariappge@ufrrj.br<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tel: (21) 2681-4938<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Rodovia BR 465, km 7 \u2013 Serop\u00e9dica \u2013 RJ \u2013 CEP: 23.890-000<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>ADMINISTRA\u00c7\u00c3O COLEGIADA <\/strong><br>O Colegiado Pleno \u00e9 composto por:<br>I.Coordenador,<br>II. Vice-Coordenador,<br>III. Todos os docentes permanentes e colaboradores do programa,<br>IV. Servidores t\u00e9cnico-administrativo do Programa comp\u00f5em at\u00e9 10% do colegiado;<br>V. Representantes do corpo discente do Programa comp\u00f5em at\u00e9 20% do colegiado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O Colegiado Executivo \u00e9 composto por:<br>I. Coordenador,<br>II. Vice-Coordenador,<br>III. M\u00ednimo de 01 representante por linha de pesquisa;<br>IV. M\u00ednimo de 02 outros membros titulares do colegiado pleno, podendo ser servidor t\u00e9cnico administrativo, discente e\/ou docente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Hist\u00f3rico das Coordena\u00e7\u00f5es do MPGE&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Daniel Ribeiro &amp; Patr\u00edcia Leite (2025- atual)<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Flavia Galindo &amp; Daniel Ribeiro (2018-2025)<\/li>\n\n\n\n<li>Beatriz Villardi &amp; Flavia Galindo (2015-2017)<\/li>\n\n\n\n<li>Beatriz Villardi &amp; Gustavo Olivares (2013-2014)<\/li>\n\n\n\n<li>Heloisa Nogueira &amp; Beatriz Villardi (2011-2013)<\/li>\n\n\n\n<li>Heloisa Nogueira &amp; Marcelo Alvaro (2009-2010)<\/li>\n\n\n\n<li>Analice Vilas Boas &amp; Heloisa Nogueira (2006-2008)<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>BEM-VINDO AO PROGRAMA DE MESTRADO PROFISSIONAL EM GEST\u00c3O E ESTRAT\u00c9GIA \u2013 PPGE\/UFRRJ! O PPGE atua na \u00c1REA DE CONCENTRA\u00c7\u00c3O denominada \u201cGEST\u00c3O E [&hellip;]<\/p>\n","protected":false},"author":99,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":"","_links_to":"","_links_to_target":""},"class_list":["post-5113","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Apresenta\u00e7\u00e3o - Programa de P\u00f3s-gradua\u00e7\u00e3o em Gest\u00e3o e Estrat\u00e9gia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/apresentacao-2\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Apresenta\u00e7\u00e3o - Programa de P\u00f3s-gradua\u00e7\u00e3o em Gest\u00e3o e Estrat\u00e9gia\" \/>\n<meta property=\"og:description\" content=\"BEM-VINDO AO PROGRAMA DE MESTRADO PROFISSIONAL EM GEST\u00c3O E ESTRAT\u00c9GIA \u2013 PPGE\/UFRRJ! O PPGE atua na \u00c1REA DE CONCENTRA\u00c7\u00c3O denominada \u201cGEST\u00c3O E [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/apresentacao-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Programa de P\u00f3s-gradua\u00e7\u00e3o em Gest\u00e3o e Estrat\u00e9gia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MestradoProfissionalEmGestaoeEstrategia\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-28T19:47:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppge\\\/apresentacao-2\\\/\",\"url\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppge\\\/apresentacao-2\\\/\",\"name\":\"Apresenta\u00e7\u00e3o - Programa de P\u00f3s-gradua\u00e7\u00e3o em Gest\u00e3o e Estrat\u00e9gia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppge\\\/#website\"},\"datePublished\":\"2021-09-17T14:27:51+00:00\",\"dateModified\":\"2026-01-28T19:47:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppge\\\/apresentacao-2\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppge\\\/apresentacao-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppge\\\/apresentacao-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppge\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Apresenta\u00e7\u00e3o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppge\\\/#website\",\"url\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppge\\\/\",\"name\":\"Programa de P\u00f3s-gradua\u00e7\u00e3o em Gest\u00e3o e Estrat\u00e9gia\",\"description\":\"Universidade Federal Rural do Rio de Janeiro \u2013 UFRRJ\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppge\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Apresenta\u00e7\u00e3o - Programa de P\u00f3s-gradua\u00e7\u00e3o em Gest\u00e3o e Estrat\u00e9gia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/apresentacao-2\/","og_locale":"pt_BR","og_type":"article","og_title":"Apresenta\u00e7\u00e3o - Programa de P\u00f3s-gradua\u00e7\u00e3o em Gest\u00e3o e Estrat\u00e9gia","og_description":"BEM-VINDO AO PROGRAMA DE MESTRADO PROFISSIONAL EM GEST\u00c3O E ESTRAT\u00c9GIA \u2013 PPGE\/UFRRJ! O PPGE atua na \u00c1REA DE CONCENTRA\u00c7\u00c3O denominada \u201cGEST\u00c3O E [&hellip;]","og_url":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/apresentacao-2\/","og_site_name":"Programa de P\u00f3s-gradua\u00e7\u00e3o em Gest\u00e3o e Estrat\u00e9gia","article_publisher":"https:\/\/www.facebook.com\/MestradoProfissionalEmGestaoeEstrategia","article_modified_time":"2026-01-28T19:47:50+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/apresentacao-2\/","url":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/apresentacao-2\/","name":"Apresenta\u00e7\u00e3o - Programa de P\u00f3s-gradua\u00e7\u00e3o em Gest\u00e3o e Estrat\u00e9gia","isPartOf":{"@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/#website"},"datePublished":"2021-09-17T14:27:51+00:00","dateModified":"2026-01-28T19:47:50+00:00","breadcrumb":{"@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/apresentacao-2\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/apresentacao-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/apresentacao-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/"},{"@type":"ListItem","position":2,"name":"Apresenta\u00e7\u00e3o"}]},{"@type":"WebSite","@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/#website","url":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/","name":"Programa de P\u00f3s-gradua\u00e7\u00e3o em Gest\u00e3o e Estrat\u00e9gia","description":"Universidade Federal Rural do Rio de Janeiro \u2013 UFRRJ","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/wp-json\/wp\/v2\/pages\/5113","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/wp-json\/wp\/v2\/users\/99"}],"replies":[{"embeddable":true,"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/wp-json\/wp\/v2\/comments?post=5113"}],"version-history":[{"count":13,"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/wp-json\/wp\/v2\/pages\/5113\/revisions"}],"predecessor-version":[{"id":11370,"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/wp-json\/wp\/v2\/pages\/5113\/revisions\/11370"}],"wp:attachment":[{"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppge\/wp-json\/wp\/v2\/media?parent=5113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}