{"id":16467,"date":"2026-06-26T20:15:48","date_gmt":"2026-06-26T23:15:48","guid":{"rendered":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgd\/?page_id=16467"},"modified":"2026-06-26T20:43:25","modified_gmt":"2026-06-26T23:43:25","slug":"portal-de-periodicos-da-capes-2","status":"publish","type":"page","link":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgd\/es\/portal-de-periodicos-da-capes-2\/","title":{"rendered":"Portal de Peri\u00f3dicos da CAPES"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El Portal reune contenido cient\u00edfico de alta calidad y tiene el objetivo de ponerlo a disposici\u00f3n de la comunidad acad\u00e9mica brasile\u00f1a. De este modo, el <strong>Portal de Peri\u00f3dicos da CAPES<\/strong> tiene el objetivo de reducir las asimetr\u00edas regionales en el acceso a la informaci\u00f3n cient\u00edfica, cubriendo todo el territorio nacional. Es considerado una iniciativa \u00fanica en el mundo, ya que un gran n\u00famero de instituciones accede al acervo, el cual est\u00e1 enteramente financiado por el Gobierno Federal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El <strong>Portal de Peri\u00f3dicos da CAPES<\/strong> propicia el desarrollo tecnol\u00f3gico y la innovaci\u00f3n en el pa\u00eds al contribuir al crecimiento de la producci\u00f3n cient\u00edfica nacional y a la inserci\u00f3n, cada vez mayor, de la ciencia brasile\u00f1a en el exterior.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En este sentido, cabe resaltar que la Universidad Federal Rural de R\u00edo de Janeiro es una instituci\u00f3n con convenio y sus docentes y discentes poseen acceso completo al <strong>Portal de Peri\u00f3dicos da CAPES<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El <strong>Portal de Peri\u00f3dicos da CAPES<\/strong> permite el acceso de los investigadores a agregadores y a diversas plataformas internacionales como, por ejemplo, JSTOR, JCR, EBSCO, entre otras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Acceda al sitio web del Portal de Peri\u00f3dicos a continuaci\u00f3n: <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.periodicos.capes.gov.br\">https:\/\/www.periodicos.capes.gov.br<\/a><\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><a href=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgd\/files\/2026\/06\/logo_periodicos_simples-a.png\"><img decoding=\"async\" width=\"1024\" height=\"173\" src=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgd\/files\/2026\/06\/logo_periodicos_simples-a-1024x173.png\" alt=\"\" class=\"wp-image-16461\" style=\"aspect-ratio:5.919594924353343;width:359px;height:auto\" srcset=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgd\/files\/2026\/06\/logo_periodicos_simples-a-1024x173.png 1024w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgd\/files\/2026\/06\/logo_periodicos_simples-a-300x51.png 300w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgd\/files\/2026\/06\/logo_periodicos_simples-a-768x129.png 768w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgd\/files\/2026\/06\/logo_periodicos_simples-a-1536x259.png 1536w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgd\/files\/2026\/06\/logo_periodicos_simples-a-415x70.png 415w, https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgd\/files\/2026\/06\/logo_periodicos_simples-a.png 2000w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Portal reune contenido cient\u00edfico de alta calidad y tiene el objetivo de ponerlo a disposici\u00f3n de la comunidad acad\u00e9mica brasile\u00f1a. De [&hellip;]<\/p>\n","protected":false},"author":162,"featured_media":16461,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-16467","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Portal de Peri\u00f3dicos da CAPES - Programa de P\u00f3s-Gradua\u00e7\u00e3o em Direito, Ambiente e Desenvolvimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgd\/es\/portal-de-periodicos-da-capes-2\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Portal de Peri\u00f3dicos da CAPES - Programa de P\u00f3s-Gradua\u00e7\u00e3o em Direito, Ambiente e Desenvolvimento\" \/>\n<meta property=\"og:description\" content=\"El Portal reune contenido cient\u00edfico de alta calidad y tiene el objetivo de ponerlo a disposici\u00f3n de la comunidad acad\u00e9mica brasile\u00f1a. De [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgd\/es\/portal-de-periodicos-da-capes-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Programa de P\u00f3s-Gradua\u00e7\u00e3o em Direito, Ambiente e Desenvolvimento\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-26T23:43:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgd\/files\/2026\/06\/logo_periodicos_simples-a.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"337\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgd\\\/es\\\/portal-de-periodicos-da-capes-2\\\/\",\"url\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgd\\\/es\\\/portal-de-periodicos-da-capes-2\\\/\",\"name\":\"Portal de Peri\u00f3dicos da CAPES - Programa de P\u00f3s-Gradua\u00e7\u00e3o em Direito, Ambiente e Desenvolvimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgd\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgd\\\/es\\\/portal-de-periodicos-da-capes-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgd\\\/es\\\/portal-de-periodicos-da-capes-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgd\\\/files\\\/2026\\\/06\\\/logo_periodicos_simples-a.png\",\"datePublished\":\"2026-06-26T23:15:48+00:00\",\"dateModified\":\"2026-06-26T23:43:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgd\\\/es\\\/portal-de-periodicos-da-capes-2\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgd\\\/es\\\/portal-de-periodicos-da-capes-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgd\\\/es\\\/portal-de-periodicos-da-capes-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgd\\\/files\\\/2026\\\/06\\\/logo_periodicos_simples-a.png\",\"contentUrl\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgd\\\/files\\\/2026\\\/06\\\/logo_periodicos_simples-a.png\",\"width\":2000,\"height\":337},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgd\\\/es\\\/portal-de-periodicos-da-capes-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgd\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Portal de Peri\u00f3dicos da CAPES\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgd\\\/#website\",\"url\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgd\\\/\",\"name\":\"PPGD\",\"description\":\"Programa de P\u00f3s-Gradua\u00e7\u00e3o em Hist\u00f3ria\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgd\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Portal de Peri\u00f3dicos da CAPES - Programa de P\u00f3s-Gradua\u00e7\u00e3o em Direito, Ambiente e Desenvolvimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgd\/es\/portal-de-periodicos-da-capes-2\/","og_locale":"pt_BR","og_type":"article","og_title":"Portal de Peri\u00f3dicos da CAPES - Programa de P\u00f3s-Gradua\u00e7\u00e3o em Direito, Ambiente e Desenvolvimento","og_description":"El Portal reune contenido cient\u00edfico de alta calidad y tiene el objetivo de ponerlo a disposici\u00f3n de la comunidad acad\u00e9mica brasile\u00f1a. De [&hellip;]","og_url":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgd\/es\/portal-de-periodicos-da-capes-2\/","og_site_name":"Programa de P\u00f3s-Gradua\u00e7\u00e3o em Direito, Ambiente e Desenvolvimento","article_modified_time":"2026-06-26T23:43:25+00:00","og_image":[{"width":2000,"height":337,"url":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgd\/files\/2026\/06\/logo_periodicos_simples-a.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgd\/es\/portal-de-periodicos-da-capes-2\/","url":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgd\/es\/portal-de-periodicos-da-capes-2\/","name":"Portal de Peri\u00f3dicos da CAPES - Programa de P\u00f3s-Gradua\u00e7\u00e3o em Direito, Ambiente e Desenvolvimento","isPartOf":{"@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgd\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgd\/es\/portal-de-periodicos-da-capes-2\/#primaryimage"},"image":{"@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgd\/es\/portal-de-periodicos-da-capes-2\/#primaryimage"},"thumbnailUrl":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgd\/files\/2026\/06\/logo_periodicos_simples-a.png","datePublished":"2026-06-26T23:15:48+00:00","dateModified":"2026-06-26T23:43:25+00:00","breadcrumb":{"@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgd\/es\/portal-de-periodicos-da-capes-2\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgd\/es\/portal-de-periodicos-da-capes-2\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgd\/es\/portal-de-periodicos-da-capes-2\/#primaryimage","url":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgd\/files\/2026\/06\/logo_periodicos_simples-a.png","contentUrl":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgd\/files\/2026\/06\/logo_periodicos_simples-a.png","width":2000,"height":337},{"@type":"BreadcrumbList","@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgd\/es\/portal-de-periodicos-da-capes-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgd\/"},{"@type":"ListItem","position":2,"name":"Portal de Peri\u00f3dicos da CAPES"}]},{"@type":"WebSite","@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgd\/#website","url":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgd\/","name":"PPGD","description":"Programa de P\u00f3s-Gradua\u00e7\u00e3o em Hist\u00f3ria","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgd\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgd\/wp-json\/wp\/v2\/pages\/16467","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgd\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgd\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgd\/wp-json\/wp\/v2\/users\/162"}],"replies":[{"embeddable":true,"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgd\/wp-json\/wp\/v2\/comments?post=16467"}],"version-history":[{"count":2,"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgd\/wp-json\/wp\/v2\/pages\/16467\/revisions"}],"predecessor-version":[{"id":16470,"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgd\/wp-json\/wp\/v2\/pages\/16467\/revisions\/16470"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgd\/wp-json\/wp\/v2\/media\/16461"}],"wp:attachment":[{"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgd\/wp-json\/wp\/v2\/media?parent=16467"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}