{"id":16192,"date":"2026-05-23T15:52:12","date_gmt":"2026-05-23T18:52:12","guid":{"rendered":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgd\/?page_id=16192"},"modified":"2026-05-23T15:52:12","modified_gmt":"2026-05-23T18:52:12","slug":"calendario","status":"publish","type":"page","link":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgd\/calendario\/","title":{"rendered":"Calend\u00e1rio"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2026.2 (Vigente)<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td><strong>15\/09\/2026 \u00e0 17\/09\/2026<\/strong><br>\u2192&nbsp;Matr\u00edcula para o per\u00edodo 2026.2.<\/td><\/tr><tr><td><strong>15\/09\/2026 \u00e0 17\/09\/2026<\/strong><br>\u2192&nbsp;Re-matr\u00edcula para o per\u00edodo 2026.2.<\/td><\/tr><tr><td><strong>21\/09\/2026<\/strong><br>\u2192&nbsp;In\u00edcio do per\u00edodo letivo 2026.2.<\/td><\/tr><tr><td><strong>27\/09\/2026<\/strong><br>\u2192&nbsp;In\u00edcio do per\u00edodo trancamento de turma 2026.2.<\/td><\/tr><tr><td><strong>09\/10\/2026<\/strong><br>\u2192&nbsp;T\u00e9rmino do per\u00edodo trancamento de turma 2026.2.<\/td><\/tr><tr><td><strong>22\/12\/2026<\/strong><br>\u2192&nbsp;T\u00e9rmino do per\u00edodo letivo 2026.2.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">2027.1<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td><strong>20\/01\/2027 &#8211; 31\/01\/2027<\/strong><br>\u2192&nbsp;Matr\u00edcula para o per\u00edodo 2027.1.<\/td><\/tr><tr><td><strong>02\/03\/2027 &#8211; 05\/03\/2027<\/strong><br>\u2192&nbsp;Re-matr\u00edcula para o per\u00edodo 2027.1.<\/td><\/tr><tr><td><strong>15\/03\/2027<\/strong><br>\u2192&nbsp;In\u00edcio do per\u00edodo letivo 2027.1.<\/td><\/tr><tr><td><strong>11\/06\/2027<\/strong><br>\u2192&nbsp;T\u00e9rmino do per\u00edodo letivo 2027.1.<\/td><\/tr><\/tbody><\/table><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>2026.2 (Vigente) 15\/09\/2026 \u00e0 17\/09\/2026\u2192&nbsp;Matr\u00edcula para o per\u00edodo 2026.2. 15\/09\/2026 \u00e0 17\/09\/2026\u2192&nbsp;Re-matr\u00edcula para o per\u00edodo 2026.2. 21\/09\/2026\u2192&nbsp;In\u00edcio do per\u00edodo letivo 2026.2. 27\/09\/2026\u2192&nbsp;In\u00edcio [&hellip;]<\/p>\n","protected":false},"author":162,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-16192","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Calend\u00e1rio - Programa de P\u00f3s-Gradua\u00e7\u00e3o em Direito, Ambiente e Desenvolvimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgd\/calendario\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Calend\u00e1rio - Programa de P\u00f3s-Gradua\u00e7\u00e3o em Direito, Ambiente e Desenvolvimento\" \/>\n<meta property=\"og:description\" content=\"2026.2 (Vigente) 15\/09\/2026 \u00e0 17\/09\/2026\u2192&nbsp;Matr\u00edcula para o per\u00edodo 2026.2. 15\/09\/2026 \u00e0 17\/09\/2026\u2192&nbsp;Re-matr\u00edcula para o per\u00edodo 2026.2. 21\/09\/2026\u2192&nbsp;In\u00edcio do per\u00edodo letivo 2026.2. 27\/09\/2026\u2192&nbsp;In\u00edcio [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgd\/calendario\/\" \/>\n<meta property=\"og:site_name\" content=\"Programa de P\u00f3s-Gradua\u00e7\u00e3o em Direito, Ambiente e Desenvolvimento\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgd\\\/calendario\\\/\",\"url\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgd\\\/calendario\\\/\",\"name\":\"Calend\u00e1rio - Programa de P\u00f3s-Gradua\u00e7\u00e3o em Direito, Ambiente e Desenvolvimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgd\\\/#website\"},\"datePublished\":\"2026-05-23T18:52:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgd\\\/calendario\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgd\\\/calendario\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgd\\\/calendario\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgd\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Calend\u00e1rio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgd\\\/#website\",\"url\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgd\\\/\",\"name\":\"PPGD\",\"description\":\"Programa de P\u00f3s-Gradua\u00e7\u00e3o em Hist\u00f3ria\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/ppgd\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Calend\u00e1rio - Programa de P\u00f3s-Gradua\u00e7\u00e3o em Direito, Ambiente e Desenvolvimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgd\/calendario\/","og_locale":"pt_BR","og_type":"article","og_title":"Calend\u00e1rio - Programa de P\u00f3s-Gradua\u00e7\u00e3o em Direito, Ambiente e Desenvolvimento","og_description":"2026.2 (Vigente) 15\/09\/2026 \u00e0 17\/09\/2026\u2192&nbsp;Matr\u00edcula para o per\u00edodo 2026.2. 15\/09\/2026 \u00e0 17\/09\/2026\u2192&nbsp;Re-matr\u00edcula para o per\u00edodo 2026.2. 21\/09\/2026\u2192&nbsp;In\u00edcio do per\u00edodo letivo 2026.2. 27\/09\/2026\u2192&nbsp;In\u00edcio [&hellip;]","og_url":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgd\/calendario\/","og_site_name":"Programa de P\u00f3s-Gradua\u00e7\u00e3o em Direito, Ambiente e Desenvolvimento","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgd\/calendario\/","url":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgd\/calendario\/","name":"Calend\u00e1rio - Programa de P\u00f3s-Gradua\u00e7\u00e3o em Direito, Ambiente e Desenvolvimento","isPartOf":{"@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgd\/#website"},"datePublished":"2026-05-23T18:52:12+00:00","breadcrumb":{"@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgd\/calendario\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgd\/calendario\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgd\/calendario\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgd\/"},{"@type":"ListItem","position":2,"name":"Calend\u00e1rio"}]},{"@type":"WebSite","@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgd\/#website","url":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgd\/","name":"PPGD","description":"Programa de P\u00f3s-Gradua\u00e7\u00e3o em Hist\u00f3ria","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgd\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgd\/wp-json\/wp\/v2\/pages\/16192","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgd\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgd\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgd\/wp-json\/wp\/v2\/users\/162"}],"replies":[{"embeddable":true,"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgd\/wp-json\/wp\/v2\/comments?post=16192"}],"version-history":[{"count":1,"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgd\/wp-json\/wp\/v2\/pages\/16192\/revisions"}],"predecessor-version":[{"id":16194,"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgd\/wp-json\/wp\/v2\/pages\/16192\/revisions\/16194"}],"wp:attachment":[{"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/ppgd\/wp-json\/wp\/v2\/media?parent=16192"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}