{"id":6677,"date":"2026-08-10T10:04:46","date_gmt":"2026-08-10T13:04:46","guid":{"rendered":"https:\/\/cursos.ufrrj.br\/posgraduacao\/cpgacs\/?p=6677"},"modified":"2026-08-10T10:06:25","modified_gmt":"2026-08-10T13:06:25","slug":"resultado-proficiencia-em-lingua-estrangeira","status":"publish","type":"post","link":"https:\/\/cursos.ufrrj.br\/posgraduacao\/cpgacs\/resultado-proficiencia-em-lingua-estrangeira\/","title":{"rendered":"Resultado Profici\u00eancia em L\u00edngua Estrangeira"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Divulgado o Resultado do exame de profici\u00eancia em l\u00edngua estrangeira &#8211; ingl\u00eas &#8211; para o processo seletivo de Mestrado. Confira nas abas Processo Seletivo &#8211; Resultado Parcial ou clicando direto <a href=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/cpgacs\/bolsas-de-estudo\/\" target=\"_blank\" rel=\"noreferrer noopener\">aqui<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Divulgado o Resultado do exame de profici\u00eancia em l\u00edngua estrangeira &#8211; ingl\u00eas &#8211; para o processo seletivo de Mestrado. Confira nas abas [&hellip;]<\/p>\n","protected":false},"author":112,"featured_media":4056,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[25],"tags":[],"class_list":["post-6677","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Resultado Profici\u00eancia em L\u00edngua Estrangeira - Programa de P\u00f3s-gradua\u00e7\u00e3o em Agronomia - Ci\u00eancia do Solo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/cpgacs\/resultado-proficiencia-em-lingua-estrangeira\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Resultado Profici\u00eancia em L\u00edngua Estrangeira - Programa de P\u00f3s-gradua\u00e7\u00e3o em Agronomia - Ci\u00eancia do Solo\" \/>\n<meta property=\"og:description\" content=\"Divulgado o Resultado do exame de profici\u00eancia em l\u00edngua estrangeira &#8211; ingl\u00eas &#8211; para o processo seletivo de Mestrado. Confira nas abas [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/cpgacs\/resultado-proficiencia-em-lingua-estrangeira\/\" \/>\n<meta property=\"og:site_name\" content=\"Programa de P\u00f3s-gradua\u00e7\u00e3o em Agronomia - Ci\u00eancia do Solo\" \/>\n<meta property=\"article:published_time\" content=\"2026-08-10T13:04:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-10T13:06:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/cpgacs\/files\/2021\/03\/checklist.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1052\" \/>\n\t<meta property=\"og:image:height\" content=\"696\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"leandrosantos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"leandrosantos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/cpgacs\\\/resultado-proficiencia-em-lingua-estrangeira\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/cpgacs\\\/resultado-proficiencia-em-lingua-estrangeira\\\/\"},\"author\":{\"name\":\"leandrosantos\",\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/cpgacs\\\/#\\\/schema\\\/person\\\/964161dd272fa5987ef0d1e390ae4f67\"},\"headline\":\"Resultado Profici\u00eancia em L\u00edngua Estrangeira\",\"datePublished\":\"2026-08-10T13:04:46+00:00\",\"dateModified\":\"2026-08-10T13:06:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/cpgacs\\\/resultado-proficiencia-em-lingua-estrangeira\\\/\"},\"wordCount\":41,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/cpgacs\\\/resultado-proficiencia-em-lingua-estrangeira\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/cpgacs\\\/files\\\/2021\\\/03\\\/checklist.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/cpgacs\\\/resultado-proficiencia-em-lingua-estrangeira\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/cpgacs\\\/resultado-proficiencia-em-lingua-estrangeira\\\/\",\"url\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/cpgacs\\\/resultado-proficiencia-em-lingua-estrangeira\\\/\",\"name\":\"Resultado Profici\u00eancia em L\u00edngua Estrangeira - Programa de P\u00f3s-gradua\u00e7\u00e3o em Agronomia - Ci\u00eancia do Solo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/cpgacs\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/cpgacs\\\/resultado-proficiencia-em-lingua-estrangeira\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/cpgacs\\\/resultado-proficiencia-em-lingua-estrangeira\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/cpgacs\\\/files\\\/2021\\\/03\\\/checklist.jpg\",\"datePublished\":\"2026-08-10T13:04:46+00:00\",\"dateModified\":\"2026-08-10T13:06:25+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/cpgacs\\\/#\\\/schema\\\/person\\\/964161dd272fa5987ef0d1e390ae4f67\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/cpgacs\\\/resultado-proficiencia-em-lingua-estrangeira\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/cpgacs\\\/resultado-proficiencia-em-lingua-estrangeira\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/cpgacs\\\/resultado-proficiencia-em-lingua-estrangeira\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/cpgacs\\\/files\\\/2021\\\/03\\\/checklist.jpg\",\"contentUrl\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/cpgacs\\\/files\\\/2021\\\/03\\\/checklist.jpg\",\"width\":1052,\"height\":696},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/cpgacs\\\/resultado-proficiencia-em-lingua-estrangeira\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/cpgacs\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Resultado Profici\u00eancia em L\u00edngua Estrangeira\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/cpgacs\\\/#website\",\"url\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/cpgacs\\\/\",\"name\":\"Programa de P\u00f3s-gradua\u00e7\u00e3o em Agronomia - Ci\u00eancia do Solo\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/cpgacs\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/cpgacs\\\/#\\\/schema\\\/person\\\/964161dd272fa5987ef0d1e390ae4f67\",\"name\":\"leandrosantos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff977e68fd712d26fb4009460a082aaaa3a9d2e473f85031bbfabe1364c1d8a7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff977e68fd712d26fb4009460a082aaaa3a9d2e473f85031bbfabe1364c1d8a7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff977e68fd712d26fb4009460a082aaaa3a9d2e473f85031bbfabe1364c1d8a7?s=96&d=mm&r=g\",\"caption\":\"leandrosantos\"},\"description\":\"Chamado - ID: 30996 (Rural - Seropedica)\",\"url\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/cpgacs\\\/author\\\/leandrosantos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Resultado Profici\u00eancia em L\u00edngua Estrangeira - Programa de P\u00f3s-gradua\u00e7\u00e3o em Agronomia - Ci\u00eancia do Solo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cursos.ufrrj.br\/posgraduacao\/cpgacs\/resultado-proficiencia-em-lingua-estrangeira\/","og_locale":"pt_BR","og_type":"article","og_title":"Resultado Profici\u00eancia em L\u00edngua Estrangeira - Programa de P\u00f3s-gradua\u00e7\u00e3o em Agronomia - Ci\u00eancia do Solo","og_description":"Divulgado o Resultado do exame de profici\u00eancia em l\u00edngua estrangeira &#8211; ingl\u00eas &#8211; para o processo seletivo de Mestrado. Confira nas abas [&hellip;]","og_url":"https:\/\/cursos.ufrrj.br\/posgraduacao\/cpgacs\/resultado-proficiencia-em-lingua-estrangeira\/","og_site_name":"Programa de P\u00f3s-gradua\u00e7\u00e3o em Agronomia - Ci\u00eancia do Solo","article_published_time":"2026-08-10T13:04:46+00:00","article_modified_time":"2026-08-10T13:06:25+00:00","og_image":[{"width":1052,"height":696,"url":"https:\/\/cursos.ufrrj.br\/posgraduacao\/cpgacs\/files\/2021\/03\/checklist.jpg","type":"image\/jpeg"}],"author":"leandrosantos","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"leandrosantos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/cpgacs\/resultado-proficiencia-em-lingua-estrangeira\/#article","isPartOf":{"@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/cpgacs\/resultado-proficiencia-em-lingua-estrangeira\/"},"author":{"name":"leandrosantos","@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/cpgacs\/#\/schema\/person\/964161dd272fa5987ef0d1e390ae4f67"},"headline":"Resultado Profici\u00eancia em L\u00edngua Estrangeira","datePublished":"2026-08-10T13:04:46+00:00","dateModified":"2026-08-10T13:06:25+00:00","mainEntityOfPage":{"@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/cpgacs\/resultado-proficiencia-em-lingua-estrangeira\/"},"wordCount":41,"commentCount":0,"image":{"@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/cpgacs\/resultado-proficiencia-em-lingua-estrangeira\/#primaryimage"},"thumbnailUrl":"https:\/\/cursos.ufrrj.br\/posgraduacao\/cpgacs\/files\/2021\/03\/checklist.jpg","articleSection":["Noticias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cursos.ufrrj.br\/posgraduacao\/cpgacs\/resultado-proficiencia-em-lingua-estrangeira\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/cpgacs\/resultado-proficiencia-em-lingua-estrangeira\/","url":"https:\/\/cursos.ufrrj.br\/posgraduacao\/cpgacs\/resultado-proficiencia-em-lingua-estrangeira\/","name":"Resultado Profici\u00eancia em L\u00edngua Estrangeira - Programa de P\u00f3s-gradua\u00e7\u00e3o em Agronomia - Ci\u00eancia do Solo","isPartOf":{"@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/cpgacs\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/cpgacs\/resultado-proficiencia-em-lingua-estrangeira\/#primaryimage"},"image":{"@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/cpgacs\/resultado-proficiencia-em-lingua-estrangeira\/#primaryimage"},"thumbnailUrl":"https:\/\/cursos.ufrrj.br\/posgraduacao\/cpgacs\/files\/2021\/03\/checklist.jpg","datePublished":"2026-08-10T13:04:46+00:00","dateModified":"2026-08-10T13:06:25+00:00","author":{"@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/cpgacs\/#\/schema\/person\/964161dd272fa5987ef0d1e390ae4f67"},"breadcrumb":{"@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/cpgacs\/resultado-proficiencia-em-lingua-estrangeira\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cursos.ufrrj.br\/posgraduacao\/cpgacs\/resultado-proficiencia-em-lingua-estrangeira\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/cpgacs\/resultado-proficiencia-em-lingua-estrangeira\/#primaryimage","url":"https:\/\/cursos.ufrrj.br\/posgraduacao\/cpgacs\/files\/2021\/03\/checklist.jpg","contentUrl":"https:\/\/cursos.ufrrj.br\/posgraduacao\/cpgacs\/files\/2021\/03\/checklist.jpg","width":1052,"height":696},{"@type":"BreadcrumbList","@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/cpgacs\/resultado-proficiencia-em-lingua-estrangeira\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/cursos.ufrrj.br\/posgraduacao\/cpgacs\/"},{"@type":"ListItem","position":2,"name":"Resultado Profici\u00eancia em L\u00edngua Estrangeira"}]},{"@type":"WebSite","@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/cpgacs\/#website","url":"https:\/\/cursos.ufrrj.br\/posgraduacao\/cpgacs\/","name":"Programa de P\u00f3s-gradua\u00e7\u00e3o em Agronomia - Ci\u00eancia do Solo","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cursos.ufrrj.br\/posgraduacao\/cpgacs\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/cpgacs\/#\/schema\/person\/964161dd272fa5987ef0d1e390ae4f67","name":"leandrosantos","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/ff977e68fd712d26fb4009460a082aaaa3a9d2e473f85031bbfabe1364c1d8a7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ff977e68fd712d26fb4009460a082aaaa3a9d2e473f85031bbfabe1364c1d8a7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ff977e68fd712d26fb4009460a082aaaa3a9d2e473f85031bbfabe1364c1d8a7?s=96&d=mm&r=g","caption":"leandrosantos"},"description":"Chamado - ID: 30996 (Rural - Seropedica)","url":"https:\/\/cursos.ufrrj.br\/posgraduacao\/cpgacs\/author\/leandrosantos\/"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/cpgacs\/wp-json\/wp\/v2\/posts\/6677","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/cpgacs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/cpgacs\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/cpgacs\/wp-json\/wp\/v2\/users\/112"}],"replies":[{"embeddable":true,"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/cpgacs\/wp-json\/wp\/v2\/comments?post=6677"}],"version-history":[{"count":2,"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/cpgacs\/wp-json\/wp\/v2\/posts\/6677\/revisions"}],"predecessor-version":[{"id":6679,"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/cpgacs\/wp-json\/wp\/v2\/posts\/6677\/revisions\/6679"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/cpgacs\/wp-json\/wp\/v2\/media\/4056"}],"wp:attachment":[{"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/cpgacs\/wp-json\/wp\/v2\/media?parent=6677"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/cpgacs\/wp-json\/wp\/v2\/categories?post=6677"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/cpgacs\/wp-json\/wp\/v2\/tags?post=6677"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}