{"id":4941,"date":"2022-10-31T10:12:20","date_gmt":"2022-10-31T13:12:20","guid":{"rendered":"https:\/\/cursos.ufrrj.br\/posgraduacao\/cpgacs\/?page_id=4941"},"modified":"2022-10-31T10:12:21","modified_gmt":"2022-10-31T13:12:21","slug":"infraestructura","status":"publish","type":"page","link":"https:\/\/cursos.ufrrj.br\/posgraduacao\/cpgacs\/es\/infraestructura\/","title":{"rendered":"Infraestructura"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Para atender a los docentes, el Departamento de Suelo cuenta en su estructura con 15 oficinas para los docentes, 25 computadoras y 18 impresoras. Adem\u00e1s se cuenta con una estructura com\u00fan y\/o de uso administrativo consistente en: 3 secretarias, 1 oficina para la coordinaci\u00f3n del curso, 2 oficinas de inform\u00e1tica y 1 biblioteca sectorial pertenecientes al CPGA-CS.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Departamento de Suelos cuenta con: 5 aulas con capacidad para dar atenci\u00f3n a 280 estudiantes, 26 espacios destinados a la investigaci\u00f3n (laboratorios, estufas, oficinas y otros), con computadoras localizadas en estos locales y capacidad para atender a 330 estudiantes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>BIBLIOTECA&nbsp; SECTORIAL<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la biblioteca sectorial del CPGA-CS se encuentran disponibles las disertaciones y tesis producidas por el programa, as\u00ed como libros y publicaciones donadas o adquiridas por el Departamento de Suelo donde adem\u00e1s se instituye como un espacio adicional de estudio disponible a los alumnos del curso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>SECRETARIA&nbsp; ACAD\u00c9MICA<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La secretaria acad\u00e9mica del CPGA-CS est\u00e1 formada por t\u00e9cnicos que son&nbsp; responsables por el control acad\u00e9mico y que realizan funciones tales como: matr\u00edculas, procesos de selecci\u00f3n y control de notas. Adem\u00e1s de emitir documentos, atestados y ofrecer auxilio e informaciones a los estudiantes. La secretaria se encuentra en constante optimizaci\u00f3n de los recursos inform\u00e1ticos que garantizan la actualizaci\u00f3n de equipamientos y programas. De esta forma, se mantienen todas las disertaciones&nbsp; y tesis del programa disponibles integralmente, &nbsp;en medio digital, en plataformas multimedias \u201cQuiosque digital\u201d y en red con el departamento de suelo. Otros servicios de inter\u00e9s acad\u00e9micos se mantienen disponibles de esta forma como por ejemplo el programa de control acad\u00e9mico donde el estudiante tiene acceso directo a sus datos acad\u00e9micos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>LABORATORIOS<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Laboratorio de cromatograf\u00eda \u2013 EMBRAPA Agrobiologia<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Comprende un \u00fanico ambiente con cromat\u00f3grafo de gases con inyector autom\u00e1tico, equipado con detectores de captura de electrones, ionizaci\u00f3n de llama y conductividad t\u00e9rmica, que son calibrados para los an\u00e1lisis de gases de efecto invernadero (CO<sub>2<\/sub>, N<sub>2<\/sub>O y CH<sub>4<\/sub>) as\u00ed como tambi\u00e9n la cuantificaci\u00f3n de la actividad nitrogenasa que puede ser medida por otro equipamiento tambi\u00e9n existente en este laboratorio (sistema Quibt), el cual est\u00e9 equipado con sensores de H<sub>2<\/sub>. Adem\u00e1s de los cromat\u00f3grafos, est\u00e1n disponibles los sistemas para mediciones \u201c<em>in situ<\/em>\u201d de la evoluci\u00f3n de CO<sub>2<\/sub>&nbsp;y de emisi\u00f3n de \u00f3xido n\u00edtrico (NO) en el suelo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Laboratorio de F\u00edsica del Suelo<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El laboratorio de F\u00edsica del suelo ejecuta investigaciones relacionadas con las funciones del suelo y sus interrelaciones con las propiedades f\u00edsico-h\u00eddricas. Las investigaciones engloban: 1- Desarrollo de m\u00e9todos de modelaci\u00f3n y mapeo digital de suelos y de propiedades f\u00edsico-h\u00eddricas asociadas, 2- Desarrollo de m\u00e9todos de evaluaci\u00f3n de propiedades f\u00edsicas del suelo, 3- Manejo del agua en sistemas agroecol\u00f3gicos y valoraci\u00f3n de los servicios de agua y suelo en ecosistemas, 4- Evaluaci\u00f3n y mitigaci\u00f3n de procesos de degradaci\u00f3n f\u00edsica de los suelos (erosi\u00f3n h\u00eddrica y salinizaci\u00f3n), 5- educaci\u00f3n ambiental. Las actividades de investigaci\u00f3n son desarrolladas en funci\u00f3n de los cursos de pos graduaci\u00f3n del Instituto de Agronom\u00eda (CPGA-CS) y en colaboraci\u00f3n con la EMBRAPA y PESAGRO. El laboratorio desarrolla investigaciones financiadas por la FAPERJ, CAPES, CNPq y Petrobras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Laboratorio de G\u00e9nesis y clasificaci\u00f3n de Suelo<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El laboratorio de g\u00e9nesis y clasificaci\u00f3n de suelo atiende a proyectos de investigaci\u00f3n y entrenamiento de alumnos de graduaci\u00f3n y pos graduaci\u00f3n en las l\u00edneas de investigaci\u00f3n del CPGA-CS \u2013 Morfolog\u00eda, g\u00e9nesis y clasificaci\u00f3n de suelos y Uso y manejo de suelos. Sus profesores act\u00faan como l\u00edderes en los grupos de investigaci\u00f3n de la UFRRJ: Pedolog\u00eda e indicadores edafo-ambientales. El laboratorio posee colaboraci\u00f3n en la investigaci\u00f3n con la EMBRAPA suelos y Agrobiolog\u00eda, as\u00ed como con otros sectores de la UFRRJ e IES, en los temas de: Integridad de paisajes en el ambiente Mar de Morros, Geo procesamiento ambiental, caracter\u00edsticas de la tierras y planificaci\u00f3n, ciclo de nutrientes en florestas primarias, secundarias y plantaciones homog\u00e9neas, manejo y conservaci\u00f3n de suelos, etnopedologia, Suelo org\u00e1nicos y suelos de \u201ctabuleiro\u201d e indicadores de calidad del suelo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Laboratorio de Geo tecnolog\u00edas aplicadas a los estudios de los recursos naturales<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El laboratorio de Geotecnologias aplicadas a los estudios de los recursos naturales \u2013 Geoflora, cuenta actualmente con diversos equipamientos y programas, de los cuales podemos destacar: laser scan, georadar, GPS geod\u00e9sico, paquete del Arcgis, Envi y Erdas, entre otros, los cuales est\u00e1n asociados a un conjunto de computadoras modernas que permiten la realizaci\u00f3n de investigaciones en diversas \u00e1reas del conocimiento, tanto en diferentes regiones de Brasil como fuera del pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Laboratorio de gram\u00edneas. EMBRAPA Agrobiolog\u00eda<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>&nbsp;<\/strong>El laboratorio de gram\u00edneas de la EMBRAPA Agrobiolog\u00eda est\u00e1 especializado en el aislamiento e identificaci\u00f3n de bacterias diazotr\u00f3ficas que se asocian a las no leguminosas de inter\u00e9s econ\u00f3mico. El referido laboratorio tiene renombre nacional e internacional ya que los investigadores que trabajan en \u00e9l son responsables por la identificaci\u00f3n y descripci\u00f3n de 7 especies de bacterias diazotroficas, siendo la especie Azospirillum&nbsp;<em>brasilense<\/em>&nbsp;utilizada mundialmente en inoculantes comerciales y en diversos experimentos de productividad de granos. La estirpe Sp245 (A.&nbsp;<em>brasilense<\/em>) tambi\u00e9n pertenece al laboratorio la cual fue la escogida para la descripci\u00f3n de su genoma. Las estirpes que componen el reci\u00e9n lanzado inoculantes de ca\u00f1a de az\u00facar, por la EMBRAPA son tambi\u00e9n frutos de este laboratorio. Las actividades de investigaci\u00f3n realizadas cuentan con 2 investigadores bolsistas de CNPq y Cient\u00edficos de nuestro Estado, 2 pos doctorados, 2 t\u00e9cnicos y m\u00e1s de 15 estudiantes de graduaci\u00f3n y pos graduaci\u00f3n, adem\u00e1s de los colaboradores de otras \u00e1reas de investigaci\u00f3n. Sus instalaciones, reci\u00e9n reformadas, est\u00e1n debidamente equipadas y la infraestructura est\u00e1 de acuerdo con&nbsp; la necesidad de investigaci\u00f3n desarrollada.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para atender a los docentes, el Departamento de Suelo cuenta en su estructura con 15 oficinas para los docentes, 25 computadoras y [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-4941","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Infraestructura - Programa de P\u00f3s-gradua\u00e7\u00e3o em Agronomia - Ci\u00eancia do Solo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/cpgacs\/es\/infraestructura\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Infraestructura - Programa de P\u00f3s-gradua\u00e7\u00e3o em Agronomia - Ci\u00eancia do Solo\" \/>\n<meta property=\"og:description\" content=\"Para atender a los docentes, el Departamento de Suelo cuenta en su estructura con 15 oficinas para los docentes, 25 computadoras y [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cursos.ufrrj.br\/posgraduacao\/cpgacs\/es\/infraestructura\/\" \/>\n<meta property=\"og:site_name\" content=\"Programa de P\u00f3s-gradua\u00e7\u00e3o em Agronomia - Ci\u00eancia do Solo\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-31T13:12:21+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/cpgacs\\\/es\\\/infraestructura\\\/\",\"url\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/cpgacs\\\/es\\\/infraestructura\\\/\",\"name\":\"Infraestructura - Programa de P\u00f3s-gradua\u00e7\u00e3o em Agronomia - Ci\u00eancia do Solo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/cpgacs\\\/#website\"},\"datePublished\":\"2022-10-31T13:12:20+00:00\",\"dateModified\":\"2022-10-31T13:12:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/cpgacs\\\/es\\\/infraestructura\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/cpgacs\\\/es\\\/infraestructura\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/cpgacs\\\/es\\\/infraestructura\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/cpgacs\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Infraestructura\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/cpgacs\\\/#website\",\"url\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/cpgacs\\\/\",\"name\":\"Programa de P\u00f3s-gradua\u00e7\u00e3o em Agronomia - Ci\u00eancia do Solo\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cursos.ufrrj.br\\\/posgraduacao\\\/cpgacs\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Infraestructura - Programa de P\u00f3s-gradua\u00e7\u00e3o em Agronomia - Ci\u00eancia do Solo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cursos.ufrrj.br\/posgraduacao\/cpgacs\/es\/infraestructura\/","og_locale":"pt_BR","og_type":"article","og_title":"Infraestructura - Programa de P\u00f3s-gradua\u00e7\u00e3o em Agronomia - Ci\u00eancia do Solo","og_description":"Para atender a los docentes, el Departamento de Suelo cuenta en su estructura con 15 oficinas para los docentes, 25 computadoras y [&hellip;]","og_url":"https:\/\/cursos.ufrrj.br\/posgraduacao\/cpgacs\/es\/infraestructura\/","og_site_name":"Programa de P\u00f3s-gradua\u00e7\u00e3o em Agronomia - Ci\u00eancia do Solo","article_modified_time":"2022-10-31T13:12:21+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/cpgacs\/es\/infraestructura\/","url":"https:\/\/cursos.ufrrj.br\/posgraduacao\/cpgacs\/es\/infraestructura\/","name":"Infraestructura - Programa de P\u00f3s-gradua\u00e7\u00e3o em Agronomia - Ci\u00eancia do Solo","isPartOf":{"@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/cpgacs\/#website"},"datePublished":"2022-10-31T13:12:20+00:00","dateModified":"2022-10-31T13:12:21+00:00","breadcrumb":{"@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/cpgacs\/es\/infraestructura\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cursos.ufrrj.br\/posgraduacao\/cpgacs\/es\/infraestructura\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/cpgacs\/es\/infraestructura\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/cursos.ufrrj.br\/posgraduacao\/cpgacs\/"},{"@type":"ListItem","position":2,"name":"Infraestructura"}]},{"@type":"WebSite","@id":"https:\/\/cursos.ufrrj.br\/posgraduacao\/cpgacs\/#website","url":"https:\/\/cursos.ufrrj.br\/posgraduacao\/cpgacs\/","name":"Programa de P\u00f3s-gradua\u00e7\u00e3o em Agronomia - Ci\u00eancia do Solo","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cursos.ufrrj.br\/posgraduacao\/cpgacs\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/cpgacs\/wp-json\/wp\/v2\/pages\/4941","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/cpgacs\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/cpgacs\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/cpgacs\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/cpgacs\/wp-json\/wp\/v2\/comments?post=4941"}],"version-history":[{"count":1,"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/cpgacs\/wp-json\/wp\/v2\/pages\/4941\/revisions"}],"predecessor-version":[{"id":4942,"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/cpgacs\/wp-json\/wp\/v2\/pages\/4941\/revisions\/4942"}],"wp:attachment":[{"href":"https:\/\/cursos.ufrrj.br\/posgraduacao\/cpgacs\/wp-json\/wp\/v2\/media?parent=4941"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}