{"id":2560,"date":"2024-12-03T20:41:36","date_gmt":"2024-12-03T23:41:36","guid":{"rendered":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/?p=2560"},"modified":"2025-02-02T00:29:27","modified_gmt":"2025-02-02T03:29:27","slug":"defesa-de-tcc-gestao-do-tempo-no-ensino-superior-desafios-e-solucoes-digitais-para-organizacao-pessoal","status":"publish","type":"post","link":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/defesa-de-tcc-gestao-do-tempo-no-ensino-superior-desafios-e-solucoes-digitais-para-organizacao-pessoal\/","title":{"rendered":"Defesa de TCC: Gest\u00e3o do Tempo no Ensino Superior \u2013 Desafios e Solu\u00e7\u00f5es Digitais para Organiza\u00e7\u00e3o Pessoal"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">A discente Isabelle Rizzo, do curso de Sistemas de Informa\u00e7\u00e3o da Universidade Federal Rural do Rio de Janeiro (UFRRJ), apresentar\u00e1 a defesa de seu Trabalho de Conclus\u00e3o de Curso (TCC) no dia 03 de dezembro de 2024, \u00e0s 10h, de forma remota. O trabalho tem como tema &#8220;Gest\u00e3o do Tempo no Ensino Superior: Pesquisa e An\u00e1lise dos Desafios Enfrentados Pelos Estudantes para Desenvolvimento de Ferramenta Digital de Organiza\u00e7\u00e3o Pessoal&#8221; e foi orientado pelo Professor Eduardo Kinder Almentero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O estudo explora os desafios enfrentados pelos estudantes do ensino superior na gest\u00e3o de seu tempo, com foco nos impactos no desempenho acad\u00eamico e na sa\u00fade mental. A partir dessa an\u00e1lise, a pesquisa prop\u00f5e o desenvolvimento de uma ferramenta digital que auxilie na organiza\u00e7\u00e3o pessoal, buscando solu\u00e7\u00f5es pr\u00e1ticas e acess\u00edveis para o p\u00fablico universit\u00e1rio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Prestigie este momento significativo e venha conhecer mais sobre as contribui\u00e7\u00f5es acad\u00eamicas da estudante Isabelle Rizzo!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A discente Isabelle Rizzo, do curso de Sistemas de Informa\u00e7\u00e3o da Universidade Federal Rural do Rio de Janeiro (UFRRJ), apresentar\u00e1 <a class=\"read-more\" href=\"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/defesa-de-tcc-gestao-do-tempo-no-ensino-superior-desafios-e-solucoes-digitais-para-organizacao-pessoal\/ \" >&#8230; <span class=\"font-italic\">leia mais <i class=\"fas fa-angle-right\"><\/i><\/span><\/a><\/p>\n","protected":false},"author":79,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ngg_post_thumbnail":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[3,56],"tags":[21,5,55],"class_list":["post-2560","post","type-post","status-publish","format-standard","hentry","category-noticias","category-tcc","tag-pet","tag-si","tag-tcc"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Defesa de TCC: Gest\u00e3o do Tempo no Ensino Superior \u2013 Desafios e Solu\u00e7\u00f5es Digitais para Organiza\u00e7\u00e3o Pessoal - Sistemas de Informa\u00e7\u00e3o<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/defesa-de-tcc-gestao-do-tempo-no-ensino-superior-desafios-e-solucoes-digitais-para-organizacao-pessoal\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Defesa de TCC: Gest\u00e3o do Tempo no Ensino Superior \u2013 Desafios e Solu\u00e7\u00f5es Digitais para Organiza\u00e7\u00e3o Pessoal - Sistemas de Informa\u00e7\u00e3o\" \/>\n<meta property=\"og:description\" content=\"A discente Isabelle Rizzo, do curso de Sistemas de Informa\u00e7\u00e3o da Universidade Federal Rural do Rio de Janeiro (UFRRJ), apresentar\u00e1 ... leia mais\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/defesa-de-tcc-gestao-do-tempo-no-ensino-superior-desafios-e-solucoes-digitais-para-organizacao-pessoal\/\" \/>\n<meta property=\"og:site_name\" content=\"Sistemas de Informa\u00e7\u00e3o\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-03T23:41:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-02T03:29:27+00:00\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/defesa-de-tcc-gestao-do-tempo-no-ensino-superior-desafios-e-solucoes-digitais-para-organizacao-pessoal\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/defesa-de-tcc-gestao-do-tempo-no-ensino-superior-desafios-e-solucoes-digitais-para-organizacao-pessoal\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/#\\\/schema\\\/person\\\/ad16d91ae6159085b139672cd526bfe7\"},\"headline\":\"Defesa de TCC: Gest\u00e3o do Tempo no Ensino Superior \u2013 Desafios e Solu\u00e7\u00f5es Digitais para Organiza\u00e7\u00e3o Pessoal\",\"datePublished\":\"2024-12-03T23:41:36+00:00\",\"dateModified\":\"2025-02-02T03:29:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/defesa-de-tcc-gestao-do-tempo-no-ensino-superior-desafios-e-solucoes-digitais-para-organizacao-pessoal\\\/\"},\"wordCount\":182,\"keywords\":[\"PET\",\"Si\",\"TCC\"],\"articleSection\":[\"Not\u00edcias\",\"TCC\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/defesa-de-tcc-gestao-do-tempo-no-ensino-superior-desafios-e-solucoes-digitais-para-organizacao-pessoal\\\/\",\"url\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/defesa-de-tcc-gestao-do-tempo-no-ensino-superior-desafios-e-solucoes-digitais-para-organizacao-pessoal\\\/\",\"name\":\"Defesa de TCC: Gest\u00e3o do Tempo no Ensino Superior \u2013 Desafios e Solu\u00e7\u00f5es Digitais para Organiza\u00e7\u00e3o Pessoal - Sistemas de Informa\u00e7\u00e3o\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/#website\"},\"datePublished\":\"2024-12-03T23:41:36+00:00\",\"dateModified\":\"2025-02-02T03:29:27+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/#\\\/schema\\\/person\\\/ad16d91ae6159085b139672cd526bfe7\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/defesa-de-tcc-gestao-do-tempo-no-ensino-superior-desafios-e-solucoes-digitais-para-organizacao-pessoal\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/defesa-de-tcc-gestao-do-tempo-no-ensino-superior-desafios-e-solucoes-digitais-para-organizacao-pessoal\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/defesa-de-tcc-gestao-do-tempo-no-ensino-superior-desafios-e-solucoes-digitais-para-organizacao-pessoal\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Defesa de TCC: Gest\u00e3o do Tempo no Ensino Superior \u2013 Desafios e Solu\u00e7\u00f5es Digitais para Organiza\u00e7\u00e3o Pessoal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/#website\",\"url\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/\",\"name\":\"Sistemas de Informa\u00e7\u00e3o\",\"description\":\"Campus Serop\u00e9dica \u2013 UFRRJ\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/#\\\/schema\\\/person\\\/ad16d91ae6159085b139672cd526bfe7\",\"name\":\"admin\",\"url\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Defesa de TCC: Gest\u00e3o do Tempo no Ensino Superior \u2013 Desafios e Solu\u00e7\u00f5es Digitais para Organiza\u00e7\u00e3o Pessoal - Sistemas de Informa\u00e7\u00e3o","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/defesa-de-tcc-gestao-do-tempo-no-ensino-superior-desafios-e-solucoes-digitais-para-organizacao-pessoal\/","og_locale":"pt_BR","og_type":"article","og_title":"Defesa de TCC: Gest\u00e3o do Tempo no Ensino Superior \u2013 Desafios e Solu\u00e7\u00f5es Digitais para Organiza\u00e7\u00e3o Pessoal - Sistemas de Informa\u00e7\u00e3o","og_description":"A discente Isabelle Rizzo, do curso de Sistemas de Informa\u00e7\u00e3o da Universidade Federal Rural do Rio de Janeiro (UFRRJ), apresentar\u00e1 ... leia mais","og_url":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/defesa-de-tcc-gestao-do-tempo-no-ensino-superior-desafios-e-solucoes-digitais-para-organizacao-pessoal\/","og_site_name":"Sistemas de Informa\u00e7\u00e3o","article_published_time":"2024-12-03T23:41:36+00:00","article_modified_time":"2025-02-02T03:29:27+00:00","author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/defesa-de-tcc-gestao-do-tempo-no-ensino-superior-desafios-e-solucoes-digitais-para-organizacao-pessoal\/#article","isPartOf":{"@id":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/defesa-de-tcc-gestao-do-tempo-no-ensino-superior-desafios-e-solucoes-digitais-para-organizacao-pessoal\/"},"author":{"name":"admin","@id":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/#\/schema\/person\/ad16d91ae6159085b139672cd526bfe7"},"headline":"Defesa de TCC: Gest\u00e3o do Tempo no Ensino Superior \u2013 Desafios e Solu\u00e7\u00f5es Digitais para Organiza\u00e7\u00e3o Pessoal","datePublished":"2024-12-03T23:41:36+00:00","dateModified":"2025-02-02T03:29:27+00:00","mainEntityOfPage":{"@id":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/defesa-de-tcc-gestao-do-tempo-no-ensino-superior-desafios-e-solucoes-digitais-para-organizacao-pessoal\/"},"wordCount":182,"keywords":["PET","Si","TCC"],"articleSection":["Not\u00edcias","TCC"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/defesa-de-tcc-gestao-do-tempo-no-ensino-superior-desafios-e-solucoes-digitais-para-organizacao-pessoal\/","url":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/defesa-de-tcc-gestao-do-tempo-no-ensino-superior-desafios-e-solucoes-digitais-para-organizacao-pessoal\/","name":"Defesa de TCC: Gest\u00e3o do Tempo no Ensino Superior \u2013 Desafios e Solu\u00e7\u00f5es Digitais para Organiza\u00e7\u00e3o Pessoal - Sistemas de Informa\u00e7\u00e3o","isPartOf":{"@id":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/#website"},"datePublished":"2024-12-03T23:41:36+00:00","dateModified":"2025-02-02T03:29:27+00:00","author":{"@id":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/#\/schema\/person\/ad16d91ae6159085b139672cd526bfe7"},"breadcrumb":{"@id":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/defesa-de-tcc-gestao-do-tempo-no-ensino-superior-desafios-e-solucoes-digitais-para-organizacao-pessoal\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cursos.ufrrj.br\/grad\/sistemas\/defesa-de-tcc-gestao-do-tempo-no-ensino-superior-desafios-e-solucoes-digitais-para-organizacao-pessoal\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/defesa-de-tcc-gestao-do-tempo-no-ensino-superior-desafios-e-solucoes-digitais-para-organizacao-pessoal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/"},{"@type":"ListItem","position":2,"name":"Defesa de TCC: Gest\u00e3o do Tempo no Ensino Superior \u2013 Desafios e Solu\u00e7\u00f5es Digitais para Organiza\u00e7\u00e3o Pessoal"}]},{"@type":"WebSite","@id":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/#website","url":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/","name":"Sistemas de Informa\u00e7\u00e3o","description":"Campus Serop\u00e9dica \u2013 UFRRJ","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/#\/schema\/person\/ad16d91ae6159085b139672cd526bfe7","name":"admin","url":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/author\/admin\/"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/wp-json\/wp\/v2\/posts\/2560","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/wp-json\/wp\/v2\/users\/79"}],"replies":[{"embeddable":true,"href":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/wp-json\/wp\/v2\/comments?post=2560"}],"version-history":[{"count":1,"href":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/wp-json\/wp\/v2\/posts\/2560\/revisions"}],"predecessor-version":[{"id":2561,"href":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/wp-json\/wp\/v2\/posts\/2560\/revisions\/2561"}],"wp:attachment":[{"href":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/wp-json\/wp\/v2\/media?parent=2560"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/wp-json\/wp\/v2\/categories?post=2560"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/wp-json\/wp\/v2\/tags?post=2560"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}