{"id":2464,"date":"2024-02-10T16:52:01","date_gmt":"2024-02-10T19:52:01","guid":{"rendered":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/?p=2464"},"modified":"2024-02-23T10:30:44","modified_gmt":"2024-02-23T13:30:44","slug":"semana-de-integracao-2024-1","status":"publish","type":"post","link":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/semana-de-integracao-2024-1\/","title":{"rendered":"Semana de Integra\u00e7\u00e3o 2024.1"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">A coordena\u00e7\u00e3o do curso de Sistemas de Informa\u00e7\u00e3o convida a todos os discentes, em especial os ingressantes, a comparecerem \u00e0s atividades de integra\u00e7\u00e3o, na primeira semana de aulas.<br>A Semana come\u00e7a no dia 26\/02 com a aula magna, pela manh\u00e3.<br>O instituto de Ci\u00eancias Exatas, preparou uma recep\u00e7\u00e3o aos discentes, no dia 27\/02 na parte da manh\u00e3, iniciando-se \u00e0s 9h00.<br>A coordena\u00e7\u00e3o do curso preparou, \u00e0 tarde do dia 27\/02, eventos para que todos os alunos possam participar.<br>No dia 28\/02, \u00e0s 8h30, haver\u00e1 a tradicional caminhada com o professor Rafael.  Esta caminhada percorrer\u00e1 o campus de Serop\u00e9dica.<\/p>\n\n\n\n<pre class=\"wp-block-preformatted\"><strong>Dia 27\/02 - Programa\u00e7\u00e3o<\/strong>\n13h00 \u00e0s 13h30 - Conversa com a coordena\u00e7\u00e3o\n13h30 \u00e0s 14h30 - Palestra da Proas\n14h30 \u00e0s 15h00 - Conversa com o PET-SI\n15h00 \u00e0s 15h15 - Coffe-break\n15h15 \u00e0s 15h30 - Conversa com o Dasi\n15h30 \u00e0s 16h00 - palestra prof. Nilton J. Rizzo - TI Verde\n16h00 \u00e0s 16h20 - Conversa com egressos\n16h20 \u00e0s 16h50 - Palestra prof. Raimundo Mac\u00e1rio\n16h50 - Encerramento<\/pre>\n\n\n\n<pre class=\"wp-block-preformatted\"><strong>Dia 28\/02 - Programa\u00e7\u00e3o<\/strong> \n8h30 - Concentra\u00e7\u00e3o para a caminhada pelo campus de Serop\u00e9dica com o professor Rafael\nA concentra\u00e7\u00e3o ser\u00e1 feita no pr\u00e9dio do Instituto de Ci\u00eancias Exatas (ICE), ao lado do pr\u00e9dio principal.<\/pre>\n","protected":false},"excerpt":{"rendered":"<p>A coordena\u00e7\u00e3o do curso de Sistemas de Informa\u00e7\u00e3o convida a todos os discentes, em especial os ingressantes, a comparecerem \u00e0s <a class=\"read-more\" href=\"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/semana-de-integracao-2024-1\/ \" >&#8230; <span class=\"font-italic\">leia mais <i class=\"fas fa-angle-right\"><\/i><\/span><\/a><\/p>\n","protected":false},"author":195,"featured_media":2470,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ngg_post_thumbnail":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[30,3],"tags":[33,39,21,6,5],"class_list":["post-2464","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventos","category-noticias","tag-coordenacao","tag-integracao","tag-pet","tag-rural","tag-si"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Semana de Integra\u00e7\u00e3o 2024.1 - Sistemas de Informa\u00e7\u00e3o<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/semana-de-integracao-2024-1\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Semana de Integra\u00e7\u00e3o 2024.1 - Sistemas de Informa\u00e7\u00e3o\" \/>\n<meta property=\"og:description\" content=\"A coordena\u00e7\u00e3o do curso de Sistemas de Informa\u00e7\u00e3o convida a todos os discentes, em especial os ingressantes, a comparecerem \u00e0s ... leia mais\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/semana-de-integracao-2024-1\/\" \/>\n<meta property=\"og:site_name\" content=\"Sistemas de Informa\u00e7\u00e3o\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-10T19:52:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-23T13:30:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/files\/2024\/02\/2024_1_cartaz_400x400.png\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"rizzo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"rizzo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/semana-de-integracao-2024-1\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/semana-de-integracao-2024-1\\\/\"},\"author\":{\"name\":\"rizzo\",\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/#\\\/schema\\\/person\\\/53bd5ac834a651afabfdd8845572609b\"},\"headline\":\"Semana de Integra\u00e7\u00e3o 2024.1\",\"datePublished\":\"2024-02-10T19:52:01+00:00\",\"dateModified\":\"2024-02-23T13:30:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/semana-de-integracao-2024-1\\\/\"},\"wordCount\":105,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/semana-de-integracao-2024-1\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/files\\\/2024\\\/02\\\/2024_1_cartaz_400x400.png\",\"keywords\":[\"Coordena\u00e7\u00e3o\",\"Integra\u00e7\u00e3o\",\"PET\",\"Rural\",\"Si\"],\"articleSection\":[\"Eventos\",\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/semana-de-integracao-2024-1\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/semana-de-integracao-2024-1\\\/\",\"url\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/semana-de-integracao-2024-1\\\/\",\"name\":\"Semana de Integra\u00e7\u00e3o 2024.1 - Sistemas de Informa\u00e7\u00e3o\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/semana-de-integracao-2024-1\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/semana-de-integracao-2024-1\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/files\\\/2024\\\/02\\\/2024_1_cartaz_400x400.png\",\"datePublished\":\"2024-02-10T19:52:01+00:00\",\"dateModified\":\"2024-02-23T13:30:44+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/#\\\/schema\\\/person\\\/53bd5ac834a651afabfdd8845572609b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/semana-de-integracao-2024-1\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/semana-de-integracao-2024-1\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/semana-de-integracao-2024-1\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/files\\\/2024\\\/02\\\/2024_1_cartaz_400x400.png\",\"contentUrl\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/files\\\/2024\\\/02\\\/2024_1_cartaz_400x400.png\",\"width\":400,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/semana-de-integracao-2024-1\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Semana de Integra\u00e7\u00e3o 2024.1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/#website\",\"url\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/\",\"name\":\"Sistemas de Informa\u00e7\u00e3o\",\"description\":\"Campus Serop\u00e9dica \u2013 UFRRJ\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/#\\\/schema\\\/person\\\/53bd5ac834a651afabfdd8845572609b\",\"name\":\"rizzo\",\"url\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/author\\\/rizzo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Semana de Integra\u00e7\u00e3o 2024.1 - Sistemas de Informa\u00e7\u00e3o","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/semana-de-integracao-2024-1\/","og_locale":"pt_BR","og_type":"article","og_title":"Semana de Integra\u00e7\u00e3o 2024.1 - Sistemas de Informa\u00e7\u00e3o","og_description":"A coordena\u00e7\u00e3o do curso de Sistemas de Informa\u00e7\u00e3o convida a todos os discentes, em especial os ingressantes, a comparecerem \u00e0s ... leia mais","og_url":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/semana-de-integracao-2024-1\/","og_site_name":"Sistemas de Informa\u00e7\u00e3o","article_published_time":"2024-02-10T19:52:01+00:00","article_modified_time":"2024-02-23T13:30:44+00:00","og_image":[{"width":400,"height":400,"url":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/files\/2024\/02\/2024_1_cartaz_400x400.png","type":"image\/png"}],"author":"rizzo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"rizzo","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/semana-de-integracao-2024-1\/#article","isPartOf":{"@id":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/semana-de-integracao-2024-1\/"},"author":{"name":"rizzo","@id":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/#\/schema\/person\/53bd5ac834a651afabfdd8845572609b"},"headline":"Semana de Integra\u00e7\u00e3o 2024.1","datePublished":"2024-02-10T19:52:01+00:00","dateModified":"2024-02-23T13:30:44+00:00","mainEntityOfPage":{"@id":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/semana-de-integracao-2024-1\/"},"wordCount":105,"commentCount":0,"image":{"@id":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/semana-de-integracao-2024-1\/#primaryimage"},"thumbnailUrl":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/files\/2024\/02\/2024_1_cartaz_400x400.png","keywords":["Coordena\u00e7\u00e3o","Integra\u00e7\u00e3o","PET","Rural","Si"],"articleSection":["Eventos","Not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cursos.ufrrj.br\/grad\/sistemas\/semana-de-integracao-2024-1\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/semana-de-integracao-2024-1\/","url":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/semana-de-integracao-2024-1\/","name":"Semana de Integra\u00e7\u00e3o 2024.1 - Sistemas de Informa\u00e7\u00e3o","isPartOf":{"@id":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/semana-de-integracao-2024-1\/#primaryimage"},"image":{"@id":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/semana-de-integracao-2024-1\/#primaryimage"},"thumbnailUrl":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/files\/2024\/02\/2024_1_cartaz_400x400.png","datePublished":"2024-02-10T19:52:01+00:00","dateModified":"2024-02-23T13:30:44+00:00","author":{"@id":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/#\/schema\/person\/53bd5ac834a651afabfdd8845572609b"},"breadcrumb":{"@id":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/semana-de-integracao-2024-1\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cursos.ufrrj.br\/grad\/sistemas\/semana-de-integracao-2024-1\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/semana-de-integracao-2024-1\/#primaryimage","url":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/files\/2024\/02\/2024_1_cartaz_400x400.png","contentUrl":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/files\/2024\/02\/2024_1_cartaz_400x400.png","width":400,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/semana-de-integracao-2024-1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/"},{"@type":"ListItem","position":2,"name":"Semana de Integra\u00e7\u00e3o 2024.1"}]},{"@type":"WebSite","@id":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/#website","url":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/","name":"Sistemas de Informa\u00e7\u00e3o","description":"Campus Serop\u00e9dica \u2013 UFRRJ","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/#\/schema\/person\/53bd5ac834a651afabfdd8845572609b","name":"rizzo","url":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/author\/rizzo\/"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/wp-json\/wp\/v2\/posts\/2464","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/wp-json\/wp\/v2\/users\/195"}],"replies":[{"embeddable":true,"href":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/wp-json\/wp\/v2\/comments?post=2464"}],"version-history":[{"count":9,"href":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/wp-json\/wp\/v2\/posts\/2464\/revisions"}],"predecessor-version":[{"id":2480,"href":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/wp-json\/wp\/v2\/posts\/2464\/revisions\/2480"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/wp-json\/wp\/v2\/media\/2470"}],"wp:attachment":[{"href":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/wp-json\/wp\/v2\/media?parent=2464"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/wp-json\/wp\/v2\/categories?post=2464"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/wp-json\/wp\/v2\/tags?post=2464"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}