{"id":2445,"date":"2023-12-15T22:47:06","date_gmt":"2023-12-16T01:47:06","guid":{"rendered":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/?p=2445"},"modified":"2023-12-15T22:53:31","modified_gmt":"2023-12-16T01:53:31","slug":"defesa-tcc","status":"publish","type":"post","link":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/defesa-tcc\/","title":{"rendered":"Defesa de TCC"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">O curso de sistemas de informa\u00e7\u00e3o convida para a defesa de TCC do discente&nbsp;<strong>Thamara Guimar\u00e3es<\/strong> <strong>Bello de Oliveira<\/strong>, dia 20\/12 as 18h. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O tema do trabalho de conclus\u00e3o de curso \u00e9:&nbsp;<strong>ConectaPets: Um aplicativo para facilitar a ado\u00e7\u00e3o de animais e como a ferramenta Strapi agilizou seu desenvolvimento<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A banca \u00e9 composta pelo orientador, prof. Dr. Nilton Jos\u00e9 Rizzo, prof. Dr. Eduardo Kinder Almenteiro e o prof. Dr. Raimundo Mac\u00e1rio<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O curso de sistemas de informa\u00e7\u00e3o convida para a defesa de TCC do discente&nbsp;Thamara Guimar\u00e3es Bello de Oliveira, dia 20\/12 <a class=\"read-more\" href=\"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/defesa-tcc\/ \" >&#8230; <span class=\"font-italic\">leia mais <i class=\"fas fa-angle-right\"><\/i><\/span><\/a><\/p>\n","protected":false},"author":195,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ngg_post_thumbnail":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[30,29,3],"tags":[],"class_list":["post-2445","post","type-post","status-publish","format-standard","hentry","category-eventos","category-monografias","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Defesa de TCC - Sistemas de Informa\u00e7\u00e3o<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/defesa-tcc\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Defesa de TCC - Sistemas de Informa\u00e7\u00e3o\" \/>\n<meta property=\"og:description\" content=\"O curso de sistemas de informa\u00e7\u00e3o convida para a defesa de TCC do discente&nbsp;Thamara Guimar\u00e3es Bello de Oliveira, dia 20\/12 ... leia mais\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/defesa-tcc\/\" \/>\n<meta property=\"og:site_name\" content=\"Sistemas de Informa\u00e7\u00e3o\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-16T01:47:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-16T01:53:31+00:00\" \/>\n<meta name=\"author\" content=\"rizzo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"rizzo\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/defesa-tcc\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/defesa-tcc\\\/\"},\"author\":{\"name\":\"rizzo\",\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/#\\\/schema\\\/person\\\/53bd5ac834a651afabfdd8845572609b\"},\"headline\":\"Defesa de TCC\",\"datePublished\":\"2023-12-16T01:47:06+00:00\",\"dateModified\":\"2023-12-16T01:53:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/defesa-tcc\\\/\"},\"wordCount\":78,\"articleSection\":[\"Eventos\",\"Monografias\",\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/defesa-tcc\\\/\",\"url\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/defesa-tcc\\\/\",\"name\":\"Defesa de TCC - Sistemas de Informa\u00e7\u00e3o\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/#website\"},\"datePublished\":\"2023-12-16T01:47:06+00:00\",\"dateModified\":\"2023-12-16T01:53:31+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/#\\\/schema\\\/person\\\/53bd5ac834a651afabfdd8845572609b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/defesa-tcc\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/defesa-tcc\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/defesa-tcc\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Defesa de TCC\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/#website\",\"url\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/\",\"name\":\"Sistemas de Informa\u00e7\u00e3o\",\"description\":\"Campus Serop\u00e9dica \u2013 UFRRJ\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/#\\\/schema\\\/person\\\/53bd5ac834a651afabfdd8845572609b\",\"name\":\"rizzo\",\"url\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/author\\\/rizzo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Defesa de TCC - Sistemas de Informa\u00e7\u00e3o","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/defesa-tcc\/","og_locale":"pt_BR","og_type":"article","og_title":"Defesa de TCC - Sistemas de Informa\u00e7\u00e3o","og_description":"O curso de sistemas de informa\u00e7\u00e3o convida para a defesa de TCC do discente&nbsp;Thamara Guimar\u00e3es Bello de Oliveira, dia 20\/12 ... leia mais","og_url":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/defesa-tcc\/","og_site_name":"Sistemas de Informa\u00e7\u00e3o","article_published_time":"2023-12-16T01:47:06+00:00","article_modified_time":"2023-12-16T01:53:31+00:00","author":"rizzo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"rizzo"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/defesa-tcc\/#article","isPartOf":{"@id":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/defesa-tcc\/"},"author":{"name":"rizzo","@id":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/#\/schema\/person\/53bd5ac834a651afabfdd8845572609b"},"headline":"Defesa de TCC","datePublished":"2023-12-16T01:47:06+00:00","dateModified":"2023-12-16T01:53:31+00:00","mainEntityOfPage":{"@id":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/defesa-tcc\/"},"wordCount":78,"articleSection":["Eventos","Monografias","Not\u00edcias"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/defesa-tcc\/","url":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/defesa-tcc\/","name":"Defesa de TCC - Sistemas de Informa\u00e7\u00e3o","isPartOf":{"@id":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/#website"},"datePublished":"2023-12-16T01:47:06+00:00","dateModified":"2023-12-16T01:53:31+00:00","author":{"@id":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/#\/schema\/person\/53bd5ac834a651afabfdd8845572609b"},"breadcrumb":{"@id":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/defesa-tcc\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cursos.ufrrj.br\/grad\/sistemas\/defesa-tcc\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/defesa-tcc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/"},{"@type":"ListItem","position":2,"name":"Defesa de TCC"}]},{"@type":"WebSite","@id":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/#website","url":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/","name":"Sistemas de Informa\u00e7\u00e3o","description":"Campus Serop\u00e9dica \u2013 UFRRJ","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/#\/schema\/person\/53bd5ac834a651afabfdd8845572609b","name":"rizzo","url":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/author\/rizzo\/"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/wp-json\/wp\/v2\/posts\/2445","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/wp-json\/wp\/v2\/users\/195"}],"replies":[{"embeddable":true,"href":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/wp-json\/wp\/v2\/comments?post=2445"}],"version-history":[{"count":3,"href":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/wp-json\/wp\/v2\/posts\/2445\/revisions"}],"predecessor-version":[{"id":2449,"href":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/wp-json\/wp\/v2\/posts\/2445\/revisions\/2449"}],"wp:attachment":[{"href":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/wp-json\/wp\/v2\/media?parent=2445"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/wp-json\/wp\/v2\/categories?post=2445"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/wp-json\/wp\/v2\/tags?post=2445"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}