{"id":2429,"date":"2023-11-22T13:45:47","date_gmt":"2023-11-22T16:45:47","guid":{"rendered":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/?p=2429"},"modified":"2023-11-22T13:49:03","modified_gmt":"2023-11-22T16:49:03","slug":"prazo-para-pedido-de-prorrogacao-de-curso","status":"publish","type":"post","link":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/prazo-para-pedido-de-prorrogacao-de-curso\/","title":{"rendered":"Prazo para pedido de prorroga\u00e7\u00e3o de curso"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Seguindo o calend\u00e1rio de eventos da universidade, a data limite para a solicita\u00e7\u00e3o de prorroga\u00e7\u00e3o do prazo para a integraliza\u00e7\u00e3o do curso finda em 29\/11, se \u00e9 seu caso, procure a coordena\u00e7\u00e3o do curso e veja o que \u00e9 necess\u00e1rio fazer.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Apesar do prazo finalizar dia 29\/11 n\u00e3o deixe para a \u00faltima hora, pois h\u00e1 necessidade de verifica\u00e7\u00e3o de documentos junto a coordena\u00e7\u00e3o e pode n\u00e3o haver tempo h\u00e1bil para ser feita no \u00faltimo dia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seguindo o calend\u00e1rio de eventos da universidade, a data limite para a solicita\u00e7\u00e3o de prorroga\u00e7\u00e3o do prazo para a integraliza\u00e7\u00e3o <a class=\"read-more\" href=\"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/prazo-para-pedido-de-prorrogacao-de-curso\/ \" >&#8230; <span class=\"font-italic\">leia mais <i class=\"fas fa-angle-right\"><\/i><\/span><\/a><\/p>\n","protected":false},"author":195,"featured_media":1598,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ngg_post_thumbnail":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[3],"tags":[33],"class_list":["post-2429","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-coordenacao"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Prazo para pedido de prorroga\u00e7\u00e3o de curso - Sistemas de Informa\u00e7\u00e3o<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/prazo-para-pedido-de-prorrogacao-de-curso\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prazo para pedido de prorroga\u00e7\u00e3o de curso - Sistemas de Informa\u00e7\u00e3o\" \/>\n<meta property=\"og:description\" content=\"Seguindo o calend\u00e1rio de eventos da universidade, a data limite para a solicita\u00e7\u00e3o de prorroga\u00e7\u00e3o do prazo para a integraliza\u00e7\u00e3o ... leia mais\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/prazo-para-pedido-de-prorrogacao-de-curso\/\" \/>\n<meta property=\"og:site_name\" content=\"Sistemas de Informa\u00e7\u00e3o\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-22T16:45:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-22T16:49:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/files\/2013\/07\/UFRRJ.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"436\" \/>\n\t<meta property=\"og:image:height\" content=\"465\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rizzo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"rizzo\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/prazo-para-pedido-de-prorrogacao-de-curso\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/prazo-para-pedido-de-prorrogacao-de-curso\\\/\"},\"author\":{\"name\":\"rizzo\",\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/#\\\/schema\\\/person\\\/53bd5ac834a651afabfdd8845572609b\"},\"headline\":\"Prazo para pedido de prorroga\u00e7\u00e3o de curso\",\"datePublished\":\"2023-11-22T16:45:47+00:00\",\"dateModified\":\"2023-11-22T16:49:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/prazo-para-pedido-de-prorrogacao-de-curso\\\/\"},\"wordCount\":90,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/prazo-para-pedido-de-prorrogacao-de-curso\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/files\\\/2013\\\/07\\\/UFRRJ.jpg\",\"keywords\":[\"Coordena\u00e7\u00e3o\"],\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/prazo-para-pedido-de-prorrogacao-de-curso\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/prazo-para-pedido-de-prorrogacao-de-curso\\\/\",\"url\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/prazo-para-pedido-de-prorrogacao-de-curso\\\/\",\"name\":\"Prazo para pedido de prorroga\u00e7\u00e3o de curso - Sistemas de Informa\u00e7\u00e3o\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/prazo-para-pedido-de-prorrogacao-de-curso\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/prazo-para-pedido-de-prorrogacao-de-curso\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/files\\\/2013\\\/07\\\/UFRRJ.jpg\",\"datePublished\":\"2023-11-22T16:45:47+00:00\",\"dateModified\":\"2023-11-22T16:49:03+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/#\\\/schema\\\/person\\\/53bd5ac834a651afabfdd8845572609b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/prazo-para-pedido-de-prorrogacao-de-curso\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/prazo-para-pedido-de-prorrogacao-de-curso\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/prazo-para-pedido-de-prorrogacao-de-curso\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/files\\\/2013\\\/07\\\/UFRRJ.jpg\",\"contentUrl\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/files\\\/2013\\\/07\\\/UFRRJ.jpg\",\"width\":436,\"height\":465},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/prazo-para-pedido-de-prorrogacao-de-curso\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prazo para pedido de prorroga\u00e7\u00e3o de curso\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/#website\",\"url\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/\",\"name\":\"Sistemas de Informa\u00e7\u00e3o\",\"description\":\"Campus Serop\u00e9dica \u2013 UFRRJ\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/#\\\/schema\\\/person\\\/53bd5ac834a651afabfdd8845572609b\",\"name\":\"rizzo\",\"url\":\"https:\\\/\\\/cursos.ufrrj.br\\\/grad\\\/sistemas\\\/author\\\/rizzo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Prazo para pedido de prorroga\u00e7\u00e3o de curso - Sistemas de Informa\u00e7\u00e3o","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/prazo-para-pedido-de-prorrogacao-de-curso\/","og_locale":"pt_BR","og_type":"article","og_title":"Prazo para pedido de prorroga\u00e7\u00e3o de curso - Sistemas de Informa\u00e7\u00e3o","og_description":"Seguindo o calend\u00e1rio de eventos da universidade, a data limite para a solicita\u00e7\u00e3o de prorroga\u00e7\u00e3o do prazo para a integraliza\u00e7\u00e3o ... leia mais","og_url":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/prazo-para-pedido-de-prorrogacao-de-curso\/","og_site_name":"Sistemas de Informa\u00e7\u00e3o","article_published_time":"2023-11-22T16:45:47+00:00","article_modified_time":"2023-11-22T16:49:03+00:00","og_image":[{"width":436,"height":465,"url":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/files\/2013\/07\/UFRRJ.jpg","type":"image\/jpeg"}],"author":"rizzo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"rizzo"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/prazo-para-pedido-de-prorrogacao-de-curso\/#article","isPartOf":{"@id":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/prazo-para-pedido-de-prorrogacao-de-curso\/"},"author":{"name":"rizzo","@id":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/#\/schema\/person\/53bd5ac834a651afabfdd8845572609b"},"headline":"Prazo para pedido de prorroga\u00e7\u00e3o de curso","datePublished":"2023-11-22T16:45:47+00:00","dateModified":"2023-11-22T16:49:03+00:00","mainEntityOfPage":{"@id":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/prazo-para-pedido-de-prorrogacao-de-curso\/"},"wordCount":90,"commentCount":0,"image":{"@id":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/prazo-para-pedido-de-prorrogacao-de-curso\/#primaryimage"},"thumbnailUrl":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/files\/2013\/07\/UFRRJ.jpg","keywords":["Coordena\u00e7\u00e3o"],"articleSection":["Not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cursos.ufrrj.br\/grad\/sistemas\/prazo-para-pedido-de-prorrogacao-de-curso\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/prazo-para-pedido-de-prorrogacao-de-curso\/","url":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/prazo-para-pedido-de-prorrogacao-de-curso\/","name":"Prazo para pedido de prorroga\u00e7\u00e3o de curso - Sistemas de Informa\u00e7\u00e3o","isPartOf":{"@id":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/prazo-para-pedido-de-prorrogacao-de-curso\/#primaryimage"},"image":{"@id":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/prazo-para-pedido-de-prorrogacao-de-curso\/#primaryimage"},"thumbnailUrl":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/files\/2013\/07\/UFRRJ.jpg","datePublished":"2023-11-22T16:45:47+00:00","dateModified":"2023-11-22T16:49:03+00:00","author":{"@id":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/#\/schema\/person\/53bd5ac834a651afabfdd8845572609b"},"breadcrumb":{"@id":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/prazo-para-pedido-de-prorrogacao-de-curso\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cursos.ufrrj.br\/grad\/sistemas\/prazo-para-pedido-de-prorrogacao-de-curso\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/prazo-para-pedido-de-prorrogacao-de-curso\/#primaryimage","url":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/files\/2013\/07\/UFRRJ.jpg","contentUrl":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/files\/2013\/07\/UFRRJ.jpg","width":436,"height":465},{"@type":"BreadcrumbList","@id":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/prazo-para-pedido-de-prorrogacao-de-curso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/"},{"@type":"ListItem","position":2,"name":"Prazo para pedido de prorroga\u00e7\u00e3o de curso"}]},{"@type":"WebSite","@id":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/#website","url":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/","name":"Sistemas de Informa\u00e7\u00e3o","description":"Campus Serop\u00e9dica \u2013 UFRRJ","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/#\/schema\/person\/53bd5ac834a651afabfdd8845572609b","name":"rizzo","url":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/author\/rizzo\/"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/wp-json\/wp\/v2\/posts\/2429","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/wp-json\/wp\/v2\/users\/195"}],"replies":[{"embeddable":true,"href":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/wp-json\/wp\/v2\/comments?post=2429"}],"version-history":[{"count":2,"href":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/wp-json\/wp\/v2\/posts\/2429\/revisions"}],"predecessor-version":[{"id":2433,"href":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/wp-json\/wp\/v2\/posts\/2429\/revisions\/2433"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/wp-json\/wp\/v2\/media\/1598"}],"wp:attachment":[{"href":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/wp-json\/wp\/v2\/media?parent=2429"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/wp-json\/wp\/v2\/categories?post=2429"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cursos.ufrrj.br\/grad\/sistemas\/wp-json\/wp\/v2\/tags?post=2429"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}